

{"id":42203,"date":"2020-09-01T12:28:37","date_gmt":"2020-09-01T10:28:37","guid":{"rendered":"https:\/\/gestions-hospitalieres.fr\/?p=42203"},"modified":"2020-09-15T14:16:27","modified_gmt":"2020-09-15T12:16:27","slug":"le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes","status":"publish","type":"post","link":"https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/","title":{"rendered":"Le dimensionnement des effectifs param\u00e9dicaux"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture\u00a0: <\/span> <span class=\"rt-time\"> 12<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><p>Par leurs t\u00e9moignages de prise en soins des patients, les soignants attestent qu\u2019ils aiment leur profession. Pour autant, ils expriment leur fatigue \u00e0 assumer une charge de travail importante et les al\u00e9as organisationnels auxquels ils doivent r\u00e9guli\u00e8rement s\u2019adapter<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(2)<\/sup>. Dans une \u00e9tude <sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(3)<\/sup> de la Direction de l\u2019animation de la recherche, des \u00e9tudes et des statistiques, la p\u00e9nibilit\u00e9 au travail est plus \u00e9lev\u00e9e dans la fonction hospitali\u00e8re quel qu\u2019en soit le type de contraintes \u2013 physiques, organisationnelles, expositions aux agents biologiques, aux nuisances chimiques \u2013 auxquelles viennent s\u2019ajouter les risques psychosociaux. Dans les conditions actuelles de travail, les aides-soignants et les infirmiers ont des difficult\u00e9s \u00e0 se projeter dans une m\u00eame carri\u00e8re durant leur vie professionnelle. Aujourd\u2019hui, nous peinons \u00e0 recruter des soignants\u2009: le num\u00e9ro d\u2019<i>\u00c9tudes et r\u00e9sultats<\/i> de d\u00e9cembre 2019 de la Direction de la recherche, des \u00e9tudes, de l\u2019\u00e9valuation et des statistiques titre ainsi\u2009: \u00ab\u2009Aides-soignants\u2009: de moins en moins de candidats \u00e0 l\u2019entr\u00e9e en formation et une baisse du nombre d\u2019inscrits\u2009\u00bb tandis que dans une enqu\u00eate sur l\u2019attractivit\u00e9 param\u00e9dicale de la F\u00e9d\u00e9ration hospitali\u00e8re de France (FHF), les r\u00e9ponses des responsables hospitaliers en ressources humaines \u00ab\u2009mettent en lumi\u00e8re la pluralit\u00e9 des motifs de ce d\u00e9samour. C\u2019est l\u2019image n\u00e9gative des conditions de travail qui nuit le plus \u00e0 l\u2019attractivit\u00e9 param\u00e9dicale<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(4)<\/sup>\u00bb. Les explications en sont l\u2019intensification du travail des m\u00e9tiers du soin, \u00e9troitement li\u00e9e \u00e0 la faiblesse de la r\u00e9mun\u00e9ration et \u00e0 l\u2019image v\u00e9hicul\u00e9e par les m\u00e9dias des conditions de travail d\u00e9grad\u00e9es dans les h\u00f4pitaux.<\/p>\n<h1>La crise hospitali\u00e8re<span class=\"Apple-converted-space\">\u00a0<\/span><\/h1>\n<p>La crise sociale et \u00e9conomique que traversent nos h\u00f4pitaux a \u00e9t\u00e9 exacerb\u00e9e par la crise sanitaire du Covid-19. Les premiers clignotants de la premi\u00e8re crise sont venus des Ehpad, des services d\u2019urgence et de la psychiatrie. Fin 2019, la FHF et les conf\u00e9rences hospitali\u00e8res ont demand\u00e9 une hausse de 2,4\u2009% de l\u2019objectif national des d\u00e9penses d\u2019assurance maladie (Ondam) du secteur hospitalier \u00ab\u2009pour contenir la crise sociale que traversent les h\u00f4pitaux et r\u00e9pondre aux enjeux de transformation du syst\u00e8me de sant\u00e9<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(5)<\/sup>\u00bb\u2009; la Conf\u00e9rence des directeurs de CHU a alert\u00e9 les pouvoirs publics sur \u00ab\u2009un effet ciseaux rendant incompatible la poursuite concomitante du redressement des comptes de l\u2019assurance maladie et de la r\u00e9duction des d\u00e9ficits hospitaliers dans les \u00e9tablissements en difficult\u00e9 [\u2026]<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(6)<\/sup>\u00bb.<\/p>\n<p>Le gouvernement a pris des mesures en faveur des h\u00f4pitaux publics en allouant des ressources suppl\u00e9mentaires pour leur fonctionnement avec une hausse de l\u2019Ondam sur 2020-2022. Une plus grande visibilit\u00e9 a \u00e9t\u00e9 donn\u00e9e aux \u00e9tablissements de sant\u00e9 sur leurs ressources et des tarifs en hausse jusqu\u2019en 2022. D\u2019autres mesures ont \u00e9t\u00e9 prises pour accompagner les d\u00e9buts de carri\u00e8re des soignants et revaloriser le m\u00e9tier d\u2019aide-soignant<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(7)<\/sup>. Les f\u00e9d\u00e9rations d\u2019\u00e9tablissements de sant\u00e9 se sont engag\u00e9es, via un protocole d\u2019accord avec l\u2019\u00c9tat<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(8)<\/sup>, \u00e0 renforcer une politique des ressources humaines pour am\u00e9liorer la qualit\u00e9 de vie au travail, fid\u00e9liser les professionnels et promouvoir le d\u00e9veloppement des nouvelles formes d\u2019exercice tel le d\u00e9veloppement des infirmiers en pratiques avanc\u00e9es (IPA).<\/p>\n<h1>Le mod\u00e8le de financement m\u00e9dico-\u00e9conomique<\/h1>\n<p>Les raisons de la crise hospitali\u00e8re sont connues. Depuis les ordonnances Jupp\u00e9 de 1996, un objectif de progression des d\u00e9penses \u00e0 ne pas d\u00e9passer est fix\u00e9 tous les ans par la loi de financement de la s\u00e9curit\u00e9 sociale. Chaque ann\u00e9e, le projet de loi de financement de la s\u00e9curit\u00e9 sociale (PLFSS) comporte \u00ab\u2009un objectif d\u2019\u00e9conomies \u00e0 r\u00e9aliser par rapport \u00e0 l\u2019\u00e9volution tendancielle estim\u00e9e de [l\u2019]Ondam, dans le cadre des accords conventionnels portant sur la ma\u00eetrise m\u00e9dicalis\u00e9e des d\u00e9penses\u2009\u00bb<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(9)<\/sup>.<\/p>\n<p>Le financement des \u00e9tablissements de sant\u00e9 est un enjeu majeur du syst\u00e8me de sant\u00e9 compte tenu de la part importante des d\u00e9penses hospitali\u00e8res. Depuis 2004, il a \u00e9t\u00e9 profond\u00e9ment modifi\u00e9 avec l\u2019instauration de la tarification \u00e0 l\u2019activit\u00e9 (T2A), dont l\u2019un des objectifs \u00e9tait d\u2019accro\u00eetre la productivit\u00e9 des \u00e9tablissements publics avec notamment une ma\u00eetrise de la masse salariale puisque les d\u00e9penses de personnel (titre\u00a01) repr\u00e9sentent le premier poste des d\u00e9penses. Des \u00e9tudes men\u00e9es en France ont mis en \u00e9vidence des effets positifs de la T2A sur la performance \u00e9conomique des h\u00f4pitaux sur la p\u00e9riode 2003-2009<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(10)<\/sup>.<\/p>\n<p>Pour autant, la T2A a ses limites\u2009: \u00ab\u2009[\u2026] Les inqui\u00e9tudes formul\u00e9es par les critiques de la T2A m\u00e9ritent d\u2019\u00eatre entendues\u2009: avec la T2A, on mesure et l\u2019on sanctionne les performances en termes \u00e9conomiques de chacun des \u00e9tablissements au risque de privil\u00e9gier ind\u00fbment cette dimension financi\u00e8re par rapport \u00e0 la mission premi\u00e8re des \u00e9tablissements de sant\u00e9\u2009: d\u00e9livrer des soins de qualit\u00e9.<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(11)<\/sup>\u00bb<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Depuis 2006, une autre obligation s\u2019impose aux h\u00f4pitaux\u2009: l\u2019\u00e9tat pr\u00e9visionnel des recettes et des d\u00e9penses (EPRD), qui s\u2019est substitu\u00e9 au budget classique. C\u2019est un instrument de pr\u00e9vision budg\u00e9taire qui d\u00e9cloisonne l\u2019exploitation et l\u2019investissement et qui permet un suivi de l\u2019ex\u00e9cution des autorisations de cr\u00e9dits. L\u2019objectif de l\u2019EPRD est de contr\u00f4ler tout risque de d\u00e9passement budg\u00e9taire. \u00c0 tout moment, les directions hospitali\u00e8res et les tutelles doivent \u00eatre en mesure d\u2019\u00e9valuer les recettes et les d\u00e9penses \u00e0 venir\u2009: \u00ab\u2009Sous le r\u00e9gime du budget, un d\u00e9ficit d\u2019exploitation n\u2019ob\u00e9rait pas la capacit\u00e9 de l\u2019h\u00f4pital \u00e0 commander et \u00e0 investir. D\u00e9sormais, dans la logique financi\u00e8re de l\u2019EPRD, tout d\u00e9ficit d\u2019exploitation diminuera les fonds propres de l\u2019h\u00f4pital et l\u2019obligera \u00e0 repenser les modes de financement des investissements pr\u00e9vus. L\u2019EPRD introduit donc un pilotage par les recettes dont le niveau commande les d\u00e9penses<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(12)<\/sup>\u00bb, et d\u00e8s lors une ma\u00eetrise des d\u00e9penses de personnel. De m\u00eame, dans les projets d\u2019investissement, le Comit\u00e9 interminist\u00e9riel de la performance et de la modernisation de l\u2019offre de soins hospitaliers (Copermo) veille \u00e0 l\u2019\u00e9volution des \u00e9quilibres financiers pluriannuels de l\u2019\u00e9tablissement concern\u00e9.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Nous venons d\u2019\u00e9clairer en partie les causes de \u00ab\u2009l\u2019imp\u00e9ratif d\u2019efficience\u2009\u00bb qui p\u00e8se sur nos \u00e9tablissements. Questionnons-nous maintenant sur les effets dans le dimensionnement des effectifs.<\/p>\n<h1>Les crit\u00e8res de d\u00e9cision du dimensionnement des effectifs<\/h1>\n<p>La Direction g\u00e9n\u00e9rale de l\u2019offre de soins (DGOS) recommande, pour un juste dimensionnement capacitaire en hospitalisation compl\u00e8te, des unit\u00e9s de 28 \u00e0 30\u00a0lits. L\u2019allocation des ressources humaines est l\u2019un des enjeux d\u2019efficience et d\u2019am\u00e9lioration de la prise en charge des patients, en ajustant \u00ab\u2009le nombre et les qualifications des professionnels au mode de prise en charge, au niveau de s\u00e9v\u00e9rit\u00e9 de l\u2019\u00e9tat des patients, au volume d\u2019activit\u00e9 comme \u00e0 ses variations saisonni\u00e8res<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(13)<\/sup>\u00bb. Les indicateurs d\u2019impact retenus sont le nombre de lits, le taux d\u2019occupation \u2013 avec un chiffre cible de 95\u2009% en m\u00e9decine\/chirurgie, 85\u2009% en obst\u00e9trique \u2013 et l\u2019indice de performance de la dur\u00e9e moyenne de s\u00e9jour (DMS). La valorisation de l\u2019activit\u00e9 dans le cadre de la T2A est impact\u00e9e par l\u2019indicateur de performance de dur\u00e9e de s\u00e9jour (IP-DMS).<\/p>\n<p>Des maquettes organisationnelles sont \u00e9labor\u00e9es avec des indicateurs afin de donner une lecture synoptique des diff\u00e9rents services dans un m\u00eame \u00e9tablissement. Selon le guide de la Mission nationale d\u2019expertise et d\u2019audit hospitaliers (MEAH), \u00ab\u2009d\u2019une fa\u00e7on g\u00e9n\u00e9rale, une maquette est une repr\u00e9sentation partielle d\u2019un syst\u00e8me ou d\u2019un objet (r\u00e9el ou existant, ou \u00e0 concevoir) afin d\u2019en tester et valider certains aspects et ou comportements<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(14)<\/sup>\u00bb. La finalit\u00e9 est double\u2009:<\/p>\n<p>constituer une r\u00e9f\u00e9rence formalis\u00e9e de l\u2019organisation qui met en valeur ses \u00e9l\u00e9ments structurels importants\u2009;<\/p>\n<p>fournir un langage pour alimenter la r\u00e9flexion sur des \u00e9volutions souhaitables, en permettant de formaliser des sc\u00e9narios et d\u2019en analyser les implications. Les maquettes devront int\u00e9grer des hypoth\u00e8ses sur l\u2019activit\u00e9, les effectifs, les processus de prise en charge. Il demeure utile de disposer de donn\u00e9es sur le fonctionnement du service \u00e0 titre de situation de r\u00e9f\u00e9rence pour appr\u00e9cier les \u00e9carts entre les sc\u00e9narios futurs et la r\u00e9alit\u00e9 existante.<\/p>\n<p>Comme il est rappel\u00e9 dans ce m\u00eame guide, \u00ab\u2009les probl\u00e9matiques \u00e0 explorer sont toujours de m\u00eame nature. C\u2019est la fa\u00e7on de les analyser par rapport aux enjeux qui va diff\u00e9rencier les d\u00e9marches\u2009\u00bb.<\/p>\n<p>Les fiches de la DGOS cit\u00e9es plus haut sont des recommandations dont l\u2019utilisation et l\u2019interpr\u00e9tation d\u00e9pendent des acteurs.<\/p>\n<p>L\u2019Agence nationale d\u2019appui \u00e0 la performance (Anap), de son c\u00f4t\u00e9, a d\u00e9velopp\u00e9 l\u2019outil \u00c6lipce, un support de dialogue et d\u2019aide \u00e0 la d\u00e9cision afin d\u2019am\u00e9liorer la performance des organisations, destin\u00e9 aux \u00e9tablissements de sant\u00e9. Dans le module \u00ab\u2009Organisation\u2009\u00bb il est possible d\u2019analyser une organisation existante, de simuler les impacts sur cette organisation, des hypoth\u00e8ses d\u2019\u00e9volution de la volum\u00e9trie des activit\u00e9s, des modalit\u00e9s de prise en charge, des niveaux de s\u00e9v\u00e9rit\u00e9, des ressources humaines. Ces maquettes organisationnelles sont \u00e9labor\u00e9es avec des professionnels de terrain et elles donnent la possibilit\u00e9 de comparer des sc\u00e9narios au regard de diff\u00e9rents indices de performances reconnus.<\/p>\n<p>Dans cet outil, l\u2019Anap propose une maquette organisationnelle minimale pour une unit\u00e9 d\u2019hospitalisation compl\u00e8te adultes de 25 \u00e0 32\u00a0lits. Un infirmier et un aide-soignant pour 13 \u00e0 16\u00a0lits ou un soignant pour 7 \u00e0 8\u00a0lits. Pour la nuit, un infirmier et un aide-soignant pour 25 \u00e0 32\u00a0lits ou un soignant pour 13 \u00e0 16\u00a0lits. Dans le document de l\u2019Anap, il est mentionn\u00e9 que la maquette organisationnelle<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(15)<\/sup>\u2009\u00ab\u2009doit \u00eatre adapt\u00e9e et ajust\u00e9e suivant les sp\u00e9cificit\u00e9s de l\u2019unit\u00e9 (technicit\u00e9, sp\u00e9cialit\u00e9, mode de prise en charge\u2026), de l\u2019\u00e9tablissement, de la population, de l\u2019environnement, l\u2019occupation [\u2026]\u2009\u00bb. Une note pr\u00e9cise que l\u2019objectif de cette maquette organisationnelle minima est \u00ab\u2009d\u2019engager le dialogue et ne constitue pas une norme ou une r\u00e9f\u00e9rence en la mati\u00e8re\u2009\u00bb.<\/p>\n<p>D\u2019autres h\u00f4pitaux r\u00e9alisent du benchmarking pour comparer les effectifs interCHU\/CHR. Cette d\u00e9marche donne des rep\u00e8res lorsque l\u2019activit\u00e9, la prise en charge et les organisations sont similaires. Des \u00e9tablissements proc\u00e8dent \u00e0 ce benchmarking via les bases de Reims et d\u2019Angers ou encore Hospidiag<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(16)<\/sup>.<\/p>\n<p>Ainsi, depuis 2009, le CHU de Reims coordonne une \u00e9tude de benchmarking interCHU\/CHR<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(17)<\/sup> qui vise \u00e0 \u00e9tablir, sur la base de plusieurs indicateurs, des \u00e9l\u00e9ments de comparaison entre \u00e9tablissements dont les effectifs soignants et m\u00e9dicaux dans les services de soins et m\u00e9dico-techniques au regard de leurs activit\u00e9s. C\u2019est un outil \u00ab\u2009d\u2019appr\u00e9ciation de l\u2019efficience des organisations et de d\u00e9finition strat\u00e9gique de la mutabilit\u00e9 des structures hospitali\u00e8res au service de la performance \u00e9conomique et sociale des \u00e9tablissements<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(18)<\/sup>\u2009\u00bb. Aujourd\u2019hui, la base de Reims int\u00e8gre la majorit\u00e9 des CHU-CHR avec la production d\u2019indicateurs de performance m\u00e9dico-\u00e9conomique, d\u2019efficience soignante et m\u00e9dicale d\u00e9clin\u00e9s par services de soins. L\u2019\u00e9tude est utilis\u00e9e pour dialoguer avec les p\u00f4les et d\u00e9finir avec eux, les effectifs cibles soignants, administratifs et les maquettes de pr\u00e9sence au lit du patient.<\/p>\n<p>En France, il existe uniquement quelques services qui b\u00e9n\u00e9ficient de ratios norm\u00e9s comme les r\u00e9animations adultes, la dialyse, les soins intensifs de cardiologie, les blocs obst\u00e9tricaux. Pour les autres services, la r\u00e9vision des effectifs est sp\u00e9cifique \u00e0 chaque \u00e9tablissement selon leurs propres crit\u00e8res.<\/p>\n<p>En 2016, un groupe d\u2019\u00e9tudiants de l\u2019\u00c9cole des hautes \u00e9tudes en sant\u00e9 publique (EHESP) a men\u00e9 un travail d\u2019enqu\u00eate aupr\u00e8s de cinq \u00e9tablissements quant au ratio d\u2019effectifs dans les services de soins<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(19)<\/sup>. Ils \u00e9crivent\u2009: \u00ab\u2009Dans le contexte actuel du budget contraint, d\u2019augmentation de la charge de travail, d\u2019insatisfaction des personnels sur les conditions de travail ou encore de p\u00e9nurie de personnel, d\u00e9tenir une m\u00e9thode de calcul homog\u00e8ne des effectifs est devenue primordial pour les dirigeants.\u2009\u00bb En dehors des services norm\u00e9s, les \u00e9tablissements prennent en compte des \u00e9l\u00e9ments disparates. L\u2019absence de litt\u00e9rature sur ce sujet a contraint les h\u00f4pitaux \u00e0 d\u00e9finir leurs propres m\u00e9thodes de travail. Ils se basent toutefois sur des \u00e9l\u00e9ments communs\u2009: nombre de lits, taux d\u2019occupation, DMS, charge de travail, typologie des patients, activit\u00e9, projet m\u00e9dical, organisation du travail, poids moyen du cas trait\u00e9 (PMCT). Certains \u00e9tablissements \u00e9laborent des ratios, d\u2019autres int\u00e8grent des variables d\u2019ajustement comme l\u2019absent\u00e9isme, le turn-over, l\u2019architecture\u2026 La prise en compte et l\u2019\u00e9valuation de la charge de travail d\u00e9pendent ainsi de chaque structure.<\/p>\n<blockquote><p>C\u2019est bien la valeur humaine qui doit \u00eatre le fondement de toutes nos actions dans les h\u00f4pitaux.<\/p><\/blockquote>\n<h1>Des m\u00e9thodes insuffisamment prises en compte<span class=\"Apple-converted-space\">\u00a0<\/span><\/h1>\n<p>L\u2019activit\u00e9 dans les services refl\u00e8te une partie de la charge de travail mais elle ne d\u00e9crit pas la nature de la prise en charge des patients, ni sa dur\u00e9e, ni l\u2019intensit\u00e9 des soins. De plus, la charge de travail rev\u00eat plusieurs composantes\u2009:<\/p>\n<ul>\n<li>la charge physique\u2009: portage, manutention, position debout, etc.\u2009;<\/li>\n<li>la charge cognitive, li\u00e9e au traitement de l\u2019information et de la responsabilit\u00e9 qui en d\u00e9coule\u2009;<\/li>\n<li>la charge psychique\u2009: confrontation \u00e0 la souffrance et \u00e0 l\u2019angoisse des malades et parfois \u00e0 leur agressivit\u00e9<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(20)<\/sup>.<\/li>\n<\/ul>\n<p>\u00ab\u2009L\u2019appr\u00e9ciation de la charge de travail est un sujet tr\u00e8s complexe qui ne peut se r\u00e9duire au calcul de ratio.<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(21)<\/sup>\u2009\u00bb Elle est variable et sa perception diff\u00e8re d\u2019un soignant \u00e0 l\u2019autre. Elle est fortement corr\u00e9l\u00e9e \u00e0 l\u2019organisation ainsi qu\u2019au dialogue structur\u00e9 et concert\u00e9 \u00e0 l\u2019\u00e9chelle de l\u2019\u00e9tablissement.<\/p>\n<p>Certains h\u00f4pitaux utilisent des m\u00e9thodes d\u2019\u00e9valuation de la charge en soins comme celle des soins infirmiers individualis\u00e9s \u00e0 la personne soign\u00e9e (SIIPS). Cet outil distingue les soins de base, les soins techniques, les soins relationnels et \u00e9ducatifs<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(22)<\/sup>. Les activit\u00e9s aff\u00e9rentes aux soins (h\u00f4teli\u00e8res, logistiques, communication, administratives, et d\u2019encadrement) sont \u00e9galement relev\u00e9es car li\u00e9es \u00e0 l\u2019organisation de l\u2019unit\u00e9. Il est ainsi possible de calculer les postes et les comp\u00e9tences utiles en fonction de la charge de travail. En 2017, afin d\u2019\u00e9valuer l\u2019impact d\u2019une application de la m\u00e9thode SIIPS sur la valorisation de l\u2019\u00e9tude nationale des co\u00fbts MCO, l\u2019Agence technique de l\u2019information sur l\u2019hospitalisation (Atih) a organis\u00e9 un groupe de r\u00e9flexion \u00ab\u2009dont l\u2019objectif est de proposer une mesure de la charge en soins qui permettrait une ventilation plus pertinente des charges de personnel soignant sur les s\u00e9jours MCO<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(23)<\/sup>\u2009\u00bb.<\/p>\n<p>Dans les documents de la DGOS et de l\u2019Anap, c\u2019est le niveau de s\u00e9v\u00e9rit\u00e9 des s\u00e9jours qui est requis comme indicateur de lourdeur de prise en charge des patients et, par cons\u00e9quent, comme indicateur de charge en soins. Les complications ou morbidit\u00e9s associ\u00e9es (CMA) permettent de prendre en compte la gravit\u00e9 des cas qui engendre une augmentation de la dur\u00e9e de s\u00e9jour\u2009; \u00ab\u2009selon l\u2019importance de leur effet sur la dur\u00e9e de s\u00e9jour, les codes de CMA sont r\u00e9partis selon quatre niveaux de s\u00e9v\u00e9rit\u00e9 num\u00e9rot\u00e9s d\u2019un \u00e0 quatre. Le niveau 1 correspondant au niveau sans CMA, sans s\u00e9v\u00e9rit\u00e9 significative<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(24)<\/sup>\u00bb.<\/p>\n<p>Dans d\u2019autres articles professionnels, il est fait r\u00e9f\u00e9rence aussi au poids moyen du cas trait\u00e9 (PMCT) relatif<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(25)<\/sup>\u2009: le PMCT est la valeur moyenne en euros des s\u00e9jours de l\u2019\u00e9tablissement. Il permet de d\u00e9crire la lourdeur des cas trait\u00e9s par \u00e9tablissement (complexit\u00e9 et dur\u00e9e du s\u00e9jour). Le PMCT relatif est le rapport du PMCT de l\u2019\u00e9tablissement au PMCT de r\u00e9f\u00e9rence. Lorsqu\u2019il est sup\u00e9rieur \u00e0 1, cet indicateur signifie que les s\u00e9jours de l\u2019\u00e9tablissement sont, en moyenne et d\u2019un point de vue m\u00e9dico-\u00e9conomique, plus lourds que la moyenne nationale.<\/p>\n<p>Dans nos h\u00f4pitaux, les s\u00e9jours seront de plus en plus lourds, notamment du fait du vieillissement de la population, donc de la d\u00e9pendance. En MCO, \u00ab\u2009au total, un peu plus d\u2019un s\u00e9jour sur trois concerne des personnes de 65 ans ou plus<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(26)<\/sup>\u00bb. En cons\u00e9quence, nous pensons que le crit\u00e8re de \u00ab\u2009charge en soins\u2009\u00bb devrait \u00eatre obligatoirement int\u00e9gr\u00e9 dans les d\u00e9cisions concernant le dimensionnement des effectifs.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Par ailleurs, qu\u2019en est-il de l\u2019interpr\u00e9tation et de la volont\u00e9 d\u2019harmoniser des indicateurs fiables et robustes\u2009? Le risque de l\u2019h\u00e9t\u00e9rog\u00e9n\u00e9it\u00e9 des crit\u00e8res de charge en soins est la dilution de la responsabilit\u00e9 selon l\u2019interpr\u00e9tation des acteurs et de leurs influences, en donnant son assentiment \u00e0 une repr\u00e9sentation dont on n\u2019a pas la \u00ab\u2009preuve\u2009\u00bb. Nous estimons qu\u2019il y a n\u00e9cessit\u00e9 de r\u00e9habiliter cette \u00ab\u2009notion\u2009\u00bb incluse dans les activit\u00e9s et les organisations. De surcro\u00eet, les projets d\u2019am\u00e9liorer \u00ab\u2009l\u2019\u00e9quit\u00e9 de traitement\u2009\u00bb entre unit\u00e9s de soins seront un enjeu majeur pour les conditions de travail des soignants\u2009; alors que la complexit\u00e9 et la lourdeur de la prise en charge des patients s\u2019accentueront avec le virage ambulatoire.<\/p>\n<h1>Promouvoir la recherche param\u00e9dicale sur la dotation en effectifs<\/h1>\n<p>Une recherche fran\u00e7aise quantitative et inter\u00e9tablissement serait \u00e0 conduire sur le lien ratio personnel\/qualit\u00e9 des soins. Nous en d\u00e9duirions l\u2019influence de la charge de travail et de l\u2019organisation. Un sous-dimensionnement d\u2019une \u00e9quipe aurait-il des r\u00e9percussions sur la qualit\u00e9 du travail\u2009?<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Des \u00e9tudes internationales ont montr\u00e9 l\u2019impact des ratios sur la qualit\u00e9 de la prise en charge des patients. Ainsi, l\u2019enqu\u00eate multicentrique RN4CAST (Nurse Forecasting Human Resources Planning in Nursing) a \u00e9t\u00e9 men\u00e9e entre 2009 et 2011 dans douze pays europ\u00e9ens \u2013 except\u00e9 la France \u2013 et 617\u00a0h\u00f4pitaux aux \u00c9tats-Unis<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(27)<\/sup>. Les objectifs \u00e9taient doubles\u2009: pr\u00e9ciser les mod\u00e8les de pr\u00e9vision sur les effectifs infirmiers et comprendre les rapports entre le profil des infirmiers (niveau de formation), des h\u00f4pitaux (taille, rotation de personnel) et les r\u00e9sultats de ces enqu\u00eates aupr\u00e8s du personnel soignant (<i>burn-out<\/i>, maintien dans le poste) et des patients (satisfaction, complications d\u00e9c\u00e8s).<\/p>\n<p>Cette enqu\u00eate a servi de base \u00e0 plusieurs \u00e9tudes nationales et internationales, dont l\u2019une sur la charge de travail et le niveau de formation en 2014<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(28)<\/sup>. Les variables qui expliquent la mortalit\u00e9 hospitali\u00e8re \u00e0 30 jours sont les effectifs infirmiers et le niveau de formation\u2009: \u00ab\u2009L\u2019ajout d\u2019un patient \u00e0 la charge de travail par infirmi\u00e8re augmente de 7\u2009% le risque qu\u2019un patient hospitalis\u00e9 meure dans les 30 jours de son admission.<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(29)<\/sup>\u00bb La m\u00eame ann\u00e9e, une \u00e9tude sur les soins infirmiers n\u00e9glig\u00e9s a relev\u00e9 les actes qui n\u2019ont pu \u00eatre r\u00e9alis\u00e9s par manque de temps<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(30)<\/sup>.<\/p>\n<h1>Le processus d\u00e9cisionnel\u2009: un biais \u00e9pist\u00e9mique\u2009?<\/h1>\n<p>Dans les processus de d\u00e9cisions concernant les effectifs, nous constatons des points de cristallisation qui \u00e9mergent dans le v\u00e9cu de l\u2019encadrement. Parfois, les cadres subissent des d\u00e9cisions qu\u2019ils n\u2019approuvent pas mais qu\u2019ils doivent appliquer, \u00e0 contre-valeur. Nous observons aussi une absence de litt\u00e9rature \u00e0 ce sujet alors que nous travaillons dans des centres hospitaliers universitaires, avec une valorisation de la recherche et des donn\u00e9es probantes. Pour Christian\u00a0Morel, le risque est \u00ab\u2009une erreur de raisonnement<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(31)<\/sup>\u00bb, un indicateur, le ratio qui pr\u00e9vaut sur d\u2019autres crit\u00e8res comme la charge de travail et l\u2019organisation. D\u00e8s lors, une certaine dimension politique interf\u00e8re dans les d\u00e9cisions, c\u2019est-\u00e0-dire \u00ab\u2009une dimension o\u00f9 se tissent et se concluent les oppositions et les alliances vis-\u00e0-vis des d\u00e9cisions<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(32)<\/sup>\u00bb, tels qu\u2019un plan de retour \u00e0 l\u2019\u00e9quilibre<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(33)<\/sup>, l\u2019influence des syndicats ou de chefs de service.<\/p>\n<p>Ce que nous questionnons \u00e0 travers la responsabilit\u00e9, c\u2019est le processus de d\u00e9cision allant du strat\u00e9gique \u00e0 l\u2019op\u00e9rationnel, aux niveaux individuel et collectif. C\u2019est pourquoi nous proposons d\u2019un point de vue politique une r\u00e9partition diff\u00e9rente des responsabilit\u00e9s avec la cr\u00e9ation d\u2019une plateforme nationale o\u00f9 l\u2019enjeu serait le \u00ab\u2009chiffre juste<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(34)<\/sup>\u00bb<\/p>\n<h1>\u00c9valuation du dimensionnement des effectifs\u2009: une mission pour la HAS\u2009?<\/h1>\n<p>La DGOS s\u2019est engag\u00e9e \u00ab\u2009dans une d\u00e9marche globale d\u2019am\u00e9lioration de l\u2019efficience des \u00e9tablissements\u2009\u00bb. Elle a \u00e9labor\u00e9 des fiches pratiques sur l\u2019efficience hospitali\u00e8re qui traduisent cette politique de performance incluant l\u2019optimisation des maquettes organisationnelles<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(35)<\/sup>. Nous devons rendre obligatoire la prise en compte de la charge de travail, de l\u2019activit\u00e9 et de l\u2019organisation dans le dimensionnement des effectifs.<\/p>\n<p>Nous proposons que cette responsabilit\u00e9 rel\u00e8ve de la Haute Autorit\u00e9 de sant\u00e9 (HAS) et non de la DGOS et de l\u2019Anap. En effet, l\u2019esprit est de s\u00e9parer la dimension financi\u00e8re de la dimension humaine. Le lien qualit\u00e9 de vie au travail\/qualit\u00e9 des soins n\u2019est plus \u00e0 d\u00e9montrer<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(36)<\/sup>\u2009; si de nombreux aspects de la qualit\u00e9 de vie au travail sont pris en compte par les \u00e9tablissements de sant\u00e9, la dimension \u00ab\u2009contenu du travail\u2009\u00bb est sous-\u00e9valu\u00e9e. Nous proposons qu\u2019un groupe de travail soit constitu\u00e9 au sein de la HAS afin d\u2019\u00e9tablir des crit\u00e8res d\u2019\u00e9valuation homog\u00e8nes comme l\u2019activit\u00e9, la charge de travail, le capacitaire, l\u2019architecture, les fonctions externalis\u00e9es, etc. Nous avons besoin que les r\u00e9ponses soient instituantes et non d\u00e9fiantes car nous avons conscience qu\u2019il y a une politisation des m\u00e9thodes<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(37)<\/sup>. Le fait de rendre compte au niveau national correspond \u00e0 la \u00ab\u2009publication kantienne\u2009\u00bb, qui signifie une argumentation publique des normes \u00e0 la vue et au su de tous. Et, de mani\u00e8re effective, qui situe la d\u00e9marche \u00e0 un autre niveau conceptuel que le benchmarking.<\/p>\n<p>D\u2019un point de vue op\u00e9rationnel, nous reprenons la proposition du groupe d\u2019\u00e9l\u00e8ves directeurs de la cr\u00e9ation d\u2019une plateforme nationale. Elle permettrait le partage d\u2019informations sur les crit\u00e8res, sur l\u2019outil utilis\u00e9 pour la charge de travail, sur les organisations. Si, d\u2019un point de vue politique, nous s\u00e9parons l\u2019agence de performance de l\u2019agence de qualit\u00e9, les articulations pourront se r\u00e9aliser au niveau op\u00e9rationnel.<\/p>\n<h1>Conclusion<\/h1>\n<p>Nous confirmons l\u2019importance de la responsabilit\u00e9 des d\u00e9cisions concernant les\u00a0\u00ab\u2009ressources\u2009\u00bb humaines. Car si le dimensionnement des effectifs est s\u00e9rieusement impact\u00e9 par \u00ab\u2009la performance \u00e9conomique, le risque av\u00e9r\u00e9 parfois a \u00e9t\u00e9 la pr\u00e9dominance des pr\u00e9occupations des gestionnaires hospitaliers sur les exigences tenant \u00e0 la qualit\u00e9 des soins et des conditions de travail des soignants<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(38)<\/sup>\u00bb. Nous souhaitons ainsi une s\u00e9paration de la performance des d\u00e9cisions de calcul des effectifs.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Assur\u00e9ment, des \u00e9volutions organisationnelles sont indispensables dans nos unit\u00e9s d\u2019hospitalisation. Elles conditionnent en partie le dimensionnement des effectifs. Aujourd\u2019hui, la tendance est \u00e0 l\u2019innovation organisationnelle. \u00c0 cet \u00e9gard, nous pouvons interroger<span class=\"Apple-converted-space\">\u00a0 <\/span>le \u00ab\u2009leadership soignant<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(39)<\/sup>\u00bb dans les organisations. \u00ab\u2009La plupart du temps, le personnel non m\u00e9dical se situe dans une tradition d\u2019adaptation des organisations, dont les dysfonctionnements sont v\u00e9cus avec fatalit\u00e9.<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(40)<\/sup>\u00bb Nous avons interrog\u00e9 le processus de d\u00e9cision et la gouvernance qui s\u2019y rattache. Est-ce parce qu\u2019il n\u2019y a pas de leadership soignant en France que la charge en soins est sous-estim\u00e9e dans les crit\u00e8res de d\u00e9cision\u2009? Il manque un consensus sur des indicateurs fiables, robustes et simples. Nous savons que certains pays \u00e9trangers ont l\u00e9gif\u00e9r\u00e9 sur la dotation des effectifs, est-ce une solution\u2009?<\/p>\n<p>C\u2019est bien la valeur humaine qui doit \u00eatre le fondement de toutes nos actions dans les h\u00f4pitaux. Soyons vigilants quant \u00e0 notre incapacit\u00e9 \u00e0 d\u00e9finir le but du chemin autrement que par le chemin lui-m\u00eame.<\/p>\n<script>function PlayerjsAsync(){} if(window[\"Playerjs\"]){PlayerjsAsync();}<\/script>","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture\u00a0: <\/span> <span class=\"rt-time\"> 12<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span>Par leurs t\u00e9moignages de prise en soins des patients, les soignants attestent qu\u2019ils aiment leur profession. Pour autant, ils expriment leur fatigue \u00e0 assumer une charge de travail importante et les al\u00e9as organisationnels auxquels ils doivent r\u00e9guli\u00e8rement s\u2019adapter(2). Dans une \u00e9tude (3) de la Direction de l\u2019animation de la recherche, des \u00e9tudes et des statistiques, la p\u00e9nibilit\u00e9 au travail est plus \u00e9lev\u00e9e dans la fonction hospitali\u00e8re quel qu\u2019en soit le&hellip; <\/p>\n","protected":false},"author":23133,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[2,72],"tags":[8066,573,315,36,8065,359,1319,672],"class_list":["post-42203","post","type-post","status-publish","format-standard","hentry","category-gestions-hospitalieres","category-reflexion","tag-dimensionnement","tag-effectif","tag-efficience","tag-organisation","tag-pcmt","tag-personnel","tag-qualite-de-vie","tag-ressources-humaines"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le dimensionnement des effectifs param\u00e9dicaux - Gestions hospitali\u00e8res<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le dimensionnement des effectifs param\u00e9dicaux - Gestions hospitali\u00e8res\" \/>\n<meta property=\"og:description\" content=\"Temps de lecture\u00a0:  12 minutesPar leurs t\u00e9moignages de prise en soins des patients, les soignants attestent qu\u2019ils aiment leur profession. Pour autant, ils expriment leur fatigue \u00e0 assumer une charge de travail importante et les al\u00e9as organisationnels auxquels ils doivent r\u00e9guli\u00e8rement s\u2019adapter(2). Dans une \u00e9tude (3) de la Direction de l\u2019animation de la recherche, des \u00e9tudes et des statistiques, la p\u00e9nibilit\u00e9 au travail est plus \u00e9lev\u00e9e dans la fonction hospitali\u00e8re quel qu\u2019en soit le&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/\" \/>\n<meta property=\"og:site_name\" content=\"Gestions hospitali\u00e8res\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gestionshospitalieres\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-01T10:28:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-15T12:16:27+00:00\" \/>\n<meta name=\"author\" content=\"Gestions hospitali\u00e8res\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revue_GH\" \/>\n<meta name=\"twitter:site\" content=\"@revue_GH\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestions hospitali\u00e8res\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/\"},\"author\":{\"name\":\"Gestions hospitali\u00e8res\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f\"},\"headline\":\"Le dimensionnement des effectifs param\u00e9dicaux\",\"datePublished\":\"2020-09-01T10:28:37+00:00\",\"dateModified\":\"2020-09-15T12:16:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/\"},\"wordCount\":4028,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#organization\"},\"keywords\":[\"dimensionnement\",\"effectif\",\"efficience\",\"organisation\",\"PCMT\",\"personnel\",\"qualit\u00e9 de vie\",\"ressources humaines\"],\"articleSection\":[\"Gestions Hospitali\u00e8res\",\"r\u00e9flexion\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/\",\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/\",\"name\":\"Le dimensionnement des effectifs param\u00e9dicaux - Gestions hospitali\u00e8res\",\"isPartOf\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#website\"},\"datePublished\":\"2020-09-01T10:28:37+00:00\",\"dateModified\":\"2020-09-15T12:16:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ricom-web8.com\/gestions\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le dimensionnement des effectifs param\u00e9dicaux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#website\",\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/\",\"name\":\"Gestions hospitali\u00e8res\",\"description\":\"la revue des d\u00e9cideurs hospitaliers\",\"publisher\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ricom-web8.com\/gestions\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#organization\",\"name\":\"Gestions hospitali\u00e8res\",\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png\",\"contentUrl\":\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png\",\"width\":512,\"height\":512,\"caption\":\"Gestions hospitali\u00e8res\"},\"image\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/gestionshospitalieres\/\",\"https:\/\/x.com\/revue_GH\",\"https:\/\/www.linkedin.com\/company\/gestions-hospitalieres?trk=top_nav_home\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f\",\"name\":\"Gestions hospitali\u00e8res\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g\",\"caption\":\"Gestions hospitali\u00e8res\"},\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/author\/benjamin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le dimensionnement des effectifs param\u00e9dicaux - Gestions hospitali\u00e8res","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/","og_locale":"fr_FR","og_type":"article","og_title":"Le dimensionnement des effectifs param\u00e9dicaux - Gestions hospitali\u00e8res","og_description":"Temps de lecture\u00a0:  12 minutesPar leurs t\u00e9moignages de prise en soins des patients, les soignants attestent qu\u2019ils aiment leur profession. Pour autant, ils expriment leur fatigue \u00e0 assumer une charge de travail importante et les al\u00e9as organisationnels auxquels ils doivent r\u00e9guli\u00e8rement s\u2019adapter(2). Dans une \u00e9tude (3) de la Direction de l\u2019animation de la recherche, des \u00e9tudes et des statistiques, la p\u00e9nibilit\u00e9 au travail est plus \u00e9lev\u00e9e dans la fonction hospitali\u00e8re quel qu\u2019en soit le&hellip;","og_url":"https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/","og_site_name":"Gestions hospitali\u00e8res","article_publisher":"https:\/\/www.facebook.com\/gestionshospitalieres\/","article_published_time":"2020-09-01T10:28:37+00:00","article_modified_time":"2020-09-15T12:16:27+00:00","author":"Gestions hospitali\u00e8res","twitter_card":"summary_large_image","twitter_creator":"@revue_GH","twitter_site":"@revue_GH","twitter_misc":{"\u00c9crit par":"Gestions hospitali\u00e8res","Dur\u00e9e de lecture estim\u00e9e":"20 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/#article","isPartOf":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/"},"author":{"name":"Gestions hospitali\u00e8res","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f"},"headline":"Le dimensionnement des effectifs param\u00e9dicaux","datePublished":"2020-09-01T10:28:37+00:00","dateModified":"2020-09-15T12:16:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/"},"wordCount":4028,"commentCount":0,"publisher":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#organization"},"keywords":["dimensionnement","effectif","efficience","organisation","PCMT","personnel","qualit\u00e9 de vie","ressources humaines"],"articleSection":["Gestions Hospitali\u00e8res","r\u00e9flexion"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/","url":"https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/","name":"Le dimensionnement des effectifs param\u00e9dicaux - Gestions hospitali\u00e8res","isPartOf":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#website"},"datePublished":"2020-09-01T10:28:37+00:00","dateModified":"2020-09-15T12:16:27+00:00","breadcrumb":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ricom-web8.com\/gestions\/le-dimensionnement-des-effectifs-paramedicaux-pour-des-criteres-nationaux-homogenes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ricom-web8.com\/gestions\/"},{"@type":"ListItem","position":2,"name":"Le dimensionnement des effectifs param\u00e9dicaux"}]},{"@type":"WebSite","@id":"https:\/\/www.ricom-web8.com\/gestions\/#website","url":"https:\/\/www.ricom-web8.com\/gestions\/","name":"Gestions hospitali\u00e8res","description":"la revue des d\u00e9cideurs hospitaliers","publisher":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ricom-web8.com\/gestions\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ricom-web8.com\/gestions\/#organization","name":"Gestions hospitali\u00e8res","url":"https:\/\/www.ricom-web8.com\/gestions\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/","url":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png","contentUrl":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png","width":512,"height":512,"caption":"Gestions hospitali\u00e8res"},"image":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gestionshospitalieres\/","https:\/\/x.com\/revue_GH","https:\/\/www.linkedin.com\/company\/gestions-hospitalieres?trk=top_nav_home"]},{"@type":"Person","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f","name":"Gestions hospitali\u00e8res","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g","caption":"Gestions hospitali\u00e8res"},"url":"https:\/\/www.ricom-web8.com\/gestions\/author\/benjamin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/posts\/42203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/users\/23133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/comments?post=42203"}],"version-history":[{"count":0,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/posts\/42203\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/media?parent=42203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/categories?post=42203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/tags?post=42203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}