

{"id":43333,"date":"2021-05-01T11:02:18","date_gmt":"2021-05-01T09:02:18","guid":{"rendered":"https:\/\/gestions-hospitalieres.fr\/?p=43333"},"modified":"2021-05-31T16:43:28","modified_gmt":"2021-05-31T14:43:28","slug":"developper-la-recherche-clinique-au-sein-des-ght","status":"publish","type":"post","link":"https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/","title":{"rendered":"D\u00e9velopper la recherche clinique au sein des GHT"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture\u00a0: <\/span> <span class=\"rt-time\"> 9<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><p>Le calendrier soutenu pour la constitution des fili\u00e8res de soins et les objectifs ambitieux assign\u00e9s aux fonctions mutualis\u00e9es ont concentr\u00e9 les GHT sur ces finalit\u00e9s princeps. Ainsi, le r\u00e9cent rapport de l\u2019Inspection des affaires sociales (Igas), qui fait \u00e9tat de diverses difficult\u00e9s dans la mise en place, le fonctionnement et donc <i>in fine<\/i> l\u2019atteinte des objectifs premiers des GHT, ne mentionne pas le d\u00e9veloppement de la recherche clinique comme un r\u00e9sultat observable<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(1)<\/sup>. La Cour des comptes rel\u00e8ve quant \u00e0 elle quelques initiatives locales, peu nombreuses, mais suffisamment int\u00e9ressantes pour envisager les GHT comme un cadre pertinent et prometteur<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(2)<\/sup>. Si certains projets ont pu \u00e9merger sur certains territoires, il s\u2019agit d\u2019initiatives individuelles li\u00e9es \u00e0 des contextes aussi favorables que singuliers. La coop\u00e9ration ne va pas encore de soi en mati\u00e8re de recherche clinique, ligne de conduite largement entretenue par un environnement o\u00f9 la concurrence semble \u00eatre de rigueur.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<h1>Financements publics en berne, strat\u00e9gies individuelles<\/h1>\n<p>Dans un premier temps, la tarification \u00e0 l\u2019activit\u00e9 (T2A), d\u00e9ploy\u00e9e \u00e0 compter de 2008, a fortement incit\u00e9 les \u00e9tablissements \u00e0 construire leur strat\u00e9gie dans une logique de concurrence afin que chacun puisse le plus possible d\u00e9velopper ses activit\u00e9s de soins et ainsi maximiser ses recettes.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Dans un second temps, dans un objectif de diversification des sources de recettes<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(3)<\/sup>, la Direction g\u00e9n\u00e9rale de l\u2019offre de soins (DGOS) a ouvert les financements des missions d\u2019enseignement, de recherche, de r\u00e9f\u00e9rence et d\u2019innovation (Merri) \u00e0 l\u2019ensemble des \u00e9tablissements de sant\u00e9 alors qu\u2019ils \u00e9taient traditionnellement r\u00e9serv\u00e9s aux seuls centres de lutte contre le cancer (CLCC) et centres hospitaliers universitaires (CHU), dont la recherche fait partie int\u00e9grante de leurs missions. C\u2019est ainsi que depuis un peu moins de dix ans, de plus en plus d\u2019\u00e9tablissements se disputent une enveloppe Merri qui, au pire, diminue, au mieux stagne. Entre 2012 et 2019, le financement de la recherche clinique sur les cr\u00e9dits Merri (part fixe et part variable jusqu\u2019en 2015 puis dotation socle \u00e0 partir de 2016) a diminu\u00e9 de 6\u2009% alors que le taux d\u2019\u00e9volution de l\u2019objectif national des d\u00e9penses d\u2019assurance maladie (Ondam) hospitalier vot\u00e9 chaque ann\u00e9e a \u00e9t\u00e9 de +2,15\u2009% en moyenne (<i>figure 1<\/i>). M\u00eame les r\u00e9centes annonces faites dans le cadre du S\u00e9gur de la sant\u00e9<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(4)<\/sup> ne permettent pas de rattraper ce retard de financement.<\/p>\n<button data-toggle=\"collapse\" data-target=\"#enc_2021_274_01\">Figure 1<\/button><div id=\"enc_2021_274_01\" class=\"encadre collapse\"><p><span class=\"surtitre_enc\">Figure 1<\/span><\/p>\n<h2>\u00c9volution du financement de la recherche clinique (2012-2019)<\/h2>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-43338\" src=\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2021\/05\/Capture-d\u2019\u00e9cran-2021-05-31-\u00e0-11.18.05.png\" alt=\"\" width=\"1676\" height=\"1032\" srcset=\"https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2021\/05\/Capture-d\u2019\u00e9cran-2021-05-31-\u00e0-11.18.05.png 1676w, https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2021\/05\/Capture-d\u2019\u00e9cran-2021-05-31-\u00e0-11.18.05-300x185.png 300w, https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2021\/05\/Capture-d\u2019\u00e9cran-2021-05-31-\u00e0-11.18.05-1024x631.png 1024w, https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2021\/05\/Capture-d\u2019\u00e9cran-2021-05-31-\u00e0-11.18.05-768x473.png 768w, https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2021\/05\/Capture-d\u2019\u00e9cran-2021-05-31-\u00e0-11.18.05-1536x946.png 1536w\" sizes=\"(max-width: 1676px) 100vw, 1676px\" \/><\/p>\n<\/div>\n<p>Parall\u00e8lement, le nombre d\u2019\u00e9tablissements pouvant pr\u00e9tendre \u00e0 la part modulable \u00e9tait de 86 en 2012 contre 133 en 2019 qui \u00e9margent sur la dotation socle. Si ces chiffres t\u00e9moignent d\u2019une r\u00e9elle volont\u00e9 d\u2019ouverture des cr\u00e9dits Merri \u00e0 l\u2019ensemble des \u00e9tablissements de sant\u00e9, le nombre d\u2019\u00e9tablissements<span class=\"Apple-converted-space\">\u00a0 <\/span>pratiquant une activit\u00e9 de recherche clinique ouvrant droit \u00e0 des cr\u00e9dits Merri<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(5)<\/sup> reste relativement modeste. \u00c0 enveloppe constante, cet effort d\u2019universalisation de la recherche clinique a n\u00e9anmoins eu pour effet de disperser entre \u00e9tablissements de sant\u00e9 les cr\u00e9dits disponibles, et en particulier de diminuer la part des CHU, alors que ce sont les plus \u00e0 m\u00eame de tenir la position \u00e9lev\u00e9e de la France dans un environnement international extr\u00eamement concurrentiel. Dans son \u00ab\u2009Panorama de la production scientifique globale des 32 CHU-CHR\u2009\u00bb, le Comit\u00e9 national de coordination de la recherche (CNCR) a mis en \u00e9vidence que, toutes disciplines confondues, sur la p\u00e9riode 2006-2015, les CHU ont contribu\u00e9 \u00e0 hauteur de 17\u2009% de la production scientifique fran\u00e7aise et \u00e0 55\u2009% des publications biom\u00e9dicales fran\u00e7aises.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Depuis plusieurs ann\u00e9es, les centres hospitaliers g\u00e9n\u00e9raux, \u00e9tablissements priv\u00e9s et \u00e9tablissements priv\u00e9s \u00e0 but non lucratif (Espic) ont pu s\u2019engager dans la recherche clinique dans l\u2019objectif d\u2019atteindre une production scientifique suffisante pour b\u00e9n\u00e9ficier de la dotation socle. Mais la recherche clinique \u00e9tant une activit\u00e9 complexe et exigeante, ils ont d\u00fb consentir des investissements importants, qu\u2019il s\u2019agisse de moyens mat\u00e9riels mais surtout humains avec le recrutement de personnels sp\u00e9cialis\u00e9s et d\u00e9di\u00e9s. Ces \u00e9tablissements voient donc en premier lieu leur int\u00e9r\u00eat \u00e0 d\u00e9velopper seuls leur propre activit\u00e9 de recherche clinique pour pouvoir pr\u00e9tendre aux financements Merri. Des projets de coop\u00e9ration sont<i> a priori<\/i> per\u00e7us comme une concurrence en d\u00e9faveur des \u00e9tablissements les moins aguerris, entretenant <i>de facto<\/i> une logique d\u2019opposition.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Cette politique n\u2019est <i>a priori<\/i> pas sans effet sur la qualit\u00e9 de la production fran\u00e7aise. Cinq \u00e0 sept ans \u00e9tant n\u00e9cessaires entre le lancement d\u2019un projet de recherche et sa publication, les \u00e9ventuels effets de la diminution des financements initi\u00e9e en 2012 devraient commencer \u00e0 se percevoir \u00e0 compter de 2017. C\u2019est justement l\u2019ann\u00e9e \u00e0 partir de laquelle on peut noter un fl\u00e9chissement des publications les plus qualitatives. L\u2019analyse des parts relatives de chaque cat\u00e9gorie d\u2019\u00e9tablissement est \u00e0 mettre en perspective de leur volume respectif de publications de rangs A et B avec un auteur en premi\u00e8re ou derni\u00e8re position (<i>figure 2<\/i>). Ainsi, la production des CHU demeure largement sup\u00e9rieure \u00e0 4\u2009000\u00a0publications annuelles alors que l\u2019activit\u00e9 cumul\u00e9e des CH, \u00e9tablissements priv\u00e9s et Espic varie entre 400 et 700\u00a0publications annuelles. Malgr\u00e9 ces chiffres notables, la Cour des comptes s\u2019inqui\u00e9tait de la capacit\u00e9 des CHU \u00e0 rester comp\u00e9titifs et visibles sur le plan international<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(6)<\/sup>.<\/p>\n<button data-toggle=\"collapse\" data-target=\"#enc_2021_274_02\">Figure 2<\/button><div id=\"enc_2021_274_02\" class=\"encadre collapse\"><p><span class=\"surtitre_enc\">Figure 2<\/span><\/p>\n<h2>\u00c9volution des publications scientifiques de rangs A et B\u00a0avec un auteur en premi\u00e8re ou derni\u00e8re position (2012-2018)<\/h2>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-43339\" src=\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2021\/05\/Capture-d\u2019\u00e9cran-2021-05-31-\u00e0-11.18.34.png\" alt=\"\" width=\"1152\" height=\"528\" srcset=\"https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2021\/05\/Capture-d\u2019\u00e9cran-2021-05-31-\u00e0-11.18.34.png 1152w, https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2021\/05\/Capture-d\u2019\u00e9cran-2021-05-31-\u00e0-11.18.34-300x138.png 300w, https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2021\/05\/Capture-d\u2019\u00e9cran-2021-05-31-\u00e0-11.18.34-1024x469.png 1024w, https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2021\/05\/Capture-d\u2019\u00e9cran-2021-05-31-\u00e0-11.18.34-768x352.png 768w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-43340\" src=\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2021\/05\/Capture-d\u2019\u00e9cran-2021-05-31-\u00e0-11.18.40.png\" alt=\"\" width=\"876\" height=\"422\" srcset=\"https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2021\/05\/Capture-d\u2019\u00e9cran-2021-05-31-\u00e0-11.18.40.png 876w, https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2021\/05\/Capture-d\u2019\u00e9cran-2021-05-31-\u00e0-11.18.40-300x145.png 300w, https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2021\/05\/Capture-d\u2019\u00e9cran-2021-05-31-\u00e0-11.18.40-768x370.png 768w\" sizes=\"(max-width: 876px) 100vw, 876px\" \/><\/p>\n<\/div>\n<h1>Une forte concurrence internationale<\/h1>\n<p>La recherche scientifique et technologique en g\u00e9n\u00e9ral, en sant\u00e9 en particulier, constitue un enjeu majeur de rayonnement international pour la France. Depuis 2010, l\u2019\u00c9tat investit massivement dans la recherche et sa valorisation via le programme d\u2019investissement d\u2019avenir (PIA 1, 2 et 3 dot\u00e9s de 57\u00a0milliards d\u2019euros), puis le grand plan d\u2019investissement 2018-2022 (57\u00a0milliards d\u2019euros \u00e9galement). Il s\u2019agit de soutenir la politique industrielle fran\u00e7aise pour passer du statut de pays suiveur \u00e0 celui de pays leader en termes d\u2019innovation. D\u00e8s lors, la recherche s\u2019inscrit \u00e0 l\u2019\u00e9chelle internationale dans un environnement extr\u00eamement comp\u00e9titif.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Si la France demeure, par son avance pr\u00e9alablement acquise, le premier pays en termes de recherche clinique en Europe<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(7)<\/sup>, la situation se d\u00e9grade. En effet, le nombre d\u2019essais \u00e0 promotion industrielle recule r\u00e9guli\u00e8rement depuis plusieurs ann\u00e9es, sans que l\u2019augmentation du nombre d\u2019essais cliniques \u00e0 promotion acad\u00e9mique parvienne \u00e0 compenser l\u2019\u00e9cart. Plusieurs rapports alertent les pouvoirs publics sur cette d\u00e9gradation qui traduit une nette diminution de l\u2019attractivit\u00e9 fran\u00e7aise<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(8)<\/sup>.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Cette perte de vitesse s\u2019explique par plusieurs facteurs. Tout d\u2019abord des fortes contraintes juridiques, certes un gage d\u2019\u00e9thique et de rigueur dans la validation des protocoles mais aussi une source de d\u00e9lais incompatibles avec l\u2019intensit\u00e9 de la comp\u00e9tition<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(9)<\/sup>. Par ailleurs, les financements publics de la recherche ne sont pas \u00e0 la hauteur des besoins et des co\u00fbts de l\u2019innovation qui ne cessent d\u2019augmenter afin d\u2019accompagner la permanence du progr\u00e8s m\u00e9dical. Le rapport annexe de l\u2019avant-projet de loi de programmation de la recherche pour 2021-2030 mentionne un risque de d\u00e9crochage de la France en termes d\u2019investissements, avec un effort de recherche global (public et priv\u00e9) de 2,19\u2009% du produit int\u00e9rieur brut (valeur 2017) contre 2,79\u2009% aux \u00c9tats-Unis et 2,37\u2009% en moyenne pour l\u2019Organisation de coop\u00e9ration et de d\u00e9veloppement \u00e9conomiques (OCDE). Alors que cet effort global \u00e9tait de 2,28\u2009% en 2014, la France s\u2019est progressivement \u00e9loign\u00e9e de l\u2019objectif des 3\u2009% fix\u00e9s dans la strat\u00e9gie de Lisbonne<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(10)<\/sup>, axe majeur de la politique \u00e9conomique et de d\u00e9veloppement de l\u2019Union europ\u00e9enne entre 2000 et 2010.<\/p>\n<blockquote><p>L\u2019\u00e9gal acc\u00e8s \u00e0 l\u2019innovation en tout point du territoire doit donc ind\u00e9niablement s\u2019ancrer dans les projets des \u00e9tablissements de sant\u00e9 et des territoires.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p><\/blockquote>\n<h1>Les enjeux de la m\u00e9decine et de la recherche de demain<span class=\"Apple-converted-space\">\u00a0<\/span><\/h1>\n<p>La m\u00e9decine du XX<sup>e<\/sup>\u00a0si\u00e8cle a \u00e9t\u00e9 avant tout une m\u00e9decine dite \u00ab\u2009curative\u2009\u00bb, c\u2019est-\u00e0-dire ax\u00e9e sur le soin et la prise en charge d\u2019une pathologie. Mais depuis le d\u00e9but du XXI<sup>e<\/sup>\u00a0si\u00e8cle et l\u2019av\u00e8nement de l\u2019\u00e8re du num\u00e9rique, la pratique m\u00e9dicale se transforme, avec une convergence de trois composantes jusqu\u2019alors relativement distinctes\u2009: m\u00e9decine, <i>big data<\/i> et patient.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>En 2013, le Dr Leroy Hood<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(11)<\/sup> th\u00e9orise la m\u00e9decine des \u00ab\u20094P\u2009\u00bb\u2009:<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<ul>\n<li>personnalis\u00e9e, car tenant compte du profil g\u00e9n\u00e9tique ou prot\u00e9ique d\u2019un individu,<span class=\"Apple-converted-space\">\u00a0<\/span><\/li>\n<li>pr\u00e9ventive, car prenant en consid\u00e9ration les probl\u00e8mes de sant\u00e9 en se concentrant sur le mieux-\u00eatre et non la maladie,<\/li>\n<li>pr\u00e9dictive, car indiquant les traitements les plus appropri\u00e9s pour le patient,<\/li>\n<li>participative, car amenant les patients \u00e0 \u00eatre plus responsables en ce qui concerne leur sant\u00e9 et leurs soins.<span class=\"Apple-converted-space\">\u00a0<\/span><\/li>\n<\/ul>\n<p>Le socle de la m\u00e9decine des 4P repose incontestablement sur l\u2019essor des biotechnologies et la r\u00e9volution num\u00e9rique, avec l\u2019\u00e9mergence d\u2019un nouveau corpus de connaissances sur l\u2019individu. Le suivi individuel, r\u00e9gulier et dans la dur\u00e9e de l\u2019\u00e9volution de nombreuses pathologies chroniques, quelle qu\u2019en soit la nature (cancer, affections cardio-vasculaires, maladies neurologiques et musculaires, maladies respiratoires, pathologies endocriniennes, maladies infectieuses, etc.), alimente des bases de donn\u00e9es grandissantes qui permettent de segmenter de plus en plus finement les populations, jusqu\u2019\u00e0 l\u2019\u00e9chelle d\u2019un patient dans ce qu\u2019il a de plus singulier.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>L\u2019av\u00e8nement des 4P transforme certes la pratique de la m\u00e9decine mais, en premier lieu, la pratique de la recherche elle-m\u00eame qui s\u2019oriente vers des travaux d\u00e9sormais ax\u00e9s sur la validation de biomarqueurs, la d\u00e9couverte de th\u00e9rapies cibl\u00e9es bas\u00e9es sur des profils mol\u00e9culaires, etc. Le besoin accru de donn\u00e9es de sant\u00e9 modifie les besoins de recrutement de patients en \u00e9largissant les inclusions bien au-del\u00e0 des seuls CHU et autres gros centres.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<h1>La territorialisation de la recherche clinique<span class=\"Apple-converted-space\">\u00a0<\/span><\/h1>\n<p>En ce sens, les GHT constituent une v\u00e9ritable opportunit\u00e9 pour impliquer l\u2019ensemble des \u00e9tablissements de sant\u00e9 \u2013 <i>a fortiori<\/i> les \u00e9tablissements publics \u2013 et ainsi permettre aux patients d\u2019acc\u00e9der \u00e0 la recherche clinique au minimum via la constitution de cohortes. Par ailleurs, pour les \u00e9tablissements dont les infrastructures permettent de r\u00e9pondre aux bonnes pratiques cliniques, les GHT doivent aussi permettre de favoriser en proximit\u00e9 l\u2019inclusion de patients dans des essais th\u00e9rapeutiques promus par les \u00e9tablissements supports et\/ou les \u00e9tablissements associ\u00e9s des GHT. Il s\u2019agit ainsi de mettre en place une gradation de l\u2019offre de recherche clinique en fonction des moyens techniques et humains disponibles dans chaque \u00e9tablissement, suivant un \u00e9ventail recherche interventionnelle\/recherche interventionnelle \u00e0 risques et contraintes minimes\/recherche non interventionnelle.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Combiner recherche clinique et coop\u00e9rations territoriales poss\u00e8de une triple vertu\u2009:<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<ul>\n<li>diversifier le profil des patients recrut\u00e9s, aussi bien en termes de crit\u00e8res sociaux, culturels, environnementaux que d\u2019habitude de vie\u2009;<\/li>\n<li>recruter plus rapidement le nombre de patients n\u00e9cessaires \u00e0 l\u2019\u00e9tude clinique\u2009;<\/li>\n<li>augmenter significativement le nombre de patients recrut\u00e9s sur un m\u00eame territoire,<\/li>\n<li>\u2026\u2009l\u2019ensemble renfor\u00e7ant la robustesse des protocoles men\u00e9s \u00e0 bien.<span class=\"Apple-converted-space\">\u00a0<\/span><\/li>\n<\/ul>\n<p>Par ailleurs, pour les \u00e9tablissements de sant\u00e9, pratiquer une activit\u00e9 de recherche clinique se r\u00e9v\u00e8le \u00eatre un v\u00e9ritable atout en termes de rayonnement. C\u2019est tout d\u2019abord un facteur ind\u00e9niable de progr\u00e8s m\u00e9dical et de cr\u00e9ation de connaissances scientifiques. Cet aspect intellectuellement stimulant fait de cette activit\u00e9 un argument majeur en termes d\u2019attractivit\u00e9 m\u00e9dicale et donc de recrutement et de fid\u00e9lisation des praticiens. Outre le caract\u00e8re scientifique et acad\u00e9mique, la recherche s\u00e9duit \u00e9galement les praticiens pour sa pratique en \u00e9quipe et la \u00ab\u2009bouff\u00e9e d\u2019oxyg\u00e8ne\u2009\u00bb qu\u2019elle repr\u00e9sente dans un quotidien parfois r\u00e9p\u00e9titif, isol\u00e9 et empreint de t\u00e2ches administratives dont les m\u00e9decins ne voient pas le sens. Elle constitue par ailleurs un vecteur d\u2019am\u00e9lioration des pratiques professionnelles par l\u2019exigence de mise \u00e0 jour continue des connaissances voire comp\u00e9tences et permet objectivement d\u2019am\u00e9liorer la prise en charge des patients et de diminuer la mortalit\u00e9<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(12)<\/sup>.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>La recherche constitue ainsi un v\u00e9ritable enjeu de qualit\u00e9 et de s\u00e9curit\u00e9 des soins et, en ce sens, devrait \u00eatre accessible \u2013 autant pour les patients que pour les professionnels \u2013 en tout point du territoire. La recherche porte par ailleurs d\u2019autres effets structurels b\u00e9n\u00e9fiques, notamment en termes d\u2019image de marque, \u00e9largissant ainsi les capacit\u00e9s de recrutement de patients ou limitant leur fuite vers des \u00e9tablissements de r\u00e9f\u00e9rence proposant des traitements plus innovants. Il existe donc un impact financier imm\u00e9diat, en termes \u00e0 la fois de tarification \u00e0 l\u2019activit\u00e9 par la valorisation d\u2019une activit\u00e9 de soins stimul\u00e9e et de financement sur l\u2019enveloppe des Merri si la recherche est suffisamment d\u00e9velopp\u00e9e.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Pour le Pr Jo\u00ebl M\u00e9nard, professeur \u00e9m\u00e9rite de sant\u00e9 publique et ancien directeur g\u00e9n\u00e9ral de la sant\u00e9, \u00ab\u2009dans une recherche m\u00e9dicale \u00e9largie au monde entier au XXI<sup>e<\/sup> si\u00e8cle, la concentration de la recherche m\u00e9dicale de pointe et les changements de son fonctionnement en r\u00e9seaux r\u00e9gionaux, europ\u00e9ens et internationaux sont devenus n\u00e9cessaires<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(13)<\/sup>\u2009\u00bb. L\u2019\u00e9chelle des r\u00e9seaux r\u00e9gionaux peut et doit s\u2019inscrire dans la dynamique des GHT, dont la mont\u00e9e en puissance est certes tr\u00e8s h\u00e9t\u00e9rog\u00e8ne mais incontestable de par la mise en \u0153uvre des projets m\u00e9dico-soignants partag\u00e9s, des fonctions mutualis\u00e9es et des gouvernances d\u00e9di\u00e9es. C\u2019est aujourd\u2019hui une unit\u00e9 de lieu consacr\u00e9e qui peut se conjuguer \u00e0 l\u2019\u00e9chelle des subdivisions universitaires via les conventions d\u2019association. L\u2019esprit de la loi de modernisation de notre syst\u00e8me de sant\u00e9 voulait insuffler un esprit de coop\u00e9ration global et transversal au sein des \u00e9tablissements publics de sant\u00e9. Ne pas capitaliser sur les pr\u00e9mices de ces nouvelles strat\u00e9gies de groupe reviendrait \u00e0 se priver de la dynamique enclench\u00e9e.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Mais territorialiser la recherche clinique par la voie des GHT signifie concr\u00e8tement d\u00e9velopper la recherche clinique dans les CH g\u00e9n\u00e9raux. Il est actuellement difficile de tirer des conclusions quant \u00e0 l\u2019activit\u00e9 de recherche clinique dans les CH tant les situations sont h\u00e9t\u00e9rog\u00e8nes. En 2019, 60\u00a0CH percevaient la dotation socle, un avait une d\u00e9l\u00e9gation \u00e0 la recherche clinique et \u00e0 l\u2019innovation financ\u00e9e (CH de Versailles) et sept une structure d\u2019investigation financ\u00e9e<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(14)<\/sup>. De par les moyens et comp\u00e9tences rares et sp\u00e9cifiques que n\u00e9cessite l\u2019activit\u00e9 de promotion, les CH sont naturellement plus tourn\u00e9s vers l\u2019activit\u00e9 d\u2019investigation qu\u2019ils r\u00e9alisent efficacement. Malgr\u00e9 des r\u00e9sultats encourageants ces derni\u00e8res ann\u00e9es, le d\u00e9veloppement de la recherche clinique dans les CH g\u00e9n\u00e9raux reste une \u00e9tape \u00e0 franchir.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Plusieurs \u00e9l\u00e9ments favorisant les coop\u00e9rations sont \u00e0 relever.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Tout d\u2019abord l\u2019existence, depuis 2011, des groupements interr\u00e9gionaux de recherche clinique et d\u2019innovation (Girci). L\u2019objectif de ces structures interr\u00e9gionales, au nombre de sept, est d\u2019animer et de soutenir la recherche clinique sur cet \u00e9chelon territorial en rationalisant des outils et ressources que peu d\u2019h\u00f4pitaux peuvent d\u00e9velopper seuls\u2009: formation des professionnels de recherche clinique\u2009; appui \u00e0 la r\u00e9alisation de certaines missions sp\u00e9cifiques du promoteur (assurance qualit\u00e9, monitoring, vigilance, \u00e9laboration et diffusion de grilles communes de co\u00fbts\/surco\u00fbts), etc. Par ailleurs, afin d\u2019inciter les \u00e9tablissements publics de sant\u00e9 \u00e0 unir leurs forces, il est d\u00e9sormais offert la possibilit\u00e9 aux \u00e9tablissements parties d\u2019un GHT de d\u00e9clarer ensemble leur activit\u00e9 de recherche aupr\u00e8s de la DGOS dans l\u2019objectif de maximiser les cr\u00e9dits attribuables dans le cadre de la dotation socle<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(15)<\/sup>. D\u2019autre part, mesure de simplification administrative permettant de r\u00e9duire les d\u00e9lais de mise en \u0153uvre des protocoles de recherche clinique, rendue applicable \u00e0 l\u2019ensemble des \u00e9tablissements, maisons et centres de sant\u00e9 par la loi de modernisation de notre syst\u00e8me de sant\u00e9, la convention unique permet la signature d\u2019un seul contrat liant le promoteur industriel et l\u2019ensemble des structures participant au m\u00eame protocole<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(16)<\/sup>.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Le maillage territorial de la recherche clinique est donc un enjeu aussi contemporain que strat\u00e9gique, encourag\u00e9 par les pouvoirs publics, pour le moment plus dans les intentions que dans les financements. En ce sens, le nouveau dispositif de la Haute Autorit\u00e9 de sant\u00e9 (HAS) de certification des \u00e9tablissements de sant\u00e9 pour la qualit\u00e9 des soins pr\u00e9voit deux nouveaux crit\u00e8res en lien avec la territorialisation de la recherche clinique\u2009:<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<ul>\n<li>crit\u00e8re 3.1-08\u2009: \u00ab\u2009L\u2019\u00e9tablissement, investi ou non de missions universitaires, promeut la recherche clinique en son sein ou en lien avec d\u2019autres acteurs du territoire\u2009\u00bb,<\/li>\n<li>crit\u00e8re 3.2-10\u2009: \u00ab\u2009L\u2019\u00e9tablissement, porteur ou non de missions institutionnelles de recherche clinique, favorise l\u2019acc\u00e8s aux innovations pour les patients\u2009\u00bb.<span class=\"Apple-converted-space\">\u00a0<\/span><\/li>\n<\/ul>\n<p>L\u2019\u00e9gal acc\u00e8s \u00e0 l\u2019innovation en tout point du territoire doit donc ind\u00e9niablement s\u2019ancrer dans les projets des \u00e9tablissements de sant\u00e9 et des territoires.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<h1>Conclusion<span class=\"Apple-converted-space\">\u00a0<\/span><\/h1>\n<p>Le d\u00e9veloppement de la recherche clinique dans les territoires reste un objectif \u00e0 atteindre et, pour ce faire, doit \u00eatre pens\u00e9 et structur\u00e9, notamment en termes de financement des coop\u00e9rations. La recherche clinique doit s\u2019adapter dans son organisation pour r\u00e9pondre au paradoxe du \u00ab\u2009en m\u00eame temps\u2009\u00bb\u2009: capitaliser sur l\u2019exp\u00e9rience et les ressources des CHU en concentrant en leur sein les outils et expertises rares pour mieux les ventiler ensuite au b\u00e9n\u00e9fice des \u00e9tablissements du territoire, des \u00e9tablissements parties au GHT en particulier. La mission d\u2019animation territoriale qui incombe aux CHU doit \u00eatre soutenue par un financement sp\u00e9cifique et assortie d\u2019une obligation de r\u00e9sultats, tant sur le nombre que la qualit\u00e9 des protocoles men\u00e9s en commun. \u00c0 l\u2019heure de l\u2019ouverture souhait\u00e9e de l\u2019h\u00f4pital sur ses partenaires des secteurs ambulatoire et m\u00e9dico-social, le p\u00e9rim\u00e8tre des coop\u00e9rations \u2013 au-del\u00e0 des actuels GHT \u2013 n\u00e9cessite d\u2019\u00eatre interrog\u00e9.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Face \u00e0 ces nouveaux enjeux de coop\u00e9ration et de mutualisation, pourrait se poser la question de la pertinence d\u2019\u00e9riger la recherche clinique \u2013 concomitamment aux affaires m\u00e9dicales \u2013 comme une des prochaines fonctions mutualis\u00e9es des GHT.<\/p>\n<script>function PlayerjsAsync(){} if(window[\"Playerjs\"]){PlayerjsAsync();}<\/script>","protected":false},"excerpt":{"rendered":"<p>Le calendrier soutenu pour la constitution des fili\u00e8res de soins et les objectifs ambitieux assign\u00e9s aux fonctions mutualis\u00e9es ont concentr\u00e9 les GHT sur ces finalit\u00e9s princeps. Ainsi, le r\u00e9cent rapport de l\u2019Inspection des affaires sociales (Igas), qui fait \u00e9tat de diverses difficult\u00e9s dans la mise en place, le fonctionnement et donc in fine l\u2019atteinte des objectifs premiers des GHT, ne mentionne pas le d\u00e9veloppement de la recherche clinique comme un&hellip; <\/p>\n","protected":false},"author":23133,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[2,72],"tags":[465,46,1809,23,8507,28,1812],"class_list":["post-43333","post","type-post","status-publish","format-standard","hentry","category-gestions-hospitalieres","category-reflexion","tag-cooperation","tag-financement","tag-ght","tag-merri","tag-parcours","tag-recherche-clinique","tag-territoire"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>D\u00e9velopper la recherche clinique au sein des GHT - Gestions hospitali\u00e8res<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9velopper la recherche clinique au sein des GHT - Gestions hospitali\u00e8res\" \/>\n<meta property=\"og:description\" content=\"Le calendrier soutenu pour la constitution des fili\u00e8res de soins et les objectifs ambitieux assign\u00e9s aux fonctions mutualis\u00e9es ont concentr\u00e9 les GHT sur ces finalit\u00e9s princeps. Ainsi, le r\u00e9cent rapport de l\u2019Inspection des affaires sociales (Igas), qui fait \u00e9tat de diverses difficult\u00e9s dans la mise en place, le fonctionnement et donc in fine l\u2019atteinte des objectifs premiers des GHT, ne mentionne pas le d\u00e9veloppement de la recherche clinique comme un&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/\" \/>\n<meta property=\"og:site_name\" content=\"Gestions hospitali\u00e8res\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gestionshospitalieres\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-01T09:02:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-31T14:43:28+00:00\" \/>\n<meta name=\"author\" content=\"Gestions hospitali\u00e8res\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revue_GH\" \/>\n<meta name=\"twitter:site\" content=\"@revue_GH\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestions hospitali\u00e8res\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/\"},\"author\":{\"name\":\"Gestions hospitali\u00e8res\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f\"},\"headline\":\"D\u00e9velopper la recherche clinique au sein des GHT\",\"datePublished\":\"2021-05-01T09:02:18+00:00\",\"dateModified\":\"2021-05-31T14:43:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/\"},\"wordCount\":3053,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#organization\"},\"keywords\":[\"coop\u00e9ration\",\"financement\",\"GHT\",\"Merri\",\"parcours\",\"recherche clinique\",\"territoire\"],\"articleSection\":[\"Gestions Hospitali\u00e8res\",\"r\u00e9flexion\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/\",\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/\",\"name\":\"D\u00e9velopper la recherche clinique au sein des GHT - Gestions hospitali\u00e8res\",\"isPartOf\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#website\"},\"datePublished\":\"2021-05-01T09:02:18+00:00\",\"dateModified\":\"2021-05-31T14:43:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ricom-web8.com\/gestions\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9velopper la recherche clinique au sein des GHT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#website\",\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/\",\"name\":\"Gestions hospitali\u00e8res\",\"description\":\"la revue des d\u00e9cideurs hospitaliers\",\"publisher\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ricom-web8.com\/gestions\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#organization\",\"name\":\"Gestions hospitali\u00e8res\",\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png\",\"contentUrl\":\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png\",\"width\":512,\"height\":512,\"caption\":\"Gestions hospitali\u00e8res\"},\"image\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/gestionshospitalieres\/\",\"https:\/\/x.com\/revue_GH\",\"https:\/\/www.linkedin.com\/company\/gestions-hospitalieres?trk=top_nav_home\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f\",\"name\":\"Gestions hospitali\u00e8res\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g\",\"caption\":\"Gestions hospitali\u00e8res\"},\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/author\/benjamin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9velopper la recherche clinique au sein des GHT - Gestions hospitali\u00e8res","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9velopper la recherche clinique au sein des GHT - Gestions hospitali\u00e8res","og_description":"Le calendrier soutenu pour la constitution des fili\u00e8res de soins et les objectifs ambitieux assign\u00e9s aux fonctions mutualis\u00e9es ont concentr\u00e9 les GHT sur ces finalit\u00e9s princeps. Ainsi, le r\u00e9cent rapport de l\u2019Inspection des affaires sociales (Igas), qui fait \u00e9tat de diverses difficult\u00e9s dans la mise en place, le fonctionnement et donc in fine l\u2019atteinte des objectifs premiers des GHT, ne mentionne pas le d\u00e9veloppement de la recherche clinique comme un&hellip;","og_url":"https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/","og_site_name":"Gestions hospitali\u00e8res","article_publisher":"https:\/\/www.facebook.com\/gestionshospitalieres\/","article_published_time":"2021-05-01T09:02:18+00:00","article_modified_time":"2021-05-31T14:43:28+00:00","author":"Gestions hospitali\u00e8res","twitter_card":"summary_large_image","twitter_creator":"@revue_GH","twitter_site":"@revue_GH","twitter_misc":{"\u00c9crit par":"Gestions hospitali\u00e8res","Dur\u00e9e de lecture estim\u00e9e":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/#article","isPartOf":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/"},"author":{"name":"Gestions hospitali\u00e8res","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f"},"headline":"D\u00e9velopper la recherche clinique au sein des GHT","datePublished":"2021-05-01T09:02:18+00:00","dateModified":"2021-05-31T14:43:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/"},"wordCount":3053,"commentCount":0,"publisher":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#organization"},"keywords":["coop\u00e9ration","financement","GHT","Merri","parcours","recherche clinique","territoire"],"articleSection":["Gestions Hospitali\u00e8res","r\u00e9flexion"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/","url":"https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/","name":"D\u00e9velopper la recherche clinique au sein des GHT - Gestions hospitali\u00e8res","isPartOf":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#website"},"datePublished":"2021-05-01T09:02:18+00:00","dateModified":"2021-05-31T14:43:28+00:00","breadcrumb":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ricom-web8.com\/gestions\/developper-la-recherche-clinique-au-sein-des-ght\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ricom-web8.com\/gestions\/"},{"@type":"ListItem","position":2,"name":"D\u00e9velopper la recherche clinique au sein des GHT"}]},{"@type":"WebSite","@id":"https:\/\/www.ricom-web8.com\/gestions\/#website","url":"https:\/\/www.ricom-web8.com\/gestions\/","name":"Gestions hospitali\u00e8res","description":"la revue des d\u00e9cideurs hospitaliers","publisher":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ricom-web8.com\/gestions\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ricom-web8.com\/gestions\/#organization","name":"Gestions hospitali\u00e8res","url":"https:\/\/www.ricom-web8.com\/gestions\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/","url":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png","contentUrl":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png","width":512,"height":512,"caption":"Gestions hospitali\u00e8res"},"image":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gestionshospitalieres\/","https:\/\/x.com\/revue_GH","https:\/\/www.linkedin.com\/company\/gestions-hospitalieres?trk=top_nav_home"]},{"@type":"Person","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f","name":"Gestions hospitali\u00e8res","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g","caption":"Gestions hospitali\u00e8res"},"url":"https:\/\/www.ricom-web8.com\/gestions\/author\/benjamin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/posts\/43333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/users\/23133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/comments?post=43333"}],"version-history":[{"count":0,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/posts\/43333\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/media?parent=43333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/categories?post=43333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/tags?post=43333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}