

{"id":44678,"date":"2022-02-01T16:33:01","date_gmt":"2022-02-01T15:33:01","guid":{"rendered":"https:\/\/gestions-hospitalieres.fr\/?p=44678"},"modified":"2022-03-02T17:07:53","modified_gmt":"2022-03-02T16:07:53","slug":"assistants-familiaux","status":"publish","type":"post","link":"https:\/\/www.ricom-web8.com\/gestions\/assistants-familiaux\/","title":{"rendered":"Assistants familiaux"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture\u00a0: <\/span> <span class=\"rt-time\"> 8<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><p>Selon l\u2019article L.421-2 du code de l\u2019action sociale et des familles (CASF), \u00ab\u2009l\u2019assistant familial est la personne qui, moyennant r\u00e9mun\u00e9ration, accueille habituellement et de fa\u00e7on permanente des mineurs et des jeunes majeurs de moins de vingt et un ans \u00e0 son domicile. Son activit\u00e9 s\u2019ins\u00e8re dans un dispositif de protection de l\u2019enfance, un dispositif m\u00e9dico-social ou un service d\u2019accueil familial th\u00e9rapeutique. Il exerce sa profession comme salari\u00e9 de personnes morales de droit public ou de personnes morales de droit priv\u00e9 [\u2026], apr\u00e8s avoir \u00e9t\u00e9 agr\u00e9\u00e9 \u00e0 cet effet. L\u2019assistant familial constitue, avec l\u2019ensemble des personnes r\u00e9sidant \u00e0 son domicile, une famille d\u2019accueil\u2009\u00bb.<\/p>\n<p>La loi distingue les assistants familiaux employ\u00e9s par des personnes morales de droit priv\u00e9 et les assistants familiaux employ\u00e9s par des personnes morales de droit public, tout en pr\u00e9cisant que les assistants familiaux employ\u00e9s par le d\u00e9partement ou par un \u00e9tablissement public sont des agents non titulaires de la fonction publique (art\u00a0L.422-6 et L.422-7 du CASF). Par cons\u00e9quent, ces derniers ont un statut particulier et sont r\u00e9gis par des dispositions hybrides\u2009: code du travail et code g\u00e9n\u00e9ral de la fonction publique (CGFP). Fin 2017, au moins 90\u2009% des assistants familiaux \u00e9taient directement employ\u00e9s par les d\u00e9partements<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(2)<\/sup>. <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Pendant longtemps, les familles d\u2019accueil n\u2019ont pas b\u00e9n\u00e9fici\u00e9 d\u2019un r\u00e9el encadrement juridique. Ce n\u2019est qu\u2019en 1977, avec la loi n\u00b077-505 du 17 mai relative aux assistantes maternelles, que la fonction de famille d\u2019accueil pour enfants en difficult\u00e9 est pour la premi\u00e8re fois organis\u00e9e. Le 12 juillet 1992, la loi n\u00b0\u200992 642 relative aux assistants maternels et assistantes maternelles et modifiant le code de la famille et de l\u2019aide sociale d\u00e9signe les familles d\u2019accueil comme des \u00ab\u2009assistants maternels permanents\u2009\u00bb, qui rel\u00e8vent alors du m\u00eame cadre juridique que les assistants maternels. Le 27 juin 2005, la loi n\u00b0\u20092005-706 relative aux assistants maternels et aux assistants familiaux a finalement diff\u00e9renci\u00e9 ce m\u00e9tier de la garde d\u2019enfant ponctuelle.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Aujourd\u2019hui, la profession traverse une grave crise et peine \u00e0 recruter tant elle est difficile et insuffisamment valoris\u00e9e. Il manque ainsi de nombreux assistants familiaux pour faire face aux demandes de placement des enfants, et la crise sanitaire a aggrav\u00e9 la situation. Le 20\u00a0mai\u00a02021, les assistants familiaux \u00e9taient en gr\u00e8ve pour demander une revalorisation salariale, une reconnaissance de leur profession et des jours de cong\u00e9. Il \u00e9tait plus que n\u00e9cessaire de l\u00e9gif\u00e9rer.<\/p>\n<p>Renforcer l\u2019attractivit\u00e9 du m\u00e9tier d\u2019assistant familial est l\u2019un des objectifs de la loi n\u00b02022-140 du 7 f\u00e9vrier 2022 relative \u00e0 la protection des enfants qui entend am\u00e9liorer la situation des enfants prot\u00e9g\u00e9s par l\u2019ASE. Dans son titre IV \u00ab\u2009Am\u00e9liorer l\u2019exercice du m\u00e9tier d\u2019assistant familial\u2009\u00bb (art.\u200928 \u00e0 31), plusieurs mesures importantes sont act\u00e9es.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<ul>\n<li>La reconnaissance du r\u00f4le des assistants familiaux, avec participation \u00e0 l\u2019\u00e9laboration et au suivi du projet pour l\u2019enfant. Les assistants familiaux \u00e9tant trop souvent mis \u00e0 l\u2019\u00e9cart des d\u00e9cisions importantes concernant l\u2019enfant, la loi du 7 f\u00e9vrier 2022 ajoute un article L.421-17-2 au CASF\u2009: \u00ab\u2009L\u2019employeur assure l\u2019accompagnement et le soutien professionnels des assistants familiaux qu\u2019il emploie. \u00c0 cette fin, l\u2019assistant familial est int\u00e9gr\u00e9 dans une \u00e9quipe de professionnels qualifi\u00e9s dans les domaines social, \u00e9ducatif, psychologique et m\u00e9dical. Il participe \u00e0 l\u2019\u00e9laboration et au suivi du projet pour l\u2019enfant [\u2026].\u2009\u00bb \u00c0 noter que ces dispositions entreront en vigueur \u00e0 une date fix\u00e9e par d\u00e9cret, et au plus tard le 1<sup>er<\/sup> septembre 2022.<\/li>\n<li>La revalorisation et l\u2019harmonisation de la r\u00e9mun\u00e9ration des assistants familiaux. Les dispositions r\u00e9glementaires actuellement en vigueur ne constituent qu\u2019un montant plancher de r\u00e9mun\u00e9ration. Or, il a \u00e9t\u00e9 constat\u00e9 que les r\u00e9mun\u00e9rations des assistants familiaux varient selon les d\u00e9partements\u2009: elles sont en effet librement fix\u00e9es par d\u00e9lib\u00e9ration du conseil d\u00e9partemental lorsque le d\u00e9partement les emploie directement (art.\u00a0L.422-1 du CASF) et fix\u00e9es dans le cadre du contrat de travail, selon les stipulations de la convention collective applicable, pour ceux employ\u00e9s par des personnes de droit priv\u00e9. Le montant de la r\u00e9mun\u00e9ration fluctue en fonction du nombre d\u2019enfants accueillis alors que le montant fixe ne permet pas de garantir un revenu d\u00e9cent aux assistants familiaux n\u2019accueillant qu\u2019un enfant. Au 1<sup>er<\/sup> janvier 2021, la fonction globale est r\u00e9mun\u00e9r\u00e9e au moins 512,50 \u20ac brut par mois (forfait de base, vers\u00e9, y compris si aucun enfant n\u2019est accueilli), l\u2019accueil d\u2019un enfant 1\u2009230 \u20ac brut (qui comprend le forfait de base)<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(3)<\/sup>.<br \/>\nLa r\u00e9forme propose une nouvelle r\u00e9daction de l\u2019article L.423-30 du CASF\u2009: \u00ab\u2009Sous r\u00e9serve de dispositions contractuelles et conventionnelles plus favorables et sans pr\u00e9judice des indemnit\u00e9s et fournitures qui leur sont remises pour l\u2019entretien des enfants, les assistants familiaux [\u2026] b\u00e9n\u00e9ficient d\u2019une r\u00e9mun\u00e9ration garantie correspondant \u00e0 la dur\u00e9e mentionn\u00e9e dans le contrat d\u2019accueil [\u2026]. Les \u00e9l\u00e9ments de cette r\u00e9mun\u00e9ration et son montant minimal sont d\u00e9termin\u00e9s par d\u00e9cret en r\u00e9f\u00e9rence au salaire minimum de croissance [Smic]. Ce montant minimal varie selon que l\u2019accueil est continu ou intermittent [\u2026], et en fonction du nombre d\u2019enfants accueillis confi\u00e9s par un ou plusieurs employeurs. Il ne peut \u00eatre inf\u00e9rieur au salaire minimum de croissance mensuel. La r\u00e9mun\u00e9ration cesse d\u2019\u00eatre vers\u00e9e lorsque l\u2019enfant accueilli quitte d\u00e9finitivement le domicile de l\u2019assistant familial. L\u2019employeur verse \u00e0 l\u2019assistant familial une indemnit\u00e9 dont le montant ne peut \u00eatre inf\u00e9rieur \u00e0 80\u2009% de la r\u00e9mun\u00e9ration pr\u00e9vue par le contrat, hors indemnit\u00e9s et fournitures, pour les accueils non r\u00e9alis\u00e9s, lorsque le nombre d\u2019enfants qui lui sont confi\u00e9s est inf\u00e9rieur aux pr\u00e9visions du contrat du fait de l\u2019employeur\u2009\u00bb.<span class=\"Apple-converted-space\"><br \/>\n<\/span>La derni\u00e8re partie de l\u2019article n\u2019est toutefois pas applicable aux accueils pr\u00e9vus \u00e0 l\u2019article L.423-30-1 du CASF, c\u2019est-\u00e0-dire aux accueils urgents et de courte dur\u00e9e. Dans cette hypoth\u00e8se, les assistants familiaux concern\u00e9s s\u2019engageant \u00e0 recevoir imm\u00e9diatement les enfants, ils per\u00e7oivent en contrepartie, durant la p\u00e9riode o\u00f9 aucun enfant ne leur est confi\u00e9, une indemnit\u00e9 de disponibilit\u00e9. Son montant minimal est sup\u00e9rieur \u00e0 celui de l\u2019indemnit\u00e9 pr\u00e9vue \u00e0 l\u2019article L.423-30 et est fix\u00e9 par d\u00e9cret en r\u00e9f\u00e9rence au Smic.<br \/>\n\u00c0 l\u2019avenir, il y aura donc une garantie globale de r\u00e9mun\u00e9ration au Smic mensuel qui rehaussera la r\u00e9mun\u00e9ration minimale de l\u2019assistant familial accueillant un seul enfant. Le dispositif entra\u00eenera \u00e9galement une hausse du seuil pour les deuxi\u00e8me et troisi\u00e8me enfants. Par ailleurs, une nouvelle indemnit\u00e9 en cas d\u2019accueil d\u2019enfants non r\u00e9alis\u00e9 du fait de l\u2019employeur est act\u00e9e.<span class=\"Apple-converted-space\">\u00a0<\/span><br \/>\nEnsuite, la loi du 7 f\u00e9vrier 2022 garantit un maintien de la r\u00e9mun\u00e9ration en cas de suspension de l\u2019agr\u00e9ment, hors indemnit\u00e9s d\u2019entretien et de fournitures. Le maintien de la r\u00e9mun\u00e9ration ne peut faire l\u2019objet d\u2019aucune compensation (art.\u00a0L.423-8 du CASF).<span class=\"Apple-converted-space\"><br \/>\n<\/span>Enfin, la loi relative \u00e0 la protection des enfants clarifie les conditions de cumul d\u2019employeurs par un m\u00eame assistant familial. Le futur article L.423-31 du CASF pr\u00e9voit que \u00ab\u2009le contrat de travail pass\u00e9 entre l\u2019assistant familial et son employeur pr\u00e9cise le nombre de mineurs ou de jeunes majeurs \u00e2g\u00e9s de moins de vingt et un ans susceptibles d\u2019\u00eatre confi\u00e9s \u00e0 l\u2019assistant familial, dans les limites pr\u00e9vues par l\u2019agr\u00e9ment de ce dernier. Il peut inclure une clause d\u2019exclusivit\u00e9 ou pr\u00e9voir des restrictions aux possibilit\u00e9s de cumul d\u2019employeurs, si l\u2019employeur est en mesure\u2009:<span class=\"Apple-converted-space\"><br \/>\n<\/span>\u2022 1\u00b0 Soit de lui confier autant d\u2019enfants que le nombre fix\u00e9 par l\u2019agr\u00e9ment d\u00e9tenu par l\u2019assistant familial\u2009;<br \/>\n\u2022 2\u00b0 Soit de compenser ces restrictions par un salaire \u00e9gal \u00e0 celui dont l\u2019assistant familial aurait b\u00e9n\u00e9fici\u00e9 s\u2019il avait effectivement accueilli autant d\u2019enfants que son agr\u00e9ment le permet\u2009\u00bb.<br \/>\nIl est soulign\u00e9 qu\u2019il peut \u00eatre d\u00e9rog\u00e9 aux clauses ou stipulations mentionn\u00e9es dans cet article avec l\u2019accord de l\u2019employeur en cas de situation exceptionnelle et impr\u00e9visible.<br \/>\nToutes ces dispositions entreront en vigueur \u00e0 une date fix\u00e9e par d\u00e9cret, et au plus tard le 1<sup>er<\/sup> septembre 2022.<\/li>\n<li>La possibilit\u00e9 d\u2019attribuer un week-end de repos une fois par mois. Le S\u00e9nat a souhait\u00e9 consacrer les week-ends de repos mensuels\u2009: \u00ab\u2009Le contrat de travail pass\u00e9 entre l\u2019assistant familial et son employeur peut pr\u00e9voir que l\u2019assistant familial b\u00e9n\u00e9ficie d\u2019au moins un samedi et un dimanche de repos cons\u00e9cutifs par mois, qui ne s\u2019imputent pas sur la dur\u00e9e de cong\u00e9s pay\u00e9s qui lui est accord\u00e9e\u2009\u00bb (art. L.423-33-1 du CASF).<\/li>\n<li>La possibilit\u00e9 de diff\u00e9rer le d\u00e9part \u00e0 la retraite. L\u2019assistant familial salari\u00e9 d\u2019une personne morale de droit public se voit appliquer la l\u00e9gislation aff\u00e9rente \u00e0 la fonction publique, notamment pour les dispositions relatives \u00e0 la limite d\u2019\u00e2ge. De ce fait, il appara\u00eet que la limite d\u2019\u00e2ge des agents contractuels, employ\u00e9s par des collectivit\u00e9s territoriales, est fix\u00e9e \u00e0 67 \u00a0ans<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(4)<\/sup>. Si une circulaire minist\u00e9rielle du 4 juillet 1984<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(5)<\/sup> permettait aux assistants familiaux de b\u00e9n\u00e9ficier d\u2019une d\u00e9rogation, la jurisprudence administrative a toutefois estim\u00e9 qu\u2019elle \u00e9tait d\u00e9pourvue de toute valeur r\u00e9glementaire<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(6)<\/sup>.<br \/>\n\u00c0 ce sujet, en 2015, le D\u00e9fenseur des droits a soulign\u00e9 que lorsque des assistants familiaux employ\u00e9s par un d\u00e9partement atteignent cette limite d\u2019\u00e2ge durant la prise en charge de l\u2019enfant, \u00ab\u2009la question du d\u00e9part en retraite est alors brutale et complexe, tant pour l\u2019enfant que pour l\u2019assistant familial<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(7)<\/sup>\u00bb.<br \/>\nEn l\u2019esp\u00e8ce, le D\u00e9fenseur des droits avait \u00e9t\u00e9 saisi de la situation d\u2019un enfant, \u00e2g\u00e9 de 12 ans, accueilli chez un assistant familial, \u00e2g\u00e9 de 68 ans, dans le cadre de son placement. Le conseil d\u00e9partemental envisageait un changement de famille d\u2019accueil de l\u2019enfant du fait de l\u2019atteinte, par l\u2019assistant familial, de l\u2019\u00e2ge limite d\u2019emploi dans la fonction publique. L\u2019assistant familial \u00e9tait dans l\u2019incompr\u00e9hension de cette d\u00e9cision du fait d\u2019un renouvellement r\u00e9cent de son agr\u00e9ment pour une dur\u00e9e de cinq\u00a0ans et s\u2019opposait \u00e0 sa cessation d\u2019activit\u00e9 qui lui semblait contraire \u00e0 l\u2019int\u00e9r\u00eat de l\u2019enfant qui lui avait \u00e9t\u00e9 confi\u00e9. \u00c0 la suite de l\u2019intervention du D\u00e9fenseur des droits, une solution a pu \u00eatre trouv\u00e9e dans l\u2019int\u00e9r\u00eat de l\u2019enfant\u2009: l\u2019assistant familial a \u00e9t\u00e9 recrut\u00e9 par une association de placement familial relevant du secteur priv\u00e9 aupr\u00e8s de qui le juge des enfants, saisi de la situation, a plac\u00e9 directement l\u2019enfant.<br \/>\nD\u00e9sormais, pour \u00e9viter les ruptures de parcours et pr\u00e9server les liens qui se sont construits entre l\u2019assistant familial et l\u2019enfant, l\u2019article L.422-5-1 du CASF est r\u00e9dig\u00e9 de la fa\u00e7on suivante\u2009: \u00ab\u2009Apr\u00e8s avis du m\u00e9decin de pr\u00e9vention, l\u2019assistant familial peut \u00eatre autoris\u00e9, \u00e0 sa demande, \u00e0 travailler au-del\u00e0 de la limite d\u2019\u00e2ge mentionn\u00e9e \u00e0 l\u2019article L.556-11 du CGFP, dans la limite de trois ans, afin de prolonger l\u2019accompagnement du mineur ou du majeur \u00e2g\u00e9 de moins de vingt et un\u00a0ans qu\u2019il accueille. Cette autorisation est d\u00e9livr\u00e9e pour un an. Elle peut \u00eatre renouvel\u00e9e selon les m\u00eames conditions, apr\u00e8s avis du m\u00e9decin de pr\u00e9vention. \u00bb<\/li>\n<li>De nouvelles r\u00e8gles de gestion des agr\u00e9ments. L\u2019agr\u00e9ment pour exercer la profession d\u2019assistant familial est d\u00e9livr\u00e9 par le pr\u00e9sident du conseil d\u00e9partemental du d\u00e9partement o\u00f9 le demandeur r\u00e9side si les conditions d\u2019accueil garantissent la s\u00e9curit\u00e9, la sant\u00e9 et l\u2019\u00e9panouissement des mineurs et majeurs de moins de vingt et un ans accueillis, en tenant compte des aptitudes \u00e9ducatives de la personne (art. L.421-3 du CASF).<br \/>\nDans un rapport d\u2019information d\u00e9pos\u00e9 le 3 juillet 2019 \u00e0 l\u2019Assembl\u00e9e nationale par la mission d\u2019information sur l\u2019aide sociale \u00e0 l\u2019enfance<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(8)<\/sup>, le constat a \u00e9t\u00e9 fait qu\u2019un assistant familial qui se verrait retirer son agr\u00e9ment par un conseil d\u00e9partemental pour des faits n\u00e9cessairement graves pourrait tout \u00e0 fait postuler \u00e0 un agr\u00e9ment dans un autre conseil d\u00e9partemental, qui n\u2019aurait pas connaissance de ces ant\u00e9c\u00e9dents ! D\u00e9sormais, \u00ab en cas de retrait d\u2019un agr\u00e9ment motiv\u00e9 notamment par la commission de faits de violences \u00e0 l\u2019encontre des mineurs accueillis, il ne peut \u00eatre d\u00e9livr\u00e9 de nouvel agr\u00e9ment \u00e0 la m\u00eame personne avant l\u2019expiration d\u2019un d\u00e9lai appropri\u00e9, quel que soit le d\u00e9partement dans lequel la nouvelle demande est le cas \u00e9ch\u00e9ant pr\u00e9sent\u00e9e\u2009\u00bb (art. L.421-6 du CASF). Les modalit\u00e9s de mise en \u0153uvre de cet article seront d\u00e9finies par d\u00e9cret en Conseil d\u2019\u00c9tat. Ce d\u00e9cret devra notamment pr\u00e9ciser les donn\u00e9es enregistr\u00e9es, leur dur\u00e9e de conservation, les conditions de leur mise \u00e0 jour, les cat\u00e9gories de personnes pouvant y acc\u00e9der ou en \u00eatre destinataires. Il s\u2019agit donc de la cr\u00e9ation d\u2019un fichier national des agr\u00e9ments des assistants familiaux, dont l\u2019objectif est d\u2019assurer un accueil s\u00e9curis\u00e9 et de qualit\u00e9 aux enfants confi\u00e9s, notamment en cas de changement de d\u00e9partement. Pour ce faire, la loi a pr\u00e9vu qu\u2019un organisme national unique, sous la forme d\u2019un groupement d\u2019int\u00e9r\u00eat public (GIP) pour la protection de l\u2019enfance, l\u2019adoption et l\u2019acc\u00e8s aux origines personnelles, sera cr\u00e9\u00e9 pour appuyer l\u2019\u00c9tat et les conseils d\u00e9partementaux (art. L.147-14 du CASF).<br \/>\nCe GIP mettra en \u0153uvre une base nationale recensant les agr\u00e9ments d\u00e9livr\u00e9s par les pr\u00e9sidents des conseils d\u00e9partementaux pour l\u2019exercice des professions d\u2019assistant familial ainsi que les suspensions et les retraits d\u2019agr\u00e9ment (art. L.421-7-1 du CASF).<span class=\"Apple-converted-space\"><br \/>\n<\/span>En toute logique, \u00e0 partir du 1<sup>er<\/sup> novembre 2022, l\u2019agr\u00e9ment ne sera pas accord\u00e9 si l\u2019une des personnes majeures ou mineures \u00e2g\u00e9es d\u2019au moins treize ans vivant au domicile du demandeur (\u00e0 l\u2019exception de celles accueillies en application d\u2019une mesure d\u2019aide sociale \u00e0 l\u2019enfance) est inscrite au fichier judiciaire automatis\u00e9 des auteurs d\u2019infractions sexuelles ou violentes (art. L.421-3 du CASF).<\/li>\n<\/ul>\n<h1>Conclusion<\/h1>\n<p>La loi relative \u00e0 la protection des enfants du 7 f\u00e9vrier 2022 am\u00e9liore incontestablement les conditions de travail des assistants familiaux mais elle devra \u00eatre \u00ab\u2009compl\u00e9t\u00e9e par de nombreux ajouts visant \u00e0 restructurer la formation initiale et continue des assistants familiaux pour mieux prendre en compte les \u00e9volutions du m\u00e9tier et des profils des enfants, \u00e0 mieux int\u00e9grer les assistants familiaux au sein des \u00e9quipes p\u00e9dagogiques, ou encore \u00e0 mieux r\u00e9mun\u00e9rer l\u2019accueil des enfants \u00e0 besoins sp\u00e9cifiques\u2009\u00bb<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(9)<\/sup>. Une question demeure\u2009: est-ce que l\u2019ensemble du dispositif sera suffisant pour relancer l\u2019attractivit\u00e9 d\u2019une profession si essentielle\u2009?<\/p>\n<script>function PlayerjsAsync(){} if(window[\"Playerjs\"]){PlayerjsAsync();}<\/script>","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture\u00a0: <\/span> <span class=\"rt-time\"> 8<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span>Selon l\u2019article L.421-2 du code de l\u2019action sociale et des familles (CASF), \u00ab\u2009l\u2019assistant familial est la personne qui, moyennant r\u00e9mun\u00e9ration, accueille habituellement et de fa\u00e7on permanente des mineurs et des jeunes majeurs de moins de vingt et un ans \u00e0 son domicile. Son activit\u00e9 s\u2019ins\u00e8re dans un dispositif de protection de l\u2019enfance, un dispositif m\u00e9dico-social ou un service d\u2019accueil familial th\u00e9rapeutique. Il exerce sa profession comme salari\u00e9 de personnes morales&hellip; <\/p>\n","protected":false},"author":23133,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[2,70],"tags":[8963,5113,8962,8964,7281,435],"class_list":["post-44678","post","type-post","status-publish","format-standard","hentry","category-gestions-hospitalieres","category-jurisante","tag-accueil-familial","tag-aide-sociale-a-lenfance","tag-assistant-familial","tag-assistant-maternel","tag-casf","tag-protection-de-lenfance"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Assistants familiaux - Gestions hospitali\u00e8res<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ricom-web8.com\/gestions\/assistants-familiaux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assistants familiaux - Gestions hospitali\u00e8res\" \/>\n<meta property=\"og:description\" content=\"Temps de lecture\u00a0:  8 minutesSelon l\u2019article L.421-2 du code de l\u2019action sociale et des familles (CASF), \u00ab\u2009l\u2019assistant familial est la personne qui, moyennant r\u00e9mun\u00e9ration, accueille habituellement et de fa\u00e7on permanente des mineurs et des jeunes majeurs de moins de vingt et un ans \u00e0 son domicile. Son activit\u00e9 s\u2019ins\u00e8re dans un dispositif de protection de l\u2019enfance, un dispositif m\u00e9dico-social ou un service d\u2019accueil familial th\u00e9rapeutique. Il exerce sa profession comme salari\u00e9 de personnes morales&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ricom-web8.com\/gestions\/assistants-familiaux\/\" \/>\n<meta property=\"og:site_name\" content=\"Gestions hospitali\u00e8res\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gestionshospitalieres\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-01T15:33:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-02T16:07:53+00:00\" \/>\n<meta name=\"author\" content=\"Gestions hospitali\u00e8res\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revue_GH\" \/>\n<meta name=\"twitter:site\" content=\"@revue_GH\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestions hospitali\u00e8res\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/assistants-familiaux\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/assistants-familiaux\/\"},\"author\":{\"name\":\"Gestions hospitali\u00e8res\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f\"},\"headline\":\"Assistants familiaux\",\"datePublished\":\"2022-02-01T15:33:01+00:00\",\"dateModified\":\"2022-03-02T16:07:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/assistants-familiaux\/\"},\"wordCount\":2579,\"publisher\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#organization\"},\"keywords\":[\"accueil familial\",\"Aide sociale \u00e0 l\u2019enfance\",\"assistant familial\",\"assistant maternel\",\"CASF\",\"protection de l\u2019enfance\"],\"articleSection\":[\"Gestions Hospitali\u00e8res\",\"JuriSant\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/assistants-familiaux\/\",\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/assistants-familiaux\/\",\"name\":\"Assistants familiaux - Gestions hospitali\u00e8res\",\"isPartOf\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#website\"},\"datePublished\":\"2022-02-01T15:33:01+00:00\",\"dateModified\":\"2022-03-02T16:07:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/assistants-familiaux\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ricom-web8.com\/gestions\/assistants-familiaux\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/assistants-familiaux\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ricom-web8.com\/gestions\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Assistants familiaux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#website\",\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/\",\"name\":\"Gestions hospitali\u00e8res\",\"description\":\"la revue des d\u00e9cideurs hospitaliers\",\"publisher\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ricom-web8.com\/gestions\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#organization\",\"name\":\"Gestions hospitali\u00e8res\",\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png\",\"contentUrl\":\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png\",\"width\":512,\"height\":512,\"caption\":\"Gestions hospitali\u00e8res\"},\"image\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/gestionshospitalieres\/\",\"https:\/\/x.com\/revue_GH\",\"https:\/\/www.linkedin.com\/company\/gestions-hospitalieres?trk=top_nav_home\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f\",\"name\":\"Gestions hospitali\u00e8res\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g\",\"caption\":\"Gestions hospitali\u00e8res\"},\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/author\/benjamin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Assistants familiaux - Gestions hospitali\u00e8res","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ricom-web8.com\/gestions\/assistants-familiaux\/","og_locale":"fr_FR","og_type":"article","og_title":"Assistants familiaux - Gestions hospitali\u00e8res","og_description":"Temps de lecture\u00a0:  8 minutesSelon l\u2019article L.421-2 du code de l\u2019action sociale et des familles (CASF), \u00ab\u2009l\u2019assistant familial est la personne qui, moyennant r\u00e9mun\u00e9ration, accueille habituellement et de fa\u00e7on permanente des mineurs et des jeunes majeurs de moins de vingt et un ans \u00e0 son domicile. Son activit\u00e9 s\u2019ins\u00e8re dans un dispositif de protection de l\u2019enfance, un dispositif m\u00e9dico-social ou un service d\u2019accueil familial th\u00e9rapeutique. Il exerce sa profession comme salari\u00e9 de personnes morales&hellip;","og_url":"https:\/\/www.ricom-web8.com\/gestions\/assistants-familiaux\/","og_site_name":"Gestions hospitali\u00e8res","article_publisher":"https:\/\/www.facebook.com\/gestionshospitalieres\/","article_published_time":"2022-02-01T15:33:01+00:00","article_modified_time":"2022-03-02T16:07:53+00:00","author":"Gestions hospitali\u00e8res","twitter_card":"summary_large_image","twitter_creator":"@revue_GH","twitter_site":"@revue_GH","twitter_misc":{"\u00c9crit par":"Gestions hospitali\u00e8res","Dur\u00e9e de lecture estim\u00e9e":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ricom-web8.com\/gestions\/assistants-familiaux\/#article","isPartOf":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/assistants-familiaux\/"},"author":{"name":"Gestions hospitali\u00e8res","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f"},"headline":"Assistants familiaux","datePublished":"2022-02-01T15:33:01+00:00","dateModified":"2022-03-02T16:07:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/assistants-familiaux\/"},"wordCount":2579,"publisher":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#organization"},"keywords":["accueil familial","Aide sociale \u00e0 l\u2019enfance","assistant familial","assistant maternel","CASF","protection de l\u2019enfance"],"articleSection":["Gestions Hospitali\u00e8res","JuriSant\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ricom-web8.com\/gestions\/assistants-familiaux\/","url":"https:\/\/www.ricom-web8.com\/gestions\/assistants-familiaux\/","name":"Assistants familiaux - Gestions hospitali\u00e8res","isPartOf":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#website"},"datePublished":"2022-02-01T15:33:01+00:00","dateModified":"2022-03-02T16:07:53+00:00","breadcrumb":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/assistants-familiaux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ricom-web8.com\/gestions\/assistants-familiaux\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ricom-web8.com\/gestions\/assistants-familiaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ricom-web8.com\/gestions\/"},{"@type":"ListItem","position":2,"name":"Assistants familiaux"}]},{"@type":"WebSite","@id":"https:\/\/www.ricom-web8.com\/gestions\/#website","url":"https:\/\/www.ricom-web8.com\/gestions\/","name":"Gestions hospitali\u00e8res","description":"la revue des d\u00e9cideurs hospitaliers","publisher":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ricom-web8.com\/gestions\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ricom-web8.com\/gestions\/#organization","name":"Gestions hospitali\u00e8res","url":"https:\/\/www.ricom-web8.com\/gestions\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/","url":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png","contentUrl":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png","width":512,"height":512,"caption":"Gestions hospitali\u00e8res"},"image":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gestionshospitalieres\/","https:\/\/x.com\/revue_GH","https:\/\/www.linkedin.com\/company\/gestions-hospitalieres?trk=top_nav_home"]},{"@type":"Person","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f","name":"Gestions hospitali\u00e8res","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g","caption":"Gestions hospitali\u00e8res"},"url":"https:\/\/www.ricom-web8.com\/gestions\/author\/benjamin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/posts\/44678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/users\/23133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/comments?post=44678"}],"version-history":[{"count":0,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/posts\/44678\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/media?parent=44678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/categories?post=44678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/tags?post=44678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}