

{"id":46643,"date":"2023-05-01T14:07:44","date_gmt":"2023-05-01T12:07:44","guid":{"rendered":"https:\/\/gestions-hospitalieres.fr\/?p=46643"},"modified":"2023-06-08T10:56:37","modified_gmt":"2023-06-08T08:56:37","slug":"les-communautes-de-pratique","status":"publish","type":"post","link":"https:\/\/www.ricom-web8.com\/gestions\/les-communautes-de-pratique\/","title":{"rendered":"Les communaut\u00e9s de pratique"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture\u00a0: <\/span> <span class=\"rt-time\"> 18<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><h1>Des innovations \u00e9mergentes fond\u00e9es sur les interactions entre individus<\/h1>\n<p>Avant toute chose, il faut distinguer deux grandes perspectives fondamentalement diff\u00e9rentes concernant l\u2019accompagnement de l\u2019innovation<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(1)\u2009<\/sup>:<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<ul>\n<li>la premi\u00e8re, rationnelle et instrumentale, est celle du \u00ab\u2009pilotage de l\u2019innovation\u2009\u00bb. Elle se concentre sur les r\u00f4les, les processus, les outils et les m\u00e9thodes et fait l\u2019hypoth\u00e8se que l\u2019innovation peut \u00eatre g\u00e9r\u00e9e et contr\u00f4l\u00e9e. Elle n\u00e9cessite une v\u00e9ritable expertise, qu\u2019il faut parfois aller chercher en dehors de l\u2019h\u00f4pital. Elle implique donc une \u00ab\u2009acculturation\u2009\u00bb des professionnels de sant\u00e9, l\u2019identification et la gestion d\u2019\u00e9ventuelles \u00ab\u2009r\u00e9sistances\u2009\u00bb\u2009;<\/li>\n<li>la seconde repose sur l\u2019id\u00e9e que l\u2019innovation \u00e9merge des interactions sociales et de l\u2019\u00e9change d\u2019id\u00e9es et de connaissances entre individus. La diffusion et la p\u00e9rennisation des innovations r\u00e9sultent du caract\u00e8re local et auto-organis\u00e9 de l\u2019interaction<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(2)<\/sup>. La construction collective du sens donn\u00e9 aux innovations est \u00e9galement d\u00e9terminante selon cette perspective. Si elle n\u2019exclut pas la possibilit\u00e9 d\u2019un contr\u00f4le du processus, celui-ci est secondaire\u2009: il porte sur les conditions contextuelles et organisationnelles renfor\u00e7ant la possibilit\u00e9 d\u2019apparition et de diffusion de l\u2019innovation.<\/li>\n<\/ul>\n<p>Pour le gestionnaire comme pour le chercheur, il est d\u00e8s lors int\u00e9ressant d\u2019identifier des formes \u00e9mergentes connues, susceptibles de faciliter l\u2019action des accompagnateurs de l\u2019innovation. Par exemple des formes de collectifs favorisant le d\u00e9veloppement autonome d\u2019une pratique nouvelle\u2009; des collectifs organis\u00e9s spontan\u00e9ment par les membres, autour de leur int\u00e9r\u00eat commun pour cette pratique. Et qui mettraient naturellement en place un partage de ressources et de connaissances. De tels collectifs existent, ce sont des \u00ab\u2009communaut\u00e9s de pratique<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(3)<\/sup>\u2009\u00bb.<\/p>\n<h2>Des innovations encadr\u00e9es par les logiques professionnelles et manag\u00e9riales<\/h2>\n<p>Comprendre le contexte social de l\u2019innovation, c\u2019est d\u2019abord identifier les structures sociales dans lesquelles sont \u00ab\u2009inclus\u2009\u00bb les individus et qui guident leurs raisonnements, leurs relations et leurs actions. Prenons l\u2019exemple le plus \u00e9vident de la pratique m\u00e9dicale. Le mod\u00e8le biom\u00e9dical guide \u00e0 la fois ce sur quoi le m\u00e9decin porte son attention et sa strat\u00e9gie d\u2019action\u2009: traiter la pathologie. Son identit\u00e9 est aliment\u00e9e par son expertise m\u00e9dicale, tandis que sa l\u00e9gitimit\u00e9 repose sur l\u2019efficience et le fondement scientifique de ses pratiques. Les r\u00e8gles et normes encadrant ses pratiques \u00e9manent d\u2019autorit\u00e9s professionnelles nationales. Cet ensemble d\u2019hypoth\u00e8ses, valeurs, r\u00e8gles, identit\u00e9s et pratiques mat\u00e9rielles ne constitue pas seulement une \u00ab\u2009culture\u2009\u00bb, mais plut\u00f4t ce que les sciences de gestion nomment une \u00ab\u2009logique institutionnelle\u2009\u00bb, en l\u2019occurrence une logique professionnelle<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(4)<\/sup>.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>L\u2019autre principale logique \u00e0 l\u2019h\u00f4pital est la logique \u00ab\u2009manag\u00e9riale\u2009\u00bb<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(5)<\/sup>. Cette derni\u00e8re fonde la l\u00e9gitimit\u00e9, l\u2019identit\u00e9 et l\u2019autorit\u00e9 des individus essentiellement sur les fonctions et positions hi\u00e9rarchiques qu\u2019ils occupent au sein de l\u2019organisation. Le mod\u00e8le (\u00e9conomique) qui sous-tend cette logique guide l\u2019attention des acteurs sur l\u2019efficience de la production et la meilleure affectation des ressources dans un contexte o\u00f9 celles-ci sont limit\u00e9es.<\/p>\n<p>Une logique institutionnelle se manifeste \u00e0 diff\u00e9rents niveaux\u2009: le niveau clinique (micro), le niveau de l\u2019organisation de l\u2019\u00e9tablissement (meso) et le niveau soci\u00e9tal (macro). Quel que soit le niveau, toute innovation est in\u00e9vitablement amen\u00e9e \u00e0 se subordonner, au moins partiellement, aux logiques port\u00e9es par les groupes de personnes ayant le plus d\u2019influence sur les d\u00e9cisions. Cela soul\u00e8ve plusieurs questions\u2009: <i>des innovations ne s\u2019inscrivant pas directement dans ces logiques ont-elles une chance d\u2019\u00e9merger et de se p\u00e9renniser\u2009? Une logique peut-elle \u00e9voluer, au contact d\u2019une logique alternative, pour faciliter l\u2019\u00e9mergence d\u2019innovations\u2009?<\/i><\/p>\n<p>L\u2019\u00e9tude du d\u00e9veloppement de la m\u00e9decine dite \u00ab\u2009int\u00e9grative\u2009\u00bb au sein d\u2019un CHU nous offre une r\u00e9ponse positive, bien que tout en nuances.<\/p>\n<h2>Une logique institutionnelle peut-elle \u00e9voluer localement\u2009? Le cas de la m\u00e9decine int\u00e9grative<\/h2>\n<p>Le centre de gravit\u00e9 de la m\u00e9decine int\u00e9grative est bien la logique m\u00e9dicale. Cependant, l\u2019innovation peut se produire de fa\u00e7on incr\u00e9mentale par l\u2019assimilation de logiques alternatives, le champ des pratiques dites \u00ab\u2009compl\u00e9mentaires\u2009\u00bb dans ce cas<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(6)<\/sup>. Ce processus se joue simultan\u00e9ment aux trois niveaux d\u00e9crits plus haut\u2009:<\/p>\n<ul>\n<li>au niveau clinique, l\u2019innovation impli\u00adque l\u2019engagement de pionniers, adoptant des pratiques qui, bien que valides, ne sont pas toujours valoris\u00e9es par les autres professionnels. Ces pionniers se confrontent aux routines de prise en charge, qu\u2019ils peuvent parfois faire \u00e9voluer localement\u2009;<\/li>\n<li>au niveau de l\u2019organisation, elle implique des prises de d\u00e9cision concernant l\u2019encadrement des pratiques, et l\u2019affectation de ressources pour leur p\u00e9rennisation. Et ce dans un contexte o\u00f9 les modes de financement les excluent de fait des sources de revenu \u00e0 court terme pour l\u2019\u00e9tablissement\u2009;<\/li>\n<li>au niveau de la profession, elle doit gagner en l\u00e9gitimit\u00e9 scientifique selon les r\u00e8gles d\u2019\u00e9valuation commun\u00e9ment admises en recherche m\u00e9dicale. Elle peut \u00e9galement contribuer \u00e0 enrichir le mod\u00e8le biom\u00e9dical par l\u2019incorporation d\u2019\u00e9l\u00e9ments relevant du mod\u00e8le \u00ab\u2009biopsychosocial\u2009\u00bb.<\/li>\n<\/ul>\n<h1>Le r\u00f4le des communaut\u00e9s de pratique<\/h1>\n<p>Nous l\u2019avons dit, une communaut\u00e9 de pratique est \u00ab\u2009un groupe de personnes qui partagent une pr\u00e9occupation, une s\u00e9rie de probl\u00e8mes ou une passion pour un sujet, et qui approfondissent leurs connaissances et leur expertise dans ce domaine en interagissant de mani\u00e8re continue<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(7)\u2009<\/sup>\u00bb.<\/p>\n<p>Contrairement \u00e0 une \u00e9quipe projet, une communaut\u00e9 de pratique ne repose ni sur la d\u00e9signation des membres par un manager, ni sur des objectifs et des \u00e9ch\u00e9ances pr\u00e9d\u00e9termin\u00e9s, ni sur la r\u00e9alisation de t\u00e2ches sp\u00e9cifiques<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(8)<\/sup>. Il s\u2019agit d\u2019un groupe rev\u00eatant des caract\u00e9ristiques tout \u00e0 fait singuli\u00e8res au sein d\u2019une organisation (encadr\u00e9\u00a01).<\/p>\n<p style=\"font-weight: 400;\"><button data-toggle=\"collapse\" data-target=\"#enc_2023_287_01\">encadr\u00e9 1<\/button><div id=\"enc_2023_287_01\" class=\"encadre collapse\"><p><span class=\"surtitre_enc\">encadr\u00e9 1<\/span><\/p>\n<h2>Cinq caract\u00e9ristiques des communaut\u00e9s de pratique*<span class=\"Apple-converted-space\">\u00a0<\/span><\/h2>\n<p>Leur \u00e9mergence est g\u00e9n\u00e9ralement spontan\u00e9e et repose sur l\u2019engagement et l\u2019enthousiasme de ses membres. Ces communaut\u00e9s peuvent cependant, sous certaines conditions, \u00eatre initi\u00e9es par le management.<\/p>\n<p>La participation est libre, fond\u00e9e sur l\u2019int\u00e9r\u00eat pour la pratique partag\u00e9e. Elle peut franchir les barri\u00e8res g\u00e9ographiques, organisationnelles ou professionnelles. La taille de la communaut\u00e9 peut varier dans le temps.<\/p>\n<p>Elles reposent sur les interactions sociales entre les membres, qui cimentent l\u2019identit\u00e9 et l\u2019unit\u00e9 du groupe. La r\u00e9gularit\u00e9 de ces interactions est un facteur de succ\u00e8s. Elles se font de pr\u00e9f\u00e9rence en face \u00e0 face, mais aussi via des outils de communication.<\/p>\n<p>Elles offrent un cadre s\u00e9curisant pour discuter sans jugement de questions relatives au travail, et ce de fa\u00e7on interdisciplinaire.<\/p>\n<p>Elles mettent en relation des personnes d\u2019expertise variable et cr\u00e9ent des opportunit\u00e9s d\u2019apprentissage.<\/p>\n<p><em>* G. Ranmuthugala, F.C. Cunningham, J.J. Plumb, J. Long, A. Georgiou, J.I. Westbrook, J. Braithwaite, \u201cA realist evaluation of the role of communities of practice in changing healthcare practice\u201d, Implementation Science, 6(1), 49, 2011.<\/em> <em>Idem, \u201cHow and why are communities of practice established in the healthcare sector? A systematic review of the literature\u201d, BMC Health Services Research, 2011, 11(1), 273.<\/em><\/p>\n<\/div><\/p>\n<p>S\u2019int\u00e9resser aux communaut\u00e9s de pratique, c\u2019est donc analyser une forme de collectif au sein duquel des processus de cr\u00e9ation de connaissances et de sens se mettent en place spontan\u00e9ment. Mais de quelle fa\u00e7on une telle communaut\u00e9 peut-elle contribuer \u00e0 la diffusion d\u2019une innovation au sein d\u2019une organisation\u2009?<\/p>\n<h2>Relations communaut\u00e9s de pratique\/innovation<\/h2>\n<p>Nous pouvons distinguer quatre types de communaut\u00e9s de pratique<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(9)\u2009<\/sup>: artisanales, professionnelles, d\u2019expertise et virtuelles. Nous nous int\u00e9ressons ici plus particuli\u00e8rement aux communaut\u00e9s professionnelles et d\u2019expertise et \u00e0 leurs relations avec les processus d\u2019innovation\u2009:<\/p>\n<ul>\n<li>les communaut\u00e9s de pratique professionnelles sont men\u00e9es soit par des groupes de pairs, soit par des organisations hi\u00e9rarchiques plus formelles. Elles sont fond\u00e9es sur une logique professionnelle et donc sur le respect des standards et des r\u00e8gles de la profession concern\u00e9e. Elles mettent en commun des connaissances sp\u00e9cialis\u00e9es, acquises par la formation et la pratique. L\u2019\u00e9mergence de solutions innovantes y est souvent incr\u00e9mentale et, si elle peut parfois s\u2019inscrire en rupture, elle reste, dans tous les cas, fortement d\u00e9pendante des r\u00e8gles professionnelles<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(10)\u2009<\/sup>;<\/li>\n<li>les communaut\u00e9s de type expertise (ou \u00ab\u2009de cr\u00e9ation\u2009\u00bb) sont fond\u00e9es non pas sur la qualification mais sur l\u2019expertise. Elles peuvent \u00eatre ouvertes \u00e0 toute personne ayant une l\u00e9gitimit\u00e9 dans le domaine concern\u00e9. Une place plus importante est donn\u00e9e \u00e0 l\u2019exploration et \u00e0 l\u2019exploitation de connaissances nouvelles. Les innovations peuvent s\u2019inscrire en rupture, notamment par la mobilisation d\u2019objets \u00ab\u2009fronti\u00e8res\u2009\u00bb, c\u2019est-\u00e0-dire des technologies ou pratiques qui se situent aux carrefours de diff\u00e9rentes logiques<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(11)<\/sup>.<\/li>\n<\/ul>\n<p>Nous le verrons plus loin, une communaut\u00e9 professionnelle peut \u00e9galement s\u2019ouvrir \u00e0 des expertises ext\u00e9rieures \u00e0 la profession et adopter les caract\u00e9ristiques d\u2019une communaut\u00e9 d\u2019expertise. Le cadre dans lequel s\u2019inscrit l\u2019innovation d\u00e9pend donc de la nature du ciment qui lie les membres de la communaut\u00e9. Autrement dit, lorsque l\u2019identification des membres \u00e0 la communaut\u00e9 de pratique d\u00e9passe les identit\u00e9s professionnelles initiales, le champ des possibles s\u2019\u00e9largit.<\/p>\n<h2>Une communaut\u00e9 de pratique peut-elle porter seule une innovation au sein de l\u2019h\u00f4pital\u2009?<\/h2>\n<p>La p\u00e9rennisation et la diffusion d\u2019une solution innovante port\u00e9e par une communaut\u00e9 de pratique peuvent difficilement se faire sans l\u2019aide de \u00ab\u2009parrains\u2009\u00bb au sein de l\u2019organisation. L\u2019un des r\u00f4les des parrains est de faciliter l\u2019obtention de ressources organisationnelles existantes. Pour cela, les parrains aident \u00e0 tisser un r\u00e9seau de soutien autour de la communaut\u00e9, \u00e0 la fois au sein et \u00e0 l\u2019ext\u00e9rieur de l\u2019organisation. Nous le verrons plus loin, ils peuvent agir comme de v\u00e9ritables \u00ab\u2009intrapreneurs\u2009\u00bb afin de construire des ressources nouvelles.<\/p>\n<p>Ils aident \u00e9galement la communaut\u00e9 \u00e0 prendre conscience des \u00e9preuves auxquelles elle est confront\u00e9e, \u00e0 mesure qu\u2019elle grandit et que la pratique se diffuse au sein de l\u2019organisation. Ils assurent un travail de \u00ab\u2009traduction\u2009\u00bb dans les diff\u00e9rentes logiques afin d\u2019assurer l\u2019articulation de la communaut\u00e9 avec les dispositifs institutionnels existants. Et ce tout en pr\u00e9servant l\u2019autonomie de la communaut\u00e9. Enfin, ils peuvent avoir un r\u00f4le dans la structuration et la diffusion des connaissances. Pour ces diff\u00e9rentes raisons, ils contribuent \u00e0 faire gagner en maturit\u00e9 la communaut\u00e9.<\/p>\n<h1>Exemple de la m\u00e9decine int\u00e9grative \u00e0 l\u2019h\u00f4pital\u2009: l\u2019hypnose \u00e0 l\u2019h\u00f4pital<\/h1>\n<p>L\u2019hypnose est le processus permettant de faire passer de fa\u00e7on temporaire le patient d\u2019un \u00e9tat d\u2019\u00e9veil \u00e0 un \u00e9tat de conscience alt\u00e9r\u00e9e\u2009: l\u2019\u00e9tat hypnotique. Ce dernier ne correspond ni \u00e0 l\u2019\u00e9tat de veille ni \u00e0 l\u2019\u00e9tat de sommeil et se traduit par une attention focalis\u00e9e et une moindre sensibilit\u00e9 \u00e0 l\u2019environnement<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(12)<\/sup>.<\/p>\n<p>La m\u00e9connaissance de cette pratique est fr\u00e9quente et peut susciter la m\u00e9fiance de certains professionnels. Sa l\u00e9gitimit\u00e9 est reconnue par la profession m\u00e9dicale depuis le d\u00e9but des ann\u00e9es 2000<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(13)<\/sup>.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>L\u2019hypnose est utilis\u00e9e dans diff\u00e9rents contextes \u00e0 l\u2019h\u00f4pital, mais son utilisation la plus impressionnante, l\u2019hypnos\u00e9dation, peut \u00eatre observ\u00e9e au sein des blocs op\u00e9ratoires comme adjuvant \u00e0 l\u2019anesth\u00e9sie r\u00e9gionale ou locor\u00e9gionale.<\/p>\n<p>Pratiquement, l\u2019hypnos\u00e9dation au bloc op\u00e9ratoire conjugue trois techniques\u2009:<\/p>\n<ul>\n<li>une anesth\u00e9sie locale ou locor\u00e9gionale\u2009;<\/li>\n<li>une s\u00e9dation (drogue anesth\u00e9sique l\u00e9g\u00e8rement dos\u00e9e) par voie veineuse consciente\u2009;<\/li>\n<li>l\u2019hypnose<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(14)<\/sup>.<span class=\"Apple-converted-space\">\u00a0<\/span><\/li>\n<\/ul>\n<p>L\u2019hypnose est assur\u00e9e par un praticien form\u00e9 du bloc\u2009: le m\u00e9decin anesth\u00e9siste ou l\u2019infirmi\u00e8re anesth\u00e9siste (sous la supervision du m\u00e9decin). Plus l\u2019hypnose est efficace, moins la quantit\u00e9 de s\u00e9datif n\u00e9cessaire est importante pour maintenir le patient dans un \u00e9tat de conscience compatible avec l\u2019intervention. Cette diminution des drogues anesth\u00e9siques est corr\u00e9l\u00e9e avec une diminution des effets secondaires et \u00e0 une facilitation du r\u00e9veil en fin d\u2019intervention. Au contraire, moins l\u2019hypnose est efficace, plus la quantit\u00e9 de s\u00e9datif n\u00e9cessaire est importante, et plus grande est la probabilit\u00e9 de faire perdre conscience au patient.<\/p>\n<h2>L\u2019hypnose, une innovation de rupture \u00e0 l\u2019h\u00f4pital\u2009?<\/h2>\n<p>Le terme \u00ab\u2009hypnose\u2009\u00bb recouvre en r\u00e9alit\u00e9 diff\u00e9rentes techniques et pratiques. Pour les techniques les plus simples, l\u2019innovation pourrait \u00eatre consid\u00e9r\u00e9e comme \u00ab\u2009incr\u00e9mentale\u2009\u00bb. Au contraire, le d\u00e9veloppement de l\u2019hypnose \u00ab\u2009m\u00e9dicale\u2009\u00bb, dans certains contextes comme le bloc op\u00e9ratoire, constitue selon nous une forme d\u2019innovation de rupture. Nous avons identifi\u00e9 quatre principaux niveaux de rupture au sein du bloc gyn\u00e9cologique du CHU \u00e9tudi\u00e9.<\/p>\n<h3>La place donn\u00e9e au patient<\/h3>\n<p>Le choix du recours \u00e0 l\u2019hypnos\u00e9dation comme alternative \u00e0 l\u2019anesth\u00e9sie g\u00e9n\u00e9rale repose exclusivement sur la demande du patient. Mais au-del\u00e0 du choix, l\u2019hypnose n\u00e9cessite une collaboration active de la part de ce dernier. En effet, son succ\u00e8s repose sur la fa\u00e7on dont il accepte les suggestions du praticien et dont il mobilise ses propres ressources (attention, m\u00e9moire\u2026). Du point de vue de l\u2019\u00e9quipe, le patient n\u2019est plus consid\u00e9r\u00e9 comme \u00e9tant dans une posture passive durant l\u2019anesth\u00e9sie. Ce retour en force de la relation soignant\/soign\u00e9 change aussi la fa\u00e7on dont les professionnels se per\u00e7oivent eux-m\u00eames\u2009: \u00ab\u2009On ne pourra plus faire la blague habituelle sur les infirmiers anesth\u00e9sistes, celle qui dit qu\u2019on n\u2019aime pas les patients et que c\u2019est pour \u00e7a qu\u2019on les endort\u2009\u00bb (Iade).<\/p>\n<h3>Le processus interventionnel<\/h3>\n<p>L\u2019hypnos\u00e9dation repose principalement sur l\u2019interaction verbale entre l\u2019anesth\u00e9siste et le patient, et non plus sur le seul geste technique, qui fonde pourtant l\u2019expertise m\u00e9dicale de l\u2019anesth\u00e9siste (l\u2019injection des drogues anesth\u00e9siques). Ce geste est d\u00e9sormais subordonn\u00e9 \u00e0 l\u2019efficacit\u00e9 de l\u2019hypnose. Le patient n\u2019est pas \u00ab\u2009endormi\u2009\u00bb durant l\u2019hypnose, il peut percevoir ce qui se passe dans le bloc et risque de \u00ab\u2009sortir\u2009\u00bb de l\u2019\u00e9tat hypnotique. Les professionnels en salle, de l\u2019infirmi\u00e8re circulante au chirurgien, doivent adapter collectivement leur activit\u00e9 \u00e0 cette nouvelle r\u00e9alit\u00e9<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(15)<\/sup>.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Le recours \u00e0 l\u2019hypnose, que ce soit au bloc ou dans d\u2019autres contextes, ne concerne pas que le seul praticien qui la met en \u0153uvre\u2009: elle implique in\u00e9vitablement toute l\u2019\u00e9quipe, qui doit ainsi repenser ses modes de coordination.<\/p>\n<h3>L\u2019organisation des interventions<\/h3>\n<p>Dans un contexte fortement contraint, guid\u00e9 par un souci d\u2019efficience, l\u2019organisation des prises en charge au bloc op\u00e9ratoire parvient de fa\u00e7on surprenante \u00e0 s\u2019adapter \u00e0 cette nouvelle pratique, notamment par\u2009:<\/p>\n<ul>\n<li>l\u2019adaptation du programme op\u00e9ratoire pour r\u00e9aliser les interventions sous hypnose aux cr\u00e9neaux horaires de plus grande vigilance pour les praticiens\u2009;<\/li>\n<li>la mise en concordance du planning du pool d\u2019infirmiers anesth\u00e9sistes form\u00e9s avec les interventions sous hypnoses programm\u00e9es\u2009;<\/li>\n<li>la mise en place d\u2019une consultation pr\u00e9op\u00e9ratoire d\u2019hypnose pour faciliter l\u2019hypnose le jour de l\u2019intervention\u2009;<\/li>\n<li>la r\u00e9flexion autour d\u2019une nouvelle politique de recrutement et de formation des nouveaux infirmiers anesth\u00e9sistes au bloc gyn\u00e9cologique.<\/li>\n<\/ul>\n<p>Dans un contexte fortement contraint, le recours \u00e0 l\u2019hypnose a amen\u00e9 l\u2019organisation du bloc \u00e0 s\u2019adapter au \u00ab\u2009facteur humain\u2009\u00bb\u2009: comp\u00e9tences disponibles, cr\u00e9neaux favorables \u00e0 la vigilance des praticiens, facilitation de la collaboration soignant\/soign\u00e9\u2026<\/p>\n<h3>Un nouveau mod\u00e8le de soins<\/h3>\n<p>Le mod\u00e8le th\u00e9rapeutique de l\u2019hypnose repose sur l\u2019hypoth\u00e8se de l\u2019efficacit\u00e9 d\u2019une interaction verbale sur le niveau de conscience et de douleur du patient. Ce mod\u00e8le est ici consid\u00e9r\u00e9 par les professionnels comme suffisamment valide et l\u00e9gitime pour se substituer, au moins partiellement, au mod\u00e8le biom\u00e9dical traditionnel dans le cadre d\u2019une intervention chirurgicale au bloc op\u00e9ratoire.<\/p>\n<p>L\u2019adoption de ce nouveau mod\u00e8le de soin a eu des prolongements inattendus au-del\u00e0 des murs du bloc op\u00e9ratoire, sous l\u2019impulsion d\u2019une communaut\u00e9 de pratique\u2009: HypnoCome. Cette communaut\u00e9 agit comme une v\u00e9ritable caisse de r\u00e9sonance, en simplifiant l\u2019expression de ce mod\u00e8le pour en faciliter la diffusion \u00e0 l\u2019\u00e9chelle de l\u2019\u00e9tablissement.<\/p>\n<h2>Le collectif HypnoCome<\/h2>\n<p>HypnoCome a \u00e9t\u00e9 cr\u00e9\u00e9 spontan\u00e9ment en 2016 par un tandem m\u00e9decin anesth\u00e9siste\/infirmi\u00e8re anesth\u00e9siste (Iade) du bloc gyn\u00e9cologique du CHU. Les membres du groupe, initialement issus de cette \u00e9quipe, viennent aujourd\u2019hui d\u2019une grande vari\u00e9t\u00e9 de services de l\u2019h\u00f4pital\u2009: orthop\u00e9die, cardiologie, Smur, r\u00e9animation\u2026 Ils se r\u00e9unissent environ quatre fois par an autour d\u2019un int\u00e9r\u00eat commun\u2009: la pratique de l\u2019hypnose \u00e0 l\u2019h\u00f4pital.<\/p>\n<p>La participation est libre, quels que soient la profession et le service. Les r\u00e9unions se tiennent g\u00e9n\u00e9ralement en fin de journ\u00e9e, lorsque le programme op\u00e9ratoire du bloc gyn\u00e9cologique est termin\u00e9, dans une salle de r\u00e9union d\u2019une quinzaine de places attenante au bloc gyn\u00e9cologique, d\u00e9di\u00e9e habituellement aux r\u00e9unions de staff ainsi qu\u2019aux formations.<\/p>\n<p>Ces r\u00e9unions sont pr\u00e9par\u00e9es et anim\u00e9es par le m\u00e9decin anesth\u00e9siste r\u00e9animateur et l\u2019Iade fondatrices ainsi que par une Iade en orthop\u00e9die faisant office de secr\u00e9taire\u2009; un ordre du jour et une date sont envoy\u00e9s \u00e0 l\u2019ensemble de la communaut\u00e9. La r\u00e9union commence par un tour de table, suivi du traitement des points \u00e0 l\u2019ordre du jour et elle se conclut par des \u00e9changes libres. Les comptes-rendus sont ensuite mis \u00e0 disposition des membres sur le site intranet.<\/p>\n<p>Lors de la r\u00e9union \u00e0 laquelle nous avons assist\u00e9, diff\u00e9rentes pr\u00e9sentations ont \u00e9t\u00e9 faites au vid\u00e9oprojecteur par des participants\u2009: pr\u00e9sentation par un m\u00e9decin gyn\u00e9cologue d\u2019une \u00e9tude concernant le parcours et les attentes des femmes en obst\u00e9trique, pr\u00e9sentation par des \u00e9tudiants de leur travail de m\u00e9moire autour de l\u2019hypnose, mini-formation des participants par une Iade sur un outil pratique d\u2019hypnose. En analysant les comptes-rendus de r\u00e9union sur deux ann\u00e9es et demie, nous avons constat\u00e9 une grande vari\u00e9t\u00e9 d\u2019intervenants (membres du groupe ou invit\u00e9s\u2009: infirmi\u00e8res, m\u00e9decins, psychologues\u2026) et de th\u00e8mes abord\u00e9s\u2009:<\/p>\n<ul>\n<li>pratique de l\u2019hypnose\u2009: techniques, facteurs de succ\u00e8s, retour d\u2019exp\u00e9rience\u2026\u2009;<\/li>\n<li>travaux de recherche sur l\u2019efficacit\u00e9 de l\u2019hypnose\u2009;<\/li>\n<li>opportunit\u00e9s nouvelles de pratique, selon le type de prise en charge et le contexte\u2009;<\/li>\n<li>formes de pratique alternatives\u2009: casque de r\u00e9alit\u00e9 virtuelle, autohypnose\u2026<\/li>\n<li>autres pratiques compl\u00e9mentaires\u2009: m\u00e9ditation de pleine conscience, acupuncture\u2026<\/li>\n<\/ul>\n<p>L\u2019activit\u00e9 d\u2019HypnoCome est ainsi caract\u00e9ris\u00e9e par un processus d\u2019exploration assez intense qui peut d\u00e9boucher sur des exp\u00e9rimentations locales et encadr\u00e9es.<\/p>\n<p>HypnoCome s\u2019est dot\u00e9 assez rapidement d\u2019un site d\u00e9di\u00e9 sur l\u2019intranet du CHU, aliment\u00e9 par l\u2019Iade-secr\u00e9taire qui a suivi une formation sur l\u2019outil de conception web SharePoint. Ce site intranet a un r\u00f4le de pr\u00e9sentation des membres et des activit\u00e9s de la communaut\u00e9, d\u2019agenda des \u00e9v\u00e8nements importants ou encore d\u2019acc\u00e8s \u00e0 l\u2019offre de formation interne et externe en hypnose. Mais il constitue \u00e9galement un outil de gestion documentaire pour les membres. Les documents pr\u00e9sent\u00e9s ainsi que toutes les ressources compl\u00e9mentaires pertinentes sont class\u00e9s et mis \u00e0 disposition sur cet espace num\u00e9rique. Il constitue ainsi une base de connaissances riche. Seul le forum d\u2019\u00e9change num\u00e9rique appara\u00eet inactif\u2009: les rencontres et les \u00e9changes se font exclusivement en face \u00e0 face, ce \u00e0 quoi les membres fondateurs attachent beaucoup d\u2019importance. Il ne s\u2019agit donc pas d\u2019une communaut\u00e9 virtuelle.<\/p>\n<h3>Trois leviers mobilis\u00e9s pour diffuser l\u2019hypnose<\/h3>\n<p>L\u2019une des d\u00e9couvertes de notre \u00e9tude est que la p\u00e9rennisation locale de la pratique de l\u2019hypnose (au bloc gyn\u00e9cologique) a \u00e9t\u00e9 pens\u00e9e \u00e0 travers sa diffusion \u00e0 l\u2019\u00e9chelle de tout l\u2019\u00e9tablissement. Nous illustrons la dynamique d\u2019HypnoCome autour de trois leviers mobilis\u00e9s par ses membres, avec l\u2019aide de leur \u00ab\u2009marraine\u2009\u00bb, cadre sup\u00e9rieure de p\u00f4le.<\/p>\n<h4><i>1\u2009- D\u00e9velopper et rendre accessible le mod\u00e8le de soins<\/i><\/h4>\n<p>L\u2019int\u00e9r\u00eat pour la pratique de l\u2019hypnose s\u2019est d\u00e9velopp\u00e9 par cercles concentriques autour de l\u2019\u00e9quipe pionni\u00e8re du bloc gyn\u00e9cologique. Les demandes de formations informelles se sont ainsi multipli\u00e9es de la part de diff\u00e9rentes unit\u00e9s de l\u2019h\u00f4pital couple\/enfant. Le soutien de la cadre sup\u00e9rieure de p\u00f4le, ancienne cadre de la formation continue, a permis de construire un dispositif favorisant l\u2019enracinement des pratiques \u00e9mergentes, tout en facilitant leur diffusion.<\/p>\n<p>Le d\u00e9veloppement des formations locales est pens\u00e9 \u00e0 travers le d\u00e9veloppement de la formation interne \u00e0 l\u2019\u00e9chelle de tout l\u2019\u00e9tablissement. L\u2019\u00e9quipe de pionniers du bloc gyn\u00e9cologique est de plus en plus souvent sollicit\u00e9e par d\u2019autres \u00e9quipes du p\u00f4le pour animer de courtes sessions de sensibilisation \u00e0 l\u2019hypnose. Sous l\u2019impulsion de la cadre du p\u00f4le Anesth\u00e9sie-r\u00e9animation et avec le soutien du service de la formation continue, le dispositif devient une formation \u00e0 la \u00ab\u2009communication th\u00e9rapeutique\u2009\u00bb. Elle constitue le fondement du mod\u00e8le th\u00e9rapeutique de l\u2019hypnose et est d\u2019ailleurs appel\u00e9e \u00ab\u2009langage de l\u2019hypnose\u2009\u00bb. Elle n\u2019implique pas de plonger le patient en \u00e9tat de transe et peut \u00eatre mobilis\u00e9e dans une grande vari\u00e9t\u00e9 de contextes. Cette formation devient accessible \u00e0 tout le p\u00f4le puis, progressivement, \u00e0 tout l\u2019\u00e9tablissement, avec l\u2019aval de la direction des soins. La dur\u00e9e de la formation passe progressivement d\u2019une demi-journ\u00e9e \u00e0 une journ\u00e9e compl\u00e8te. L\u2019effet d\u2019\u00e9chelle permet ainsi de mobiliser une enveloppe de formation dans le cadre du plan de formation.<\/p>\n<p>Le d\u00e9veloppement de la formation est pens\u00e9 \u00e0 travers sa structuration en diff\u00e9rents niveaux d\u2019expertise. L\u2019\u00e9tablissement fait face \u00e0 l\u2019explosion de la demande de formation \u00e0 l\u2019hypnose, dans un contexte de fortes contraintes \u00e9conomiques et professionnelles pour l\u2019acc\u00e8s au x formations longues. Pour r\u00e9pondre \u00e0 ces contraintes, l\u2019offre de formation est structur\u00e9e en trois niveaux. La formation \u00e0 la communication th\u00e9rapeutique, d\u00e9sormais assur\u00e9e en interne sur deux jours devient le premier niveau obligatoire. Les suivants sont les formations longues assur\u00e9es par des organismes externes\u2009: l\u2019hypnose dans les soins (niveau\u00a02) et l\u2019hypnose en \u00e9quipe (niveau\u00a03). Cette canalisation de la demande entra\u00eene un fort d\u00e9veloppement de la formation interne. L\u2019\u00e9quipe de formateurs internes doit donc s\u2019\u00e9toffer et ceux-ci sont recrut\u00e9s parmi les membres actifs d\u2019HypnoCome. Ils b\u00e9n\u00e9ficient alors d\u2019une formation de formateur pour d\u00e9velopper leurs comp\u00e9tences p\u00e9dagogiques.<\/p>\n<ul>\n<li><strong>Effets cognitifs<\/strong> L\u2019\u00e9volution du dispositif de formation interne alimente la d\u00e9marche de gestion des connaissances d\u2019HypnoCome. La strat\u00e9gie p\u00e9dagogique de la formation, les contenus ainsi que les mises en situation sont aliment\u00e9s en continu par les retours d\u2019exp\u00e9rience du r\u00e9seau d\u2019experts-formateurs. Une grande vari\u00e9t\u00e9 de profils professionnels a d\u00e9sormais acc\u00e8s aux bases de ce nouveau mod\u00e8le th\u00e9rapeutique et peut l\u2019adapter \u00e0 sa pratique. Les remont\u00e9es du terrain concernant les difficult\u00e9s de mise en \u0153uvre dans certains contextes ou encore la dur\u00e9e trop courte de la formation am\u00e8nent le r\u00e9seau de formateur \u00e0 faire \u00e9voluer le dispositif.<\/li>\n<li><strong>Effets politiques<\/strong> Le d\u00e9veloppement de la formation interne permet de constituer un r\u00e9seau d\u2019experts-formateurs, membres actifs d\u2019HypnoCome, ainsi qu\u2019un r\u00e9seau d\u2019alli\u00e9s \u00e0 travers le CHU, parmi les professionnels de sant\u00e9 et cadres int\u00e9ress\u00e9s. Il donne \u00e0 la communaut\u00e9 une juridiction sur des ressources de formation m\u00e9dicale et param\u00e9dicale, via l\u2019inscription au plan de formation du dispositif cr\u00e9\u00e9. Enfin, il initie une r\u00e9flexion et stimule des prises de d\u00e9cisions sur la politique de soins et les conditions de pratique des diff\u00e9rentes techniques de l\u2019hypnose.<\/li>\n<\/ul>\n<h4><i>2 &#8211; L\u00e9gitimer professionnellement la pratique de l\u2019hypnose<\/i><\/h4>\n<p>Au sein du CHU, tout comme plus g\u00e9n\u00e9ralement au sein des professions de sant\u00e9, un int\u00e9r\u00eat croissant se d\u00e9veloppe pour certaines pratiques dites \u00ab\u2009compl\u00e9mentaires\u2009\u00bb (m\u00e9ditation de pleine conscience, acupuncture\u2026). Les membres d\u2019HypnoCome se positionnent sur le calendrier d\u2019enseignement et de recherche existants.<\/p>\n<p>La pratique de l\u2019hypnose est int\u00e9gr\u00e9e \u00e0 diff\u00e9rents projets de recherche, dont plusieurs sont pilot\u00e9s par l\u2019un des trois professeurs du p\u00f4le Anesth\u00e9sie-r\u00e9animation. Ils portent sur la limitation des complications post-op\u00e9ratoires et sur la r\u00e9duction de la dur\u00e9e de r\u00e9habilitation apr\u00e8s chirurgie. Les membres d\u2019HypnoCome proposent d\u2019int\u00e9grer une technique d\u2019hypnose (l\u2019autohypnose) au protocole de ces recherches. Des retours d\u2019exp\u00e9rience sur le dispositif mis en place au bloc gyn\u00e9cologique sont \u00e9galement pr\u00e9sent\u00e9s \u00e0 l\u2019occasion de congr\u00e8s nationaux d\u2019anesth\u00e9sie.<\/p>\n<p>Des s\u00e9quences p\u00e9dagogiques sont int\u00e9gr\u00e9es \u00e0 la formation initiale des m\u00e9decins et infirmiers anesth\u00e9sistes. Des membres d\u2019HypnoCome assurent des enseignements \u00e0 la communication th\u00e9rapeutique dans l\u2019\u00e9cole de m\u00e9decine et d\u2019Iade. Ils encadrent aussi des m\u00e9moires d\u2019\u00e9tudiants sur le sujet. Une restitution de ces travaux est organis\u00e9e lors des r\u00e9unions d\u2019HypnoCome.<\/p>\n<p>Une communication cibl\u00e9e est mise en \u0153uvre aupr\u00e8s d\u2019un large panel de professionnels en interne. Les membres d\u2019HypnoCome \u00e9laborent des posters, qu\u2019ils pr\u00e9sentent lors de journ\u00e9es th\u00e9matiques au sein du CHU (ainsi le forum qualit\u00e9 \u2013 en lien avec la direction de la qualit\u00e9 \u2013 ou la journ\u00e9e de la qualit\u00e9 de soins \u2013 en lien avec la direction des soins).<\/p>\n<ul>\n<li><strong>Effets cognitifs<\/strong> Les membres d\u2019HypnoCome participent au d\u00e9veloppement des connaissances scientifiques relatives aux indications et aux effets de diff\u00e9rentes formes d\u2019hypnose. Ils contribuent \u00e9galement \u00e0 une d\u00e9marche r\u00e9flexive au sein de la profession sur les conditions d\u2019implantation de la pratique. Enfin, les travaux des \u00e9tudiants amplifient la cr\u00e9ation et le partage de connaissances.<\/li>\n<li><strong>Effets politiques<\/strong> HypnoCome participe \u00e0 la l\u00e9gitimation scientifique de l\u2019hypnose vis-\u00e0-vis de la profession m\u00e9dicale en participant \u00e0 des projets de recherche reconnus. La r\u00e9putation des praticiens se d\u00e9veloppe, \u00e0 la fois dans le domaine de la recherche et de l\u2019enseignement. L\u2019enseignement et la communication en interne favorisent le recrutement de futurs \u00ab\u2009alli\u00e9s\u2009\u00bb parmi les professionnels int\u00e9ress\u00e9s, contribuant \u00e0 la diffusion de la pratique.<\/li>\n<\/ul>\n<h4><i>3 &#8211; Dessiner un mod\u00e8le \u00e9conomique dans lequel la pratique clinique devient possible<\/i><\/h4>\n<p>L\u2019implantation de pratiques compl\u00e9mentaires est le fruit d\u2019un partenariat entre des \u00e9quipes pluridisciplinaires et des patients souhaitant (ou n\u00e9cessitant de) recourir \u00e0 des pratiques plus proches de leurs besoins. Comment r\u00e9pondre \u00e0 ces besoins dans un contexte o\u00f9 la demande n\u2019est pas encore bien connue, o\u00f9 l\u2019offre n\u00e9cessite une forte implication des \u00e9quipes et o\u00f9 il n\u2019existe pas de mod\u00e8le \u00e9conomique permettant de les financer\u2009?<\/p>\n<p>Un \u00ab\u2009parcours hypnose\u2009\u00bb est propos\u00e9 aux patientes du centre de canc\u00e9rologie, fond\u00e9 sur un partenariat \u00e9troit entre l\u2019\u00e9quipe chirurgicale et l\u2019\u00e9quipe d\u2019anesth\u00e9sie du bloc gyn\u00e9cologique. Les interactions d\u2019HypnoCome avec le bureau de p\u00f4le permettent de cr\u00e9er une consultation pr\u00e9interventionnelle syst\u00e9matique en hypnose, favorisant une meilleure pr\u00e9paration des patientes et de l\u2019\u00e9quipe. Cette consultation est soutenue par la directrice d\u00e9l\u00e9gu\u00e9e de p\u00f4le.<\/p>\n<p>Une communication est d\u00e9velopp\u00e9e aupr\u00e8s des patients par l\u2019interm\u00e9diaire du service communication interne de l\u2019h\u00f4pital (revue interne, site Internet, conf\u00e9rences\u2026) et un relais dans les m\u00e9dias r\u00e9gionaux et nationaux est assur\u00e9 (radio et t\u00e9l\u00e9vision).<\/p>\n<p>Les initiatives sont soutenues dans diff\u00e9rentes fili\u00e8res (cardiologie, orthop\u00e9die, Samu\u2026) par les membres d\u2019HypnoCome \u00e0 travers un partage d\u2019exp\u00e9riences et de ressources. Il s\u2019agit d\u2019initiatives port\u00e9es principalement par des infirmi\u00e8res et\/ou des m\u00e9decins.<\/p>\n<ul>\n<li><strong>Effets cognitifs<\/strong> HypnoCome d\u00e9veloppe des connaissances relatives aux opportunit\u00e9s de pratique de l\u2019hypnose dans les diff\u00e9rents services de l\u2019h\u00f4pital. Il contribue \u00e0 l\u2019identification des facteurs de succ\u00e8s et des freins \u00e0 son int\u00e9gration dans les routines de prise en charge d\u2019un service (importance du tandem Iade\/anesth\u00e9siste\u2009; coordination \u00e9quipes chirurgicale\/anesth\u00e9siste\u2026).<\/li>\n<li><strong>Effets politiques<\/strong> Les d\u00e9marches d\u2019HypnoCome contribuent \u00e0 d\u00e9velopper la l\u00e9gitimit\u00e9 et la r\u00e9putation des experts dans le domaine clinique et une forme de \u00ab\u2009prestige\u2009\u00bb associ\u00e9e \u00e0 cette nouvelle pratique. L\u2019augmentation de la demande des patients et des besoins de formation des professionnels contribue \u00e0 attirer l\u2019attention des d\u00e9cideurs. Une r\u00e9flexion concernant l\u2019alignement de cette offre avec la strat\u00e9gie de l\u2019\u00e9tablissement \u00e0 moyen terme est engag\u00e9e. Elle marque une rupture avec une approche \u00e0 plus court terme qui, jusqu\u2019alors, avait emp\u00each\u00e9 la cr\u00e9ation d\u2019une consultation d\u00e9di\u00e9e.<\/li>\n<\/ul>\n<h1>Porter des innovations dans les interstices des logiques existantes<\/h1>\n<p>HypnoCome nous a permis de rencontrer des professionnels qui investissent leur temps personnel, sur leur lieu de travail, autour du d\u00e9veloppement d\u2019une autre forme de relation th\u00e9rapeutique avec les patients. HypnoCome est une communaut\u00e9 de type \u00e0 la fois professionnel et d\u2019expertise\/cr\u00e9ation. Tout en structurant des \u00e9changes de connaissances autour de l\u2019\u00ab\u2009hypnose m\u00e9dicale\u2009\u00bb, elle explore\u2009:<\/p>\n<ul>\n<li>les diff\u00e9rentes situations dans lesquelles cette pratique apporterait une r\u00e9ponse utile aux besoins des patients\u2009;<\/li>\n<li>les d\u00e9clinaisons possibles de cette pratique permettant d\u2019\u00e9largir le r\u00e9pertoire de besoins auxquels elle est susceptible de r\u00e9pondre, ainsi que les possibilit\u00e9s d\u2019action des professionnels.<\/li>\n<\/ul>\n<h2>Un espace s\u00e9curis\u00e9<\/h2>\n<p>HypnoCome permet \u00e0 ses membres de d\u00e9velopper leurs connaissances sur une pratique qui, bien que conforme aux r\u00e8gles professionnelles, se situe \u00e0 la marge des pratiques habituelles. Il leur permet de se d\u00e9gager des contraintes du terrain et du regard parfois m\u00e9fiant des coll\u00e8gues pour partager des r\u00e9flexions avec les membres de la communaut\u00e9. Cette derni\u00e8re offre ainsi un soutien important aux professionnels, qui exp\u00e9rimentent de fa\u00e7on isol\u00e9e dans leur service.<\/p>\n<p>Dans un contexte de tensions fortes sur le travail des soignants et de quasi-disparition des espaces r\u00e9flexifs sur le travail, l\u2019existence d\u2019une telle communaut\u00e9 r\u00e9pond \u00e0 des besoins profonds des professionnels. Elle rel\u00e8ve de la n\u00e9cessit\u00e9 pour eux de retrouver un sentiment de contr\u00f4le sur diff\u00e9rents aspects de leur environnement\u2009:<\/p>\n<ul>\n<li><strong>le contr\u00f4le du sens\u2009:<\/strong> le besoin de redonner du sens \u00e0 leur pratique professionnelle, face au sentiment de standardisation des prises en charge et le risque de d\u00e9personnalisation\u2009;<\/li>\n<li><strong>le contr\u00f4le du lien social\u2009:<\/strong> le besoin de reconstruire un lieu de convivialit\u00e9, d\u2019\u00e9change et de r\u00e9flexion autour des pratiques, face au sentiment de rar\u00e9faction des opportunit\u00e9s de socialisation professionnelle\u2009;<\/li>\n<li><strong>le contr\u00f4le de l\u2019action\u2009:<\/strong> le besoin de red\u00e9velopper une capacit\u00e9 d\u2019action individuelle et collective dans l\u2019\u00e9volution des prises en charge et plus g\u00e9n\u00e9ralement dans l\u2019\u00e9volution de la profession\u2009;<\/li>\n<li><strong>le contr\u00f4le du temps\u2009:<\/strong> le besoin de se r\u00e9approprier une temporalit\u00e9 propre dans l\u2019\u00e9volution de leurs pratiques, face au sentiment que le calendrier organisationnel est souvent fix\u00e9 par des contraintes externes.<\/li>\n<\/ul>\n<p>Au-del\u00e0 du caract\u00e8re \u00ab\u2009s\u00e9curis\u00e9\u2009\u00bb de cet espace, nous avons \u00e9galement identifi\u00e9 la capacit\u00e9 de transformation de ce collectif.<\/p>\n<h2>Un espace \u00ab\u2009libre\u2009\u00bb<\/h2>\n<p>Introduire et diffuser des pratiques nouvelles, non issues de la m\u00e9decine conventionnelle et construire avec les patients une offre nouvelle constitue un v\u00e9ritable d\u00e9fi. Nous l\u2019avons \u00e9voqu\u00e9, des logiques fortes et plus ou moins anciennes fa\u00e7onnent le contexte dans lequel \u00e9voluent les professionnels de sant\u00e9. Toute innovation est n\u00e9cessairement subordonn\u00e9e \u00e0 ces logiques existantes, au moins partiellement.<\/p>\n<p>Les professionnels d\u2019HypnoCome ont construit ce que Heinze <i>et al.<\/i> nomment un \u00ab\u2009espace libre\u2009\u00bb<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(16)<\/sup>. Cette libert\u00e9 rel\u00e8ve d\u2019un \u00e9quilibre subtil dont nous proposons quelques caract\u00e9ristiques\u2009:<\/p>\n<ul>\n<li>\u00eatre ind\u00e9pendant des d\u00e9marches organisationnelles existantes, afin de pr\u00e9server une certaine autonomie et de ne pas \u00ab\u2009subir\u2009\u00bb l\u2019agenda de l\u2019organisation. Tout en sachant s\u2019articuler ponctuellement avec ces d\u00e9marches organisationnelles, afin de mutualiser des ressources. Le r\u00f4le d\u2019\u00ab\u2009intrapreneur\u2009\u00bb des parrains et marraines est ici essentiel pour faciliter cette articulation\u2009;<\/li>\n<li>\u00eatre pr\u00e9serv\u00e9 plus g\u00e9n\u00e9ralement des logiques institutionnelles existantes, afin de discuter et d\u2019exp\u00e9rimenter des pratiques relevant de logiques alternatives. Tout en sachant r\u00e9fl\u00e9chir aux modes de l\u00e9gitimation de ces pratiques du point de vue des logiques existantes.<\/li>\n<\/ul>\n<h1>Peut-on soutenir la cr\u00e9ation de communaut\u00e9s de pratique\u2009?<\/h1>\n<p>Les caract\u00e9ristiques des communaut\u00e9s de pratique semblent les faire r\u00e9sister \u00e0 toute volont\u00e9 d\u2019action manag\u00e9riale d\u00e9lib\u00e9r\u00e9e. Il ne s\u2019agit ni d\u2019un groupe projet, ni d\u2019un groupe d\u2019analyse des pratiques professionnelles, ni d\u2019un groupe de formation. La litt\u00e9rature sur les communaut\u00e9s de pratique s\u2019est donc interrog\u00e9e sur les conditions de leur \u00ab\u2009pilotage\u2009\u00bb. Mais plut\u00f4t que de nous int\u00e9resser aux communaut\u00e9s \u00ab\u2009pilot\u00e9es\u2009\u00bb, nous proposons d\u2019identifier les conditions du soutien des communaut\u00e9s \u00e9mergentes. Et pour cela nous faisons l\u2019hypoth\u00e8se que le principe du <i>primum non nocere<\/i> devrait pr\u00e9valoir.<\/p>\n<h2>D\u2019abord ne pas nuire<\/h2>\n<p>Le r\u00e9seau de soutien qui s\u2019est constitu\u00e9 autour d\u2019HypnoCome (encadrement de p\u00f4le, formation continue, Clud, CME\u2026) semble en effet avoir agi selon trois principes\u2009:<\/p>\n<ul>\n<li><strong>reconna\u00eetre la valeur du travail effectu\u00e9 par ses membres<\/strong>. L\u2019investissement spontan\u00e9 des membres, en dehors du temps de travail, rend leur contribution invisible pour l\u2019organisation. L\u2019autonomie du collectif complique \u00e9galement ses relations avec les services supports. Certains cadres ont su cependant reconna\u00eetre la valeur de l\u2019investissement des membres et ont accord\u00e9 de l\u2019int\u00e9r\u00eat, du temps et de l\u2019\u00e9nergie \u00e0 HypnoCome dans un v\u00e9ritable souci de \u00ab\u2009contre-don\u2009\u00bb\u2009;<\/li>\n<li><strong>cr\u00e9er les conditions dans lesquelles l\u2019action devient possible.<\/strong> HypnoCome a \u00e9t\u00e9 souvent confront\u00e9 \u00e0 la difficult\u00e9 d\u2019obtenir des ressources pour ses actions. Il a fallu toute l\u2019inventivit\u00e9 de certains soutiens pour rendre possible ce qui ne semblait pas l\u2019\u00eatre au premier abord\u2009;<\/li>\n<li><strong>pr\u00e9server l\u2019autonomie du collectif.<\/strong> C\u2019est-\u00e0-dire en ne conditionnant pas l\u2019attribution de ressources \u00e0 la subordination totale \u00e0 des dispositifs existants (promotion de la bientraitance, lutte contre la douleur\u2026). N\u00e9anmoins, des remont\u00e9es d\u2019information r\u00e9guli\u00e8res ont souvent \u00e9t\u00e9 convenues avec le r\u00e9seau de soutien.<\/li>\n<\/ul>\n<h2>Vers une forme d\u2019\u00ab\u2009agilit\u00e9\u2009\u00bb dans l\u2019accompagnement des communaut\u00e9s \u00e9mergentes<\/h2>\n<p>Favoriser indirectement l\u2019innovation, en agissant sur les conditions contextuelles et organisationnelles semble \u00eatre un art d\u00e9licat. Au-del\u00e0 des m\u00e9thodes et outils, c\u2019est plus d\u2019une forme de \u00ab\u2009capacit\u00e9 organisationnelle\u2009\u00bb dont il serait question.<\/p>\n<p>Nous proposons ici quatre caract\u00e9ristiques d\u2019une telle capacit\u00e9\u2009:<\/p>\n<ul>\n<li><strong>rep\u00e9rer et analyser les micro-transformations engag\u00e9es par des collectifs<\/strong>, qu\u2019il s\u2019agisse d\u2019\u00e9quipes ou de groupes plus informels. Une communaut\u00e9 de pratique n\u2019est en effet pas toujours visible\u2009;<\/li>\n<li><strong>mettre \u00e0 disposition des circuits courts pour les ressources de \u00ab\u2009premi\u00e8re n\u00e9cessit\u00e9\u2009\u00bb<\/strong> de la communaut\u00e9\u2009: mat\u00e9riel, outils de communication, espace physique\u2026 Les services supports ont en effet rarement le temps d\u2019interagir avec des communaut\u00e9s informelles\u2009;<\/li>\n<li><strong>mettre \u00e0 disposition de la communaut\u00e9 des comp\u00e9tences, internes ou externes<\/strong>, lui permettant de structurer et de capitaliser les connaissances produites<sup class=\"appel\" data-toggle=\"modal\" data-target=\"#notes\">(17)<\/sup>;<\/li>\n<li><strong>faciliter la cr\u00e9ation d\u2019un r\u00e9seau de soutien <i>ad hoc<\/i><\/strong> en identifiant les \u00ab\u2009parrains et marraines\u2009\u00bb susceptibles d\u2019assurer l\u2019articulation avec les dispositifs organisationnels existants.<\/li>\n<\/ul>\n<p>La collaboration entre gestionnaires et chercheurs en sciences de gestion nous semble \u00eatre une piste f\u00e9conde pour contribuer au d\u00e9veloppement d\u2019une telle capacit\u00e9.<\/p>\n<h1>Conclusion<\/h1>\n<p>Notre syst\u00e8me de sant\u00e9 conna\u00eetra probablement ces prochaines ann\u00e9es, avec l\u2019av\u00e8nement notamment de l\u2019\u00ab\u2009exp\u00e9rience patient\u2009\u00bb, des transformations profondes et bienvenues. Autour des professionnels de sant\u00e9, un grand nombre d\u2019acteurs participent d\u00e9j\u00e0 au d\u00e9veloppement de perspectives nouvelles\u2009: patients et associations de patients, experts de l\u2019industrie et des services, entreprises technologiques\u2026<\/p>\n<p>Cependant, comment \u00e9viter les appels maladroits au \u00ab\u2009changement culturel\u2009\u00bb ciblant les professionnels de sant\u00e9\u2009? Comment \u00e9viter le \u00ab\u2009th\u00e9\u00e2tre de l\u2019innovation\u2009\u00bb qui se concentrerait sur les manifestations superficielles des processus d\u2019innovation\u2009? Comment enfin \u00e9viter de cr\u00e9er des tensions nouvelles en introduisant des dispositifs ne prenant pas en compte les fortes contraintes s\u2019exer\u00e7ant sur l\u2019activit\u00e9 des professionnels de sant\u00e9\u2009?<\/p>\n<p>Ce que le collectif HypnoCome nous a rappel\u00e9, c\u2019est qu\u2019un processus d\u2019innovation peut \u00e9merger naturellement, au c\u0153ur de la pratique de la m\u00e9decine et des soins. Il est fond\u00e9 sur des interactions soutenues entre des professionnels passionn\u00e9s, au sein de collectifs spontan\u00e9s\u2009: les communaut\u00e9s de pratique. De telles communaut\u00e9s peuvent jouer un r\u00f4le important dans l\u2019exploration et l\u2019exp\u00e9rimentation. Nous pouvons r\u00e9fl\u00e9chir \u00e0 la meilleure fa\u00e7on de \u00ab\u2009piloter\u2009\u00bb de telles communaut\u00e9s, c\u2019est-\u00e0-dire de les faire \u00e9merger, gagner en maturit\u00e9 et produire des connaissances transf\u00e9rables. Mais c\u2019est peut-\u00eatre avant tout notre capacit\u00e9 \u00e0 comprendre et \u00e0 accompagner les communaut\u00e9s existantes qui est d\u00e9terminante. Et si innover, \u00e7a ne consistait pas uniquement \u00e0 introduire de la nouveaut\u00e9, mais \u00e0 savoir aussi porter un regard nouveau sur ce qui est d\u00e9j\u00e0 pr\u00e9sent\u2009?<\/p>\n<hr \/>\n<p><strong>Autres\u00a0r\u00e9f\u00e9rences<\/strong><\/p>\n<p>\u2022 F. Gosselin, P.-J. Barlatier, P. Cohendet, P. Dunlavey, O.\u00a0Dupou\u00ebt, F. Lampron, \u00ab\u2009Le partage des r\u00f4les et des responsabilit\u00e9s \u00e0 l\u2019\u00e9gard du pilotage des communaut\u00e9s de pratique\u2009\u00bb, <i>Gestion<\/i>, 2010, vol.35, n\u00b04, p.\u200936 46.<\/p>\n<p>\u2022 M. Gu\u00e9rineau, S. Ben Mahmoud-Jouini, F. Charue-Duboc, \u00ab\u2009Le r\u00f4le des communaut\u00e9s de pratiques et de leur coordination dans le d\u00e9veloppement et le d\u00e9ploiement des innovations dans une multinationale\u2009\u00bb, <i>Management international<\/i>, 2018, vol.21, n\u00b03, p.\u200918 34.<\/p>\n<p>\u2022 R. J\u00f8rgensen, E. Scarso, K\u00a0Edwards, C. Ipsen, \u201cCommunities of practice in healthcare: A framework for managing knowledge sharing in operations\u201d, <i>Knowledge and Process Management<\/i>, 2019, 26(2), 152-162.<\/p>\n<p>\u2022 R. J\u00f8rgensen, E. Scarso, K. Kirchner,<span class=\"Apple-converted-space\">\u00a0 <\/span>K. Edwards, \u201cExploring the maturity and development of global communities of practice\u201d, <i>Knowledge and Process Management<\/i>, 2019, 26(4), 321-331.<\/p>\n<p>\u2022 J. Marty, Lettre du pr\u00e9sident de la Sfar au pr\u00e9sident du conseil de l\u2019Ordre des m\u00e9decins, 2005.<\/p>\n<script>function PlayerjsAsync(){} if(window[\"Playerjs\"]){PlayerjsAsync();}<\/script>","protected":false},"excerpt":{"rendered":"<p>Des innovations \u00e9mergentes fond\u00e9es sur les interactions entre individus Avant toute chose, il faut distinguer deux grandes perspectives fondamentalement diff\u00e9rentes concernant l\u2019accompagnement de l\u2019innovation(1)\u2009:\u00a0 la premi\u00e8re, rationnelle et instrumentale, est celle du \u00ab\u2009pilotage de l\u2019innovation\u2009\u00bb. Elle se concentre sur les r\u00f4les, les processus, les outils et les m\u00e9thodes et fait l\u2019hypoth\u00e8se que l\u2019innovation peut \u00eatre g\u00e9r\u00e9e et contr\u00f4l\u00e9e. Elle n\u00e9cessite une v\u00e9ritable expertise, qu\u2019il faut parfois aller chercher en dehors&hellip; <\/p>\n","protected":false},"author":23133,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[2,72],"tags":[9672,9670,9673,629,9671,384],"class_list":["post-46643","post","type-post","status-publish","format-standard","hentry","category-gestions-hospitalieres","category-reflexion","tag-chu-grenoble-aples","tag-communaute-de-pratique","tag-hypnose","tag-innovation","tag-medecine-integrative","tag-mutualisation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les communaut\u00e9s de pratique - Gestions hospitali\u00e8res<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ricom-web8.com\/gestions\/les-communautes-de-pratique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les communaut\u00e9s de pratique - Gestions hospitali\u00e8res\" \/>\n<meta property=\"og:description\" content=\"Des innovations \u00e9mergentes fond\u00e9es sur les interactions entre individus Avant toute chose, il faut distinguer deux grandes perspectives fondamentalement diff\u00e9rentes concernant l\u2019accompagnement de l\u2019innovation(1)\u2009:\u00a0 la premi\u00e8re, rationnelle et instrumentale, est celle du \u00ab\u2009pilotage de l\u2019innovation\u2009\u00bb. Elle se concentre sur les r\u00f4les, les processus, les outils et les m\u00e9thodes et fait l\u2019hypoth\u00e8se que l\u2019innovation peut \u00eatre g\u00e9r\u00e9e et contr\u00f4l\u00e9e. Elle n\u00e9cessite une v\u00e9ritable expertise, qu\u2019il faut parfois aller chercher en dehors&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ricom-web8.com\/gestions\/les-communautes-de-pratique\/\" \/>\n<meta property=\"og:site_name\" content=\"Gestions hospitali\u00e8res\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gestionshospitalieres\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-01T12:07:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-08T08:56:37+00:00\" \/>\n<meta name=\"author\" content=\"Gestions hospitali\u00e8res\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revue_GH\" \/>\n<meta name=\"twitter:site\" content=\"@revue_GH\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestions hospitali\u00e8res\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"28 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/les-communautes-de-pratique\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/les-communautes-de-pratique\/\"},\"author\":{\"name\":\"Gestions hospitali\u00e8res\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f\"},\"headline\":\"Les communaut\u00e9s de pratique\",\"datePublished\":\"2023-05-01T12:07:44+00:00\",\"dateModified\":\"2023-06-08T08:56:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/les-communautes-de-pratique\/\"},\"wordCount\":6229,\"publisher\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#organization\"},\"keywords\":[\"CHU Grenoble-Aples\",\"communaut\u00e9 de pratique\",\"hypnose\",\"innovation\",\"m\u00e9decine int\u00e9grative\",\"mutualisation\"],\"articleSection\":[\"Gestions Hospitali\u00e8res\",\"r\u00e9flexion\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/les-communautes-de-pratique\/\",\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/les-communautes-de-pratique\/\",\"name\":\"Les communaut\u00e9s de pratique - Gestions hospitali\u00e8res\",\"isPartOf\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#website\"},\"datePublished\":\"2023-05-01T12:07:44+00:00\",\"dateModified\":\"2023-06-08T08:56:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/les-communautes-de-pratique\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ricom-web8.com\/gestions\/les-communautes-de-pratique\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/les-communautes-de-pratique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ricom-web8.com\/gestions\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les communaut\u00e9s de pratique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#website\",\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/\",\"name\":\"Gestions hospitali\u00e8res\",\"description\":\"la revue des d\u00e9cideurs hospitaliers\",\"publisher\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ricom-web8.com\/gestions\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#organization\",\"name\":\"Gestions hospitali\u00e8res\",\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png\",\"contentUrl\":\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png\",\"width\":512,\"height\":512,\"caption\":\"Gestions hospitali\u00e8res\"},\"image\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/gestionshospitalieres\/\",\"https:\/\/x.com\/revue_GH\",\"https:\/\/www.linkedin.com\/company\/gestions-hospitalieres?trk=top_nav_home\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f\",\"name\":\"Gestions hospitali\u00e8res\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g\",\"caption\":\"Gestions hospitali\u00e8res\"},\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/author\/benjamin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les communaut\u00e9s de pratique - Gestions hospitali\u00e8res","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ricom-web8.com\/gestions\/les-communautes-de-pratique\/","og_locale":"fr_FR","og_type":"article","og_title":"Les communaut\u00e9s de pratique - Gestions hospitali\u00e8res","og_description":"Des innovations \u00e9mergentes fond\u00e9es sur les interactions entre individus Avant toute chose, il faut distinguer deux grandes perspectives fondamentalement diff\u00e9rentes concernant l\u2019accompagnement de l\u2019innovation(1)\u2009:\u00a0 la premi\u00e8re, rationnelle et instrumentale, est celle du \u00ab\u2009pilotage de l\u2019innovation\u2009\u00bb. Elle se concentre sur les r\u00f4les, les processus, les outils et les m\u00e9thodes et fait l\u2019hypoth\u00e8se que l\u2019innovation peut \u00eatre g\u00e9r\u00e9e et contr\u00f4l\u00e9e. Elle n\u00e9cessite une v\u00e9ritable expertise, qu\u2019il faut parfois aller chercher en dehors&hellip;","og_url":"https:\/\/www.ricom-web8.com\/gestions\/les-communautes-de-pratique\/","og_site_name":"Gestions hospitali\u00e8res","article_publisher":"https:\/\/www.facebook.com\/gestionshospitalieres\/","article_published_time":"2023-05-01T12:07:44+00:00","article_modified_time":"2023-06-08T08:56:37+00:00","author":"Gestions hospitali\u00e8res","twitter_card":"summary_large_image","twitter_creator":"@revue_GH","twitter_site":"@revue_GH","twitter_misc":{"\u00c9crit par":"Gestions hospitali\u00e8res","Dur\u00e9e de lecture estim\u00e9e":"28 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ricom-web8.com\/gestions\/les-communautes-de-pratique\/#article","isPartOf":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/les-communautes-de-pratique\/"},"author":{"name":"Gestions hospitali\u00e8res","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f"},"headline":"Les communaut\u00e9s de pratique","datePublished":"2023-05-01T12:07:44+00:00","dateModified":"2023-06-08T08:56:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/les-communautes-de-pratique\/"},"wordCount":6229,"publisher":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#organization"},"keywords":["CHU Grenoble-Aples","communaut\u00e9 de pratique","hypnose","innovation","m\u00e9decine int\u00e9grative","mutualisation"],"articleSection":["Gestions Hospitali\u00e8res","r\u00e9flexion"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ricom-web8.com\/gestions\/les-communautes-de-pratique\/","url":"https:\/\/www.ricom-web8.com\/gestions\/les-communautes-de-pratique\/","name":"Les communaut\u00e9s de pratique - Gestions hospitali\u00e8res","isPartOf":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#website"},"datePublished":"2023-05-01T12:07:44+00:00","dateModified":"2023-06-08T08:56:37+00:00","breadcrumb":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/les-communautes-de-pratique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ricom-web8.com\/gestions\/les-communautes-de-pratique\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ricom-web8.com\/gestions\/les-communautes-de-pratique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ricom-web8.com\/gestions\/"},{"@type":"ListItem","position":2,"name":"Les communaut\u00e9s de pratique"}]},{"@type":"WebSite","@id":"https:\/\/www.ricom-web8.com\/gestions\/#website","url":"https:\/\/www.ricom-web8.com\/gestions\/","name":"Gestions hospitali\u00e8res","description":"la revue des d\u00e9cideurs hospitaliers","publisher":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ricom-web8.com\/gestions\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ricom-web8.com\/gestions\/#organization","name":"Gestions hospitali\u00e8res","url":"https:\/\/www.ricom-web8.com\/gestions\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/","url":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png","contentUrl":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png","width":512,"height":512,"caption":"Gestions hospitali\u00e8res"},"image":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gestionshospitalieres\/","https:\/\/x.com\/revue_GH","https:\/\/www.linkedin.com\/company\/gestions-hospitalieres?trk=top_nav_home"]},{"@type":"Person","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f","name":"Gestions hospitali\u00e8res","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g","caption":"Gestions hospitali\u00e8res"},"url":"https:\/\/www.ricom-web8.com\/gestions\/author\/benjamin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/posts\/46643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/users\/23133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/comments?post=46643"}],"version-history":[{"count":0,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/posts\/46643\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/media?parent=46643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/categories?post=46643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/tags?post=46643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}