

{"id":47690,"date":"2024-01-01T16:30:53","date_gmt":"2024-01-01T15:30:53","guid":{"rendered":"https:\/\/gestions-hospitalieres.fr\/?p=47690"},"modified":"2024-02-05T12:01:11","modified_gmt":"2024-02-05T11:01:11","slug":"quand-lecologie-sinvite-a-lhopital","status":"publish","type":"post","link":"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/","title":{"rendered":"Quand l\u2019\u00e9cologie s\u2019invite \u00e0 l\u2019h\u00f4pital"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture\u00a0: <\/span> <span class=\"rt-time\"> 6<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><p>Dans un contexte marqu\u00e9 par des records de temp\u00e9rature et des anomalies climatiques de plus en plus fr\u00e9quentes, le lien entre le changement climatique, les soins et notre syst\u00e8me de sant\u00e9 devient une pr\u00e9occupation cruciale. Avec ce premier colloque qui a r\u00e9uni plus de 200 participants sur le th\u00e8me\u2009: \u00ab\u2009La sant\u00e9 et les soins durables \u00e0 l\u2019\u00e8re du changement climatique\u2009\u00bb, le CHU de Bordeaux revenait sur ce lien.<\/p>\n<p>Un comit\u00e9 d\u2019organisation constitu\u00e9 de diff\u00e9rents professionnels impliqu\u00e9s dans la d\u00e9marche de transformation \u00e9cologique s\u2019est r\u00e9uni r\u00e9guli\u00e8rement pour \u00e9laborer la th\u00e9matique et le programme, s\u00e9lectionner les intervenants et pr\u00e9voir les \u00e9l\u00e9ments logistiques.<\/p>\n<p>L\u2019envie \u00e9tait de partager des id\u00e9es et des actions concr\u00e8tes afin d\u2019acc\u00e9l\u00e9rer la transformation \u00e9cologique du syst\u00e8me de sant\u00e9 face \u00e0 l\u2019urgence climatique. \u00c9tat des lieux, t\u00e9moignages, tables rondes, animations, d\u00e9bats, initiatives\u2026, l\u2019\u00e9v\u00e8nement a r\u00e9uni plus de 200 participants et dix-huit intervenants, professionnels du secteur sanitaire et social.<\/p>\n<p style=\"font-weight: 400;\"><button data-toggle=\"collapse\" data-target=\"#enc_2024_50_01\">Programme<\/button><div id=\"enc_2024_50_01\" class=\"encadre collapse\"><h2>Programme<\/h2>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-47692\" src=\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/02\/Capture-decran-2024-02-02-a-16.38.25.jpg\" alt=\"\" width=\"705\" height=\"1000\" srcset=\"https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2024\/02\/Capture-decran-2024-02-02-a-16.38.25.jpg 705w, https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2024\/02\/Capture-decran-2024-02-02-a-16.38.25-212x300.jpg 212w\" sizes=\"(max-width: 705px) 100vw, 705px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-47693\" src=\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/02\/Capture-decran-2024-02-02-a-16.38.38.jpg\" alt=\"\" width=\"1416\" height=\"1000\" srcset=\"https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2024\/02\/Capture-decran-2024-02-02-a-16.38.38.jpg 1416w, https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2024\/02\/Capture-decran-2024-02-02-a-16.38.38-300x212.jpg 300w, https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2024\/02\/Capture-decran-2024-02-02-a-16.38.38-1024x723.jpg 1024w, https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2024\/02\/Capture-decran-2024-02-02-a-16.38.38-768x542.jpg 768w\" sizes=\"(max-width: 1416px) 100vw, 1416px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-47694\" src=\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/02\/Capture-decran-2024-02-02-a-16.38.49.jpg\" alt=\"\" width=\"702\" height=\"1000\" srcset=\"https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2024\/02\/Capture-decran-2024-02-02-a-16.38.49.jpg 702w, https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2024\/02\/Capture-decran-2024-02-02-a-16.38.49-211x300.jpg 211w\" sizes=\"(max-width: 702px) 100vw, 702px\" \/><\/p>\n<\/div><\/p>\n<h1>Objectifs et enjeux<\/h1>\n<p>Le CHU de Bordeaux, d\u00e9j\u00e0 impliqu\u00e9 sur le sujet, a souhait\u00e9 lancer un rendez-vous annuel de la transformation \u00e9cologique dans les soins et la sant\u00e9. Les objectifs \u00e9taient triples. Premi\u00e8rement, mettre en avant l\u2019expertise scientifique pr\u00e9sente au CHU de Bordeaux et ailleurs sur le sujet. Si de nombreuses actions, initiatives et \u00e9v\u00e8nements ponctuels en faveur de la transition \u00e9cologique se d\u00e9veloppent, l\u2019\u00e9tablissement souhaite les regrouper et les mettre en avant. Dans un second temps, ce colloque avait pour but d\u2019inspirer et de s\u2019inspirer en b\u00e9n\u00e9ficiant de l\u2019expertise d\u2019intervenants de renomm\u00e9e nationale, en valorisant, d\u00e9veloppant et dupliquant des actions locales de d\u00e9carbonation et d\u2019\u00e9coconception des soins. Enfin, le troisi\u00e8me enjeu \u00e9tait de susciter et structurer une communaut\u00e9 sur les enjeux \u00e9cologiques en sant\u00e9. Cet \u00e9v\u00e8nement est l\u2019occasion de d\u00e9cloisonner, de promouvoir la rencontre des acteurs et de constituer des r\u00e9seaux pour favoriser la collaboration collective entre\u2009: les scientifiques en donnant un espace suppl\u00e9mentaire f\u00e9d\u00e9ratif pour la communaut\u00e9 actuelle\u2009; les experts scientifiques et le terrain pour que les experts informent et forment les acteurs du terrain et que ces derniers puissent partager leurs id\u00e9es et initiatives concr\u00e8tes, mises en place dans leur quotidien.<\/p>\n<h1>La sant\u00e9 et les soins en pleine crise climatique<\/h1>\n<p>Le changement climatique peut \u00eatre consid\u00e9r\u00e9 comme une opportunit\u00e9 permettant de repenser et de r\u00e9soudre des probl\u00e8mes de sant\u00e9 publique, selon la conf\u00e9rence introductive du Dr\u00a0R\u00e9my Slama. Des probl\u00e8mes de sant\u00e9 publique qui n\u2019ont pas \u00e9t\u00e9 efficacement abord\u00e9s ces derni\u00e8res d\u00e9cennies. Faire face au changement climatique implique de changer de paradigme et doit s\u2019accompagner de politiques de sant\u00e9 publique \u00e0 l\u2019\u00e9chelle collective et individuelle.<\/p>\n<p>Penser la sant\u00e9 dans le cadre du changement climatique est une nouvelle fa\u00e7on d\u2019aborder les d\u00e9fis sanitaires. Afin de consid\u00e9rer la sant\u00e9 publique et le d\u00e9veloppement durable \u00e0 long terme, il est n\u00e9cessaire d\u2019aborder la sant\u00e9 dans une perspective \u201cone health\u201d. Pour cela il est important de consid\u00e9rer les \u00e9tablissements de sant\u00e9 comme un \u00e9cosyst\u00e8me rassemblant populations et environnements sp\u00e9cifiques. Il faut comprendre ces enjeux dans une perspective de responsabilit\u00e9 populationnelle, en prenant en compte l\u2019exposome hospitalier.<\/p>\n<p>Penser les soins et la sant\u00e9 en pleine crise climatique passe aussi par d\u00e9sacraliser la notion de risque pour les anticiper et ne plus agir dans l\u2019urgence. La prise de conscience brutale des changements environnementaux g\u00e9n\u00e8re des \u00e9motions n\u00e9gatives voire un immobilisme avec un sentiment de perte du monde actuel et l\u2019anticipation d\u2019un monde futur hostile. Il convient de tenir compte de ces r\u00e9actions physiologiques saines pour en faire un premier jalon vers une prise de conscience, une mise en action des individus.<\/p>\n<h1>\u00c9valuer pour d\u00e9carboner les soins<\/h1>\n<p>Pour examiner pourquoi et comment aligner sant\u00e9 avec d\u00e9carbonation, la docteure Laurie Marrauld a pr\u00e9sent\u00e9 les enjeux d\u2019adaptation des \u00e9tablissements de sant\u00e9 aux aspects techniques et humains de cette transformation \u00e9cologique.<\/p>\n<p>Les soins de sant\u00e9 ont eux-m\u00eames une empreinte carbone qu\u2019il est essentiel d\u2019\u00e9valuer. Le bilan carbone sert alors de point de d\u00e9part permettant d\u2019\u00e9laborer un plan d\u2019actions, d\u2019orienter l\u2019adoption et le d\u00e9veloppement de pratiques plus durables et contribuer ainsi \u00e0 la transformation vers un syst\u00e8me de sant\u00e9 respectueux de l\u2019environnement.<\/p>\n<p>L\u2019AP-HP vient de mesurer son empreinte carbone, elle est de l\u2019ordre de 1,2\u202fmillion de tonnes d\u2019\u00e9quivalent CO2, selon Matthias Didier, directeur de projets d\u00e9veloppement durable. Cependant, si r\u00e9aliser le bilan carbone permet d\u2019avoir un \u00e9tat des lieux de la situation, cela reste encore tr\u00e8s macro\u00e9conomique.<\/p>\n<p>L\u2019objectif pour les \u00e9tablissements est d\u2019aller vers des projets et des actions plus op\u00e9rationnels afin de mettre la transition \u00e9cologique au c\u0153ur des pr\u00e9occupations de l\u2019h\u00f4pital dans une perspective transversale et pluridisciplinaire.<\/p>\n<h1>Des leviers op\u00e9rationnels pour des soins durables<\/h1>\n<p>Quatre projets concrets ont \u00e9t\u00e9 pr\u00e9sent\u00e9s, illustrant l\u2019int\u00e9gration du d\u00e9veloppement durable dans les soins. L\u2019objectif \u00e9tait de proposer des mesures concr\u00e8tes et de reprendre les grandes actions possibles illustr\u00e9es par des retours d\u2019exp\u00e9rience.<\/p>\n<p>Ces mesures prennent diff\u00e9rentes formes, des recommandations et autres guides de fonctionnement, aux \u00e9tudes terrain\u2009:<\/p>\n<ul>\n<li>en ce qui concerne les recommandations, le Pr\u202fMaryvonne Hourmant a pr\u00e9sent\u00e9 un guide sur la \u00ab\u2009dialyse verte\u2009\u00bb publi\u00e9 en mars\u202f2023 visant \u00e0 r\u00e9duire l\u2019impact environnemental de ce traitement consommateur en \u00e9nergie \u00e0 travers la r\u00e9cup\u00e9ration structurelle d\u2019\u00e9nergie ou le d\u00e9veloppement du covoiturage pour les patients\u2009;<\/li>\n<li>le groupe de travail Durabloc pr\u00e9sent\u00e9 par Ninon Rouviere a examin\u00e9 les leviers du d\u00e9veloppement durable dans un bloc op\u00e9ratoire, illustr\u00e9 par l\u2019adoption de lames de laryngoscopes r\u00e9utilisables. \u00c0 l\u2019\u00e9chelle du CHU de N\u00eemes, l\u2019\u00e9quivalent de 9 tours du monde a ainsi pu \u00eatre \u00e9conomis\u00e9, soulignant l\u2019efficacit\u00e9 de cette approche\u2009;<\/li>\n<li>le CHU de Bordeaux int\u00e8gre lui aussi la logique du d\u00e9veloppement durable dans la qualit\u00e9, la s\u00e9curit\u00e9 et la pertinence des soins, promouvant des r\u00e9flexions \u00e0 partir d\u2019indicateurs concrets. On peut ainsi citer la pertinence des soins ou la multiplication des consommations de ressources tels que les m\u00e9dicaments ou les dispositifs m\u00e9dicaux pr\u00e9sent\u00e9s par les Drs Josselin Duchateau et Florence Saillour. L\u2019objectif est \u00e0 la fois de lutter contre la d\u00e9pendance \u00e0 certains dispositifs m\u00e9dicaux, qui repr\u00e9sentent 20\u2009% des \u00e9missions dans le secteur de la sant\u00e9, et de questionner les habitudes. Les \u00ab\u2009staff perti\u2009\u00bb ont pour objectif de relever les marges d\u2019am\u00e9lioration des unit\u00e9s, comme les examens biologiques faits en double par exemple. \u00c0 terme et \u00e0 b\u00e9n\u00e9fice \u00e9gal pour le patient, l\u2019impact \u00e9cologique d\u2019un soin ou d\u2019une pratique pourrait devenir un crit\u00e8re discriminant dans le choix des prises en charge. \u00c9tudier la pertinence m\u00e9dicale n\u2019est pas simplement la recherche du moins consommer mais du mieux consommer.<\/li>\n<\/ul>\n<h1>Un premier pas pour une culture commune<\/h1>\n<p>\u00c0 travers ce premier colloque, le CHU de Bordeaux a souhait\u00e9 mettre en perspective des initiatives locales afin de les diffuser et de faire circuler le savoir en mati\u00e8re d\u2019\u00e9cologie dans les soins. Identifier des probl\u00e9matiques au sein des services et construire des solutions avec les agents permet de les impliquer tout en redonnant du sens, reconnaissant les efforts et en valorisant les engagements jusque-l\u00e0 individuels des personnels m\u00e9dicaux, param\u00e9dicaux et techniques. Construire ensemble les politiques \u00e9cologiques peut aussi \u00eatre \u00e0 la fois un outil d\u2019attractivit\u00e9 et de fid\u00e9lisation des agents comme en t\u00e9moigne le Pr\u202fNo\u00eblle Bernard dans le cadre du label Unit\u00e9s durables.<\/p>\n<p>Interroger le rapport entre les soins et la sant\u00e9 est l\u2019occasion de mettre en place une culture commune de la pertinence des soins et de l\u2019interrogation des pratiques. L\u2019exemple des unit\u00e9s durables montre que des r\u00e9seaux de coop\u00e9ration se cr\u00e9ent entre les \u00e9tablissements et au sein m\u00eame de ceux-ci. Penser des soins durables permet \u00e0 \u00e9chelle de l\u2019\u00e9tablissement la communication entre les services et l\u2019instauration d\u2019une v\u00e9ritable dynamique. En repensant les m\u00e9thodes existantes, ces outils encouragent aussi l\u2019innovation, qu\u2019elle soit organisationnelle ou technique, avec un accent sur la collaboration pluridisciplinaire.<\/p>\n<p>Outre l\u2019aspect \u00e9cologique, interroger nos pratiques a un effet \u00e9conomique. M\u00eame si cela n\u2019est pas l\u2019objectif premier de la mise en place de mesures de sobri\u00e9t\u00e9, cela peut \u00eatre un levier d\u2019impl\u00e9mentation de ces mesures. Des initiatives telles que la rationalisation des prescriptions de pansements \u00e9co- responsables, telle que pr\u00e9sent\u00e9e par C\u00e9cile Rougier, visent \u00e0 r\u00e9duire le gaspillage et l\u2019empreinte \u00e9cologique tout en am\u00e9liorant la qualit\u00e9 des soins. Les diff\u00e9rents interlocuteurs soulignent que les actions co\u00fbteuses comme quotidiennes peuvent g\u00e9n\u00e9rer des \u00e9conomies \u00e0 long terme et une am\u00e9lioration des conditions de travail et de prise en soin.<\/p>\n<p>Avec ce colloque, le CHU de Bordeaux entend \u00eatre un pr\u00e9curseur dans le domaine de la sobri\u00e9t\u00e9 dans les soins et les \u00e9tablissements de sant\u00e9. Ce nouveau rendez-vous annuel a permis de sensibiliser des agents du CHU et du GHT mais aussi du personnel d\u2019autres \u00e9tablissements. Pour engager un \u00e9tablissement, il est n\u00e9cessaire de sensibiliser aux enjeux \u00e9cologiques, de diffuser les bonnes pratiques et d\u2019impliquer tous les acteurs \u00e0 chaque \u00e9chelle. Ce colloque n\u2019est qu\u2019une \u00e9tape et s\u2019inscrit dans une politique plus globale de sobri\u00e9t\u00e9, depuis les formations jusqu\u2019au suivi des groupes de travail. Il s\u2019est conclu avec la labellisation de dix unit\u00e9s durables pour distinguer les projets conduits et l\u2019implication transversale des \u00e9quipes.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-47698 size-medium\" src=\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/02\/article-GH-quand-lecologie-sinvite-a-lhopital-colloque-CHU-BDX-EDH-MENDES-DANIEL-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2024\/02\/article-GH-quand-lecologie-sinvite-a-lhopital-colloque-CHU-BDX-EDH-MENDES-DANIEL-300x225.jpg 300w, https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2024\/02\/article-GH-quand-lecologie-sinvite-a-lhopital-colloque-CHU-BDX-EDH-MENDES-DANIEL-1024x767.jpg 1024w, https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2024\/02\/article-GH-quand-lecologie-sinvite-a-lhopital-colloque-CHU-BDX-EDH-MENDES-DANIEL-768x575.jpg 768w, https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2024\/02\/article-GH-quand-lecologie-sinvite-a-lhopital-colloque-CHU-BDX-EDH-MENDES-DANIEL-345x259.jpg 345w, https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2024\/02\/article-GH-quand-lecologie-sinvite-a-lhopital-colloque-CHU-BDX-EDH-MENDES-DANIEL.jpg 1158w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<script>function PlayerjsAsync(){} if(window[\"Playerjs\"]){PlayerjsAsync();}<\/script>","protected":false},"excerpt":{"rendered":"<p>Dans un contexte marqu\u00e9 par des records de temp\u00e9rature et des anomalies climatiques de plus en plus fr\u00e9quentes, le lien entre le changement climatique, les soins et notre syst\u00e8me de sant\u00e9 devient une pr\u00e9occupation cruciale. Avec ce premier colloque qui a r\u00e9uni plus de 200 participants sur le th\u00e8me\u2009: \u00ab\u2009La sant\u00e9 et les soins durables \u00e0 l\u2019\u00e8re du changement climatique\u2009\u00bb, le CHU de Bordeaux revenait sur ce lien. Un comit\u00e9&hellip; <\/p>\n","protected":false},"author":23133,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[26,2],"tags":[9532,8899,629,280,8898],"class_list":["post-47690","post","type-post","status-publish","format-standard","hentry","category-dossier","category-gestions-hospitalieres","tag-bilan-carbone","tag-changement-climatique","tag-innovation","tag-management","tag-transformation-ecologique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quand l\u2019\u00e9cologie s\u2019invite \u00e0 l\u2019h\u00f4pital - Gestions hospitali\u00e8res<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quand l\u2019\u00e9cologie s\u2019invite \u00e0 l\u2019h\u00f4pital - Gestions hospitali\u00e8res\" \/>\n<meta property=\"og:description\" content=\"Dans un contexte marqu\u00e9 par des records de temp\u00e9rature et des anomalies climatiques de plus en plus fr\u00e9quentes, le lien entre le changement climatique, les soins et notre syst\u00e8me de sant\u00e9 devient une pr\u00e9occupation cruciale. Avec ce premier colloque qui a r\u00e9uni plus de 200 participants sur le th\u00e8me\u2009: \u00ab\u2009La sant\u00e9 et les soins durables \u00e0 l\u2019\u00e8re du changement climatique\u2009\u00bb, le CHU de Bordeaux revenait sur ce lien. Un comit\u00e9&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/\" \/>\n<meta property=\"og:site_name\" content=\"Gestions hospitali\u00e8res\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gestionshospitalieres\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-01T15:30:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-05T11:01:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/02\/article-GH-quand-lecologie-sinvite-a-lhopital-colloque-CHU-BDX-EDH-MENDES-DANIEL-300x225.jpg\" \/>\n<meta name=\"author\" content=\"Gestions hospitali\u00e8res\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revue_GH\" \/>\n<meta name=\"twitter:site\" content=\"@revue_GH\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestions hospitali\u00e8res\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/\"},\"author\":{\"name\":\"Gestions hospitali\u00e8res\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f\"},\"headline\":\"Quand l\u2019\u00e9cologie s\u2019invite \u00e0 l\u2019h\u00f4pital\",\"datePublished\":\"2024-01-01T15:30:53+00:00\",\"dateModified\":\"2024-02-05T11:01:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/\"},\"wordCount\":1677,\"publisher\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/02\/article-GH-quand-lecologie-sinvite-a-lhopital-colloque-CHU-BDX-EDH-MENDES-DANIEL-300x225.jpg\",\"keywords\":[\"bilan carbone\",\"changement climatique\",\"innovation\",\"management\",\"transformation \u00e9cologique\"],\"articleSection\":[\"dossier\",\"Gestions Hospitali\u00e8res\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/\",\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/\",\"name\":\"Quand l\u2019\u00e9cologie s\u2019invite \u00e0 l\u2019h\u00f4pital - Gestions hospitali\u00e8res\",\"isPartOf\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/02\/article-GH-quand-lecologie-sinvite-a-lhopital-colloque-CHU-BDX-EDH-MENDES-DANIEL-300x225.jpg\",\"datePublished\":\"2024-01-01T15:30:53+00:00\",\"dateModified\":\"2024-02-05T11:01:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/#primaryimage\",\"url\":\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/02\/article-GH-quand-lecologie-sinvite-a-lhopital-colloque-CHU-BDX-EDH-MENDES-DANIEL-300x225.jpg\",\"contentUrl\":\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/02\/article-GH-quand-lecologie-sinvite-a-lhopital-colloque-CHU-BDX-EDH-MENDES-DANIEL-300x225.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ricom-web8.com\/gestions\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quand l\u2019\u00e9cologie s\u2019invite \u00e0 l\u2019h\u00f4pital\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#website\",\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/\",\"name\":\"Gestions hospitali\u00e8res\",\"description\":\"la revue des d\u00e9cideurs hospitaliers\",\"publisher\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ricom-web8.com\/gestions\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#organization\",\"name\":\"Gestions hospitali\u00e8res\",\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png\",\"contentUrl\":\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png\",\"width\":512,\"height\":512,\"caption\":\"Gestions hospitali\u00e8res\"},\"image\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/gestionshospitalieres\/\",\"https:\/\/x.com\/revue_GH\",\"https:\/\/www.linkedin.com\/company\/gestions-hospitalieres?trk=top_nav_home\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f\",\"name\":\"Gestions hospitali\u00e8res\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g\",\"caption\":\"Gestions hospitali\u00e8res\"},\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/author\/benjamin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quand l\u2019\u00e9cologie s\u2019invite \u00e0 l\u2019h\u00f4pital - Gestions hospitali\u00e8res","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/","og_locale":"fr_FR","og_type":"article","og_title":"Quand l\u2019\u00e9cologie s\u2019invite \u00e0 l\u2019h\u00f4pital - Gestions hospitali\u00e8res","og_description":"Dans un contexte marqu\u00e9 par des records de temp\u00e9rature et des anomalies climatiques de plus en plus fr\u00e9quentes, le lien entre le changement climatique, les soins et notre syst\u00e8me de sant\u00e9 devient une pr\u00e9occupation cruciale. Avec ce premier colloque qui a r\u00e9uni plus de 200 participants sur le th\u00e8me\u2009: \u00ab\u2009La sant\u00e9 et les soins durables \u00e0 l\u2019\u00e8re du changement climatique\u2009\u00bb, le CHU de Bordeaux revenait sur ce lien. Un comit\u00e9&hellip;","og_url":"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/","og_site_name":"Gestions hospitali\u00e8res","article_publisher":"https:\/\/www.facebook.com\/gestionshospitalieres\/","article_published_time":"2024-01-01T15:30:53+00:00","article_modified_time":"2024-02-05T11:01:11+00:00","og_image":[{"url":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/02\/article-GH-quand-lecologie-sinvite-a-lhopital-colloque-CHU-BDX-EDH-MENDES-DANIEL-300x225.jpg","type":"","width":"","height":""}],"author":"Gestions hospitali\u00e8res","twitter_card":"summary_large_image","twitter_creator":"@revue_GH","twitter_site":"@revue_GH","twitter_misc":{"\u00c9crit par":"Gestions hospitali\u00e8res","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/#article","isPartOf":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/"},"author":{"name":"Gestions hospitali\u00e8res","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f"},"headline":"Quand l\u2019\u00e9cologie s\u2019invite \u00e0 l\u2019h\u00f4pital","datePublished":"2024-01-01T15:30:53+00:00","dateModified":"2024-02-05T11:01:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/"},"wordCount":1677,"publisher":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#organization"},"image":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/#primaryimage"},"thumbnailUrl":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/02\/article-GH-quand-lecologie-sinvite-a-lhopital-colloque-CHU-BDX-EDH-MENDES-DANIEL-300x225.jpg","keywords":["bilan carbone","changement climatique","innovation","management","transformation \u00e9cologique"],"articleSection":["dossier","Gestions Hospitali\u00e8res"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/","url":"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/","name":"Quand l\u2019\u00e9cologie s\u2019invite \u00e0 l\u2019h\u00f4pital - Gestions hospitali\u00e8res","isPartOf":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/#primaryimage"},"image":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/#primaryimage"},"thumbnailUrl":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/02\/article-GH-quand-lecologie-sinvite-a-lhopital-colloque-CHU-BDX-EDH-MENDES-DANIEL-300x225.jpg","datePublished":"2024-01-01T15:30:53+00:00","dateModified":"2024-02-05T11:01:11+00:00","breadcrumb":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/#primaryimage","url":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/02\/article-GH-quand-lecologie-sinvite-a-lhopital-colloque-CHU-BDX-EDH-MENDES-DANIEL-300x225.jpg","contentUrl":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/02\/article-GH-quand-lecologie-sinvite-a-lhopital-colloque-CHU-BDX-EDH-MENDES-DANIEL-300x225.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ricom-web8.com\/gestions\/quand-lecologie-sinvite-a-lhopital\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ricom-web8.com\/gestions\/"},{"@type":"ListItem","position":2,"name":"Quand l\u2019\u00e9cologie s\u2019invite \u00e0 l\u2019h\u00f4pital"}]},{"@type":"WebSite","@id":"https:\/\/www.ricom-web8.com\/gestions\/#website","url":"https:\/\/www.ricom-web8.com\/gestions\/","name":"Gestions hospitali\u00e8res","description":"la revue des d\u00e9cideurs hospitaliers","publisher":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ricom-web8.com\/gestions\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ricom-web8.com\/gestions\/#organization","name":"Gestions hospitali\u00e8res","url":"https:\/\/www.ricom-web8.com\/gestions\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/","url":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png","contentUrl":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png","width":512,"height":512,"caption":"Gestions hospitali\u00e8res"},"image":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gestionshospitalieres\/","https:\/\/x.com\/revue_GH","https:\/\/www.linkedin.com\/company\/gestions-hospitalieres?trk=top_nav_home"]},{"@type":"Person","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f","name":"Gestions hospitali\u00e8res","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g","caption":"Gestions hospitali\u00e8res"},"url":"https:\/\/www.ricom-web8.com\/gestions\/author\/benjamin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/posts\/47690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/users\/23133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/comments?post=47690"}],"version-history":[{"count":1,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/posts\/47690\/revisions"}],"predecessor-version":[{"id":47699,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/posts\/47690\/revisions\/47699"}],"wp:attachment":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/media?parent=47690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/categories?post=47690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/tags?post=47690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}