

{"id":48946,"date":"2024-11-01T14:39:48","date_gmt":"2024-11-01T13:39:48","guid":{"rendered":"https:\/\/gestions-hospitalieres.fr\/?p=48946"},"modified":"2024-12-04T11:02:36","modified_gmt":"2024-12-04T10:02:36","slug":"le-document-unique-devaluation-des-risques-professionnels","status":"publish","type":"post","link":"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/","title":{"rendered":"Le document unique d\u2019\u00e9valuation des risques professionnels"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture\u00a0: <\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><p>Les conditions de travail dans l\u2019h\u00f4pital public en France sont particuli\u00e8rement exigeantes et impactent profond\u00e9ment les professionnels de sant\u00e9 au quotidien. Les agents hospitaliers, qu\u2019ils soient infirmiers, aides-soignants, m\u00e9decins ou agents techniques, doivent g\u00e9rer une charge de travail lourde et souvent marqu\u00e9e par des cadences soutenues, une pr\u00e9sence n\u00e9cessaire 24h\/24 et des horaires d\u00e9cal\u00e9s ou de nuit. \u00c0 cela s\u2019ajoutent, dans un tr\u00e8s grand nombre de services, une exposition \u00e0 des risques physiques, comme les manipulations de charges lourdes, biologiques avec les risques d\u2019infections ou de contagion, ainsi que des risques chimiques li\u00e9s \u00e0 l\u2019usage de produits m\u00e9dicaux.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Ces efforts constants sont par ailleurs amplifi\u00e9s par le contexte \u00e9motionnel et psychologique intense que repr\u00e9sente la prise en charge de patients en situation critique, avec parfois un cumul de risques de natures diff\u00e9rentes dans une m\u00eame prise en charge.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Les statistiques des accidents de travail et des maladies professionnelles (AT\/MP) dans le secteur hospitalier en sont d\u2019ailleurs le reflet imm\u00e9diat. Les h\u00f4pitaux publics en France affichent un taux d\u2019AT\/MP parmi les plus \u00e9lev\u00e9s de tous les secteurs d\u2019activit\u00e9. Ainsi, selon les donn\u00e9es r\u00e9centes de la Caisse nationale de l\u2019assurance maladie (Cnam), les h\u00f4pitaux publics enregistrent en moyenne un taux de fr\u00e9quence d\u2019accidents du travail d\u00e9passant 30\u00a0accidents pour 1\u2009000\u00a0salari\u00e9s, un niveau sup\u00e9rieur \u00e0 la moyenne nationale tous secteurs confondus, de 21 pour 1\u2009000 salari\u00e9s. Les maladies professionnelles, notamment les troubles musculo-squelettiques et les affections psychologiques, y sont \u00e9galement \u00e9lev\u00e9es.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Ce sujet est loin d\u2019\u00eatre nouveau, et des g\u00e9n\u00e9rations d\u2019acteurs hospitaliers ont \u00e9t\u00e9 confront\u00e9es \u00e0 cette th\u00e9matique. En France, la r\u00e9ponse institutionnelle a \u00e9t\u00e9 celle de la cr\u00e9ation d\u2019un arsenal de mesures de pr\u00e9vention et de protection autour de deux cl\u00e9s de vo\u00fbte\u2009: le comit\u00e9 d\u2019hygi\u00e8ne, de s\u00e9curit\u00e9 et des conditions de travail (CHSCT) et le document unique d\u2019\u00e9valuation des risques professionnels (Duerp).<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Ce dernier, obligatoire pour toutes les entreprises en France depuis 2001, concerne aussi les h\u00f4pitaux. Il a pour objet de proc\u00e9der \u00e0 l\u2019\u00e9valuation de l\u2019ensemble des risques auxquels les travailleurs sont expos\u00e9s et doit \u00eatre mis \u00e0 jour au moins une fois par an ou \u00e0 chaque modification notable des conditions de travail. Le Duerp constitue la base de toute politique de pr\u00e9vention des risques en identifiant, analysant et priorisant les mesures \u00e0 prendre pour garantir la sant\u00e9 et la s\u00e9curit\u00e9 des employ\u00e9s.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Malheureusement, celui-ci est bien trop souvent consid\u00e9r\u00e9 comme une simple formalit\u00e9 administrative, alors m\u00eame qu\u2019un Duerp optimis\u00e9 et appropri\u00e9 par l\u2019\u00e9tablissement de sant\u00e9 r\u00e9v\u00e8le un fort potentiel en mati\u00e8re de r\u00e9duction des AT\/MP, pour peu que celui-ci s\u2019incarne comme un levier strat\u00e9gique du management des \u00e9quipes.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<h1>Un outil souvent sous-exploit\u00e9 dans les \u00e9tablissements de sant\u00e9<\/h1>\n<p>Dans la grande majorit\u00e9 des \u00e9tablissements, le Duerp est per\u00e7u comme une obligation peu valoris\u00e9e au quotidien. Accus\u00e9 de rester un document formel qui ne refl\u00e8te pas toujours les r\u00e9alit\u00e9s du terrain et les risques sp\u00e9cifiques rencontr\u00e9s par les professionnels, il se confronte en effet \u00e0 un manque de sensibilisation et d\u2019implication des \u00e9quipes sur son contenu et son utilisation, ainsi que par des ressources limit\u00e9es pour \u00eatre r\u00e9guli\u00e8rement actualis\u00e9.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Par ailleurs, cadres de proximit\u00e9 et responsables d\u2019\u00e9quipe supports ne sont pas toujours form\u00e9s \u00e0 int\u00e9grer le Duerp dans leurs pratiques manag\u00e9riales. D\u00e8s lors, au lieu de servir de levier strat\u00e9gique pour anticiper et r\u00e9duire les accidents et maladies professionnelles, le Duerp est sous-exploit\u00e9, limitant son impact sur l\u2019am\u00e9lioration des conditions de travail.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-48948 size-medium\" src=\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/11\/anap-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2024\/11\/anap-300x200.jpg 300w, https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2024\/11\/anap-1024x683.jpg 1024w, https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2024\/11\/anap-768x512.jpg 768w, https:\/\/www.ricom-web8.com\/gestions\/wp-content\/uploads\/2024\/11\/anap.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h1>Int\u00e9grer le Duerp dans une d\u00e9marche de management participatif, au plus pr\u00e8s du terrain<span class=\"Apple-converted-space\">\u00a0<\/span><\/h1>\n<p>Pour autant, la partie n\u2019est pas perdue d\u2019avance. Renforcer l\u2019efficacit\u00e9 du Duerp peut effectivement passer par une approche innovante, visant \u00e0 le transformer en un document \u00e9volutif, somme des actions de terrain mises \u00e0 jour en continu gr\u00e2ce aux retours terrain et aux observations des \u00e9quipes. Plut\u00f4t qu\u2019un rapport fig\u00e9 mis \u00e0 jour une fois par an, il peut devenir un outil dynamique, refl\u00e9tant les risques r\u00e9els et actuels v\u00e9cus par les agents hospitaliers.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Cette m\u00e9thode de mise \u00e0 jour continue permet aux \u00e9quipes et \u00e0 leurs manageurs de signaler facilement tout changement dans les conditions de travail, nouvelle proc\u00e9dure, mat\u00e9riel d\u00e9fectueux ou incident survenu. En int\u00e9grant les retours r\u00e9guliers des professionnels, le Duerp gagne en pertinence et en r\u00e9activit\u00e9, ce qui facilite la prise de mesures pr\u00e9ventives cibl\u00e9es et adapt\u00e9es.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Pour concr\u00e9tiser ce projet, des outils num\u00e9riques peuvent \u00eatre mis en place afin de recueillir et centraliser les retours des \u00e9quipes en temps r\u00e9el, assurant ainsi un suivi constant des risques et un environnement de travail plus s\u00fbr et r\u00e9actif.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<h1>Un outil de mobilisation transversal au service de solutions pratiques et visibles<span class=\"Apple-converted-space\">\u00a0<\/span><\/h1>\n<p>Mais plus que tout, c\u2019est la mobilisation de l\u2019ensemble de la cha\u00eene manag\u00e9riale qui conditionne le succ\u00e8s de la d\u00e9marche\u2009: cadres de proximit\u00e9, de toutes fili\u00e8res, charg\u00e9s d\u2019animer le travail d\u2019identification des risques sur la base d\u2019une m\u00e9thodologie issue de la direction de la qualit\u00e9, cadres de p\u00f4le menant des actions de consolidation des risques identifi\u00e9s dans les services pour leur donner du sens et identifier des permanences de risques dans une fili\u00e8re de soins donn\u00e9e, direction des soins et DRH modulant les modalit\u00e9s de remplacement des accidents de travail et maladies professionnelles en fonction des r\u00e9sultats des \u00e9tudes de terrain. En somme, un travail d\u2019\u00e9quipe, que la cr\u00e9ation d\u2019un comit\u00e9 de suivi pourrait renforcer, assurant une \u00e9valuation continue des actions et une adaptation du plan selon les \u00e9volutions des risques.<\/p>\n<p>L\u2019objectif final de la d\u00e9marche reste enfin de pouvoir pr\u00e9ciser la gamme des actions possibles. Celle-ci est bien connue dans sa typologie\u2009: on y retrouve des formations de sensibilisation des salari\u00e9s aux risques identifi\u00e9s, des am\u00e9liorations des \u00e9quipements de travail, telles que l\u2019installation de dispositifs de protection collective (garde-corps, protections machines) et individuelle (casques, gants) ou encore des proc\u00e9dures d\u2019accueil renforc\u00e9es pour les nouveaux arrivants et int\u00e9rimaires, afin de les informer des risques sp\u00e9cifiques au poste. La d\u00e9marche faisant \u00e9merger observations et solutions en partant du terrain permet n\u00e9anmoins de mieux qualifier les besoins, de les pr\u00e9ciser tant en volume qu\u2019en contenu, et d\u2019en amplifier l\u2019effet sur les risques r\u00e9els et leur pr\u00e9vention.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>L\u2019Agence nationale d\u2019appui \u00e0 la performance (Anap) propose de nombreuses ressources et productions op\u00e9rationnelles permettant de d\u00e9ployer sereinement les fondamentaux RH, disponibles en libre acc\u00e8s sur son site (<a href=\"https:\/\/anap.fr\/s\/\" target=\"_blank\" rel=\"noopener\">anap.fr<\/a>). L\u2019agence conduira prochainement des travaux afin de permettre aux professionnels de s\u2019approprier pleinement le Duerp et d\u2019en maximiser l\u2019impact en tant que levier strat\u00e9gique pour la pr\u00e9vention et l\u2019am\u00e9lioration des conditions de travail.<\/p>\n<script>function PlayerjsAsync(){} if(window[\"Playerjs\"]){PlayerjsAsync();}<\/script>","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture\u00a0: <\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span>Les conditions de travail dans l\u2019h\u00f4pital public en France sont particuli\u00e8rement exigeantes et impactent profond\u00e9ment les professionnels de sant\u00e9 au quotidien. Les agents hospitaliers, qu\u2019ils soient infirmiers, aides-soignants, m\u00e9decins ou agents techniques, doivent g\u00e9rer une charge de travail lourde et souvent marqu\u00e9e par des cadences soutenues, une pr\u00e9sence n\u00e9cessaire 24h\/24 et des horaires d\u00e9cal\u00e9s ou de nuit. \u00c0 cela s\u2019ajoutent, dans un tr\u00e8s grand nombre de services, une exposition \u00e0&hellip; <\/p>\n","protected":false},"author":23133,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[2,9838],"tags":[10527,280,270,6277,994],"class_list":["post-48946","post","type-post","status-publish","format-standard","hentry","category-gestions-hospitalieres","category-performance","tag-duerp","tag-management","tag-prevention","tag-rh","tag-risques-psychosociaux"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le document unique d\u2019\u00e9valuation des risques professionnels - Gestions hospitali\u00e8res<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le document unique d\u2019\u00e9valuation des risques professionnels - Gestions hospitali\u00e8res\" \/>\n<meta property=\"og:description\" content=\"Temps de lecture\u00a0:  4 minutesLes conditions de travail dans l\u2019h\u00f4pital public en France sont particuli\u00e8rement exigeantes et impactent profond\u00e9ment les professionnels de sant\u00e9 au quotidien. Les agents hospitaliers, qu\u2019ils soient infirmiers, aides-soignants, m\u00e9decins ou agents techniques, doivent g\u00e9rer une charge de travail lourde et souvent marqu\u00e9e par des cadences soutenues, une pr\u00e9sence n\u00e9cessaire 24h\/24 et des horaires d\u00e9cal\u00e9s ou de nuit. \u00c0 cela s\u2019ajoutent, dans un tr\u00e8s grand nombre de services, une exposition \u00e0&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/\" \/>\n<meta property=\"og:site_name\" content=\"Gestions hospitali\u00e8res\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gestionshospitalieres\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-01T13:39:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-04T10:02:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/11\/anap-300x200.jpg\" \/>\n<meta name=\"author\" content=\"Gestions hospitali\u00e8res\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revue_GH\" \/>\n<meta name=\"twitter:site\" content=\"@revue_GH\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestions hospitali\u00e8res\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/\"},\"author\":{\"name\":\"Gestions hospitali\u00e8res\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f\"},\"headline\":\"Le document unique d\u2019\u00e9valuation des risques professionnels\",\"datePublished\":\"2024-11-01T13:39:48+00:00\",\"dateModified\":\"2024-12-04T10:02:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/\"},\"wordCount\":1230,\"publisher\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/11\/anap-300x200.jpg\",\"keywords\":[\"Duerp\",\"management\",\"pr\u00e9vention\",\"RH\",\"risques psychosociaux\"],\"articleSection\":[\"Gestions Hospitali\u00e8res\",\"performance\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/\",\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/\",\"name\":\"Le document unique d\u2019\u00e9valuation des risques professionnels - Gestions hospitali\u00e8res\",\"isPartOf\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/11\/anap-300x200.jpg\",\"datePublished\":\"2024-11-01T13:39:48+00:00\",\"dateModified\":\"2024-12-04T10:02:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/#primaryimage\",\"url\":\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/11\/anap-300x200.jpg\",\"contentUrl\":\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/11\/anap-300x200.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ricom-web8.com\/gestions\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le document unique d\u2019\u00e9valuation des risques professionnels\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#website\",\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/\",\"name\":\"Gestions hospitali\u00e8res\",\"description\":\"la revue des d\u00e9cideurs hospitaliers\",\"publisher\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ricom-web8.com\/gestions\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#organization\",\"name\":\"Gestions hospitali\u00e8res\",\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png\",\"contentUrl\":\"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png\",\"width\":512,\"height\":512,\"caption\":\"Gestions hospitali\u00e8res\"},\"image\":{\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/gestionshospitalieres\/\",\"https:\/\/x.com\/revue_GH\",\"https:\/\/www.linkedin.com\/company\/gestions-hospitalieres?trk=top_nav_home\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f\",\"name\":\"Gestions hospitali\u00e8res\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g\",\"caption\":\"Gestions hospitali\u00e8res\"},\"url\":\"https:\/\/www.ricom-web8.com\/gestions\/author\/benjamin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le document unique d\u2019\u00e9valuation des risques professionnels - Gestions hospitali\u00e8res","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/","og_locale":"fr_FR","og_type":"article","og_title":"Le document unique d\u2019\u00e9valuation des risques professionnels - Gestions hospitali\u00e8res","og_description":"Temps de lecture\u00a0:  4 minutesLes conditions de travail dans l\u2019h\u00f4pital public en France sont particuli\u00e8rement exigeantes et impactent profond\u00e9ment les professionnels de sant\u00e9 au quotidien. Les agents hospitaliers, qu\u2019ils soient infirmiers, aides-soignants, m\u00e9decins ou agents techniques, doivent g\u00e9rer une charge de travail lourde et souvent marqu\u00e9e par des cadences soutenues, une pr\u00e9sence n\u00e9cessaire 24h\/24 et des horaires d\u00e9cal\u00e9s ou de nuit. \u00c0 cela s\u2019ajoutent, dans un tr\u00e8s grand nombre de services, une exposition \u00e0&hellip;","og_url":"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/","og_site_name":"Gestions hospitali\u00e8res","article_publisher":"https:\/\/www.facebook.com\/gestionshospitalieres\/","article_published_time":"2024-11-01T13:39:48+00:00","article_modified_time":"2024-12-04T10:02:36+00:00","og_image":[{"url":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/11\/anap-300x200.jpg","type":"","width":"","height":""}],"author":"Gestions hospitali\u00e8res","twitter_card":"summary_large_image","twitter_creator":"@revue_GH","twitter_site":"@revue_GH","twitter_misc":{"\u00c9crit par":"Gestions hospitali\u00e8res","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/#article","isPartOf":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/"},"author":{"name":"Gestions hospitali\u00e8res","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f"},"headline":"Le document unique d\u2019\u00e9valuation des risques professionnels","datePublished":"2024-11-01T13:39:48+00:00","dateModified":"2024-12-04T10:02:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/"},"wordCount":1230,"publisher":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#organization"},"image":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/#primaryimage"},"thumbnailUrl":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/11\/anap-300x200.jpg","keywords":["Duerp","management","pr\u00e9vention","RH","risques psychosociaux"],"articleSection":["Gestions Hospitali\u00e8res","performance"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/","url":"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/","name":"Le document unique d\u2019\u00e9valuation des risques professionnels - Gestions hospitali\u00e8res","isPartOf":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/#primaryimage"},"image":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/#primaryimage"},"thumbnailUrl":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/11\/anap-300x200.jpg","datePublished":"2024-11-01T13:39:48+00:00","dateModified":"2024-12-04T10:02:36+00:00","breadcrumb":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/#primaryimage","url":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/11\/anap-300x200.jpg","contentUrl":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2024\/11\/anap-300x200.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ricom-web8.com\/gestions\/le-document-unique-devaluation-des-risques-professionnels\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ricom-web8.com\/gestions\/"},{"@type":"ListItem","position":2,"name":"Le document unique d\u2019\u00e9valuation des risques professionnels"}]},{"@type":"WebSite","@id":"https:\/\/www.ricom-web8.com\/gestions\/#website","url":"https:\/\/www.ricom-web8.com\/gestions\/","name":"Gestions hospitali\u00e8res","description":"la revue des d\u00e9cideurs hospitaliers","publisher":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ricom-web8.com\/gestions\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ricom-web8.com\/gestions\/#organization","name":"Gestions hospitali\u00e8res","url":"https:\/\/www.ricom-web8.com\/gestions\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/","url":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png","contentUrl":"https:\/\/gestions-hospitalieres.fr\/wp-content\/uploads\/2017\/02\/picto_Gif-GH-trans.png","width":512,"height":512,"caption":"Gestions hospitali\u00e8res"},"image":{"@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gestionshospitalieres\/","https:\/\/x.com\/revue_GH","https:\/\/www.linkedin.com\/company\/gestions-hospitalieres?trk=top_nav_home"]},{"@type":"Person","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/3ba9fe913190dfe9507feb621e902c1f","name":"Gestions hospitali\u00e8res","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ricom-web8.com\/gestions\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1a0d93e6db5dbe7dac96bae4757d256f?s=96&d=mm&r=g","caption":"Gestions hospitali\u00e8res"},"url":"https:\/\/www.ricom-web8.com\/gestions\/author\/benjamin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/posts\/48946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/users\/23133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/comments?post=48946"}],"version-history":[{"count":1,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/posts\/48946\/revisions"}],"predecessor-version":[{"id":48949,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/posts\/48946\/revisions\/48949"}],"wp:attachment":[{"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/media?parent=48946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/categories?post=48946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ricom-web8.com\/gestions\/wp-json\/wp\/v2\/tags?post=48946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}